{"id":4386,"date":"2021-03-15T11:22:56","date_gmt":"2021-03-15T11:22:56","guid":{"rendered":"https:\/\/www.neuraxpharm.com\/it2\/?p=4386"},"modified":"2022-12-13T09:29:37","modified_gmt":"2022-12-13T09:29:37","slug":"epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie","status":"publish","type":"post","link":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie","title":{"rendered":"\u00c9pilepsie et scolarisation : Mon enfant peut-il suivre une scolarit\u00e9 normale si on lui a diagnostiqu\u00e9 une \u00e9pilepsie ?"},"content":{"rendered":"<p>La plupart des enfants \u00e9pileptiques devraient pouvoir fr\u00e9quenter une \u00e9cole normale et profiter d\u2019une \u00e9ducation sans probl\u00e8me majeur, \u00e0 condition qu&rsquo;il y ait une bonne communication entre la famille et l&rsquo;\u00e9cole.<\/p>\n<p>Bien que de nombreux \u00e9tablissements scolaires et universitaires soient compr\u00e9hensifs et acceptent la situation, il existe d&rsquo;\u00e9normes diff\u00e9rences \u00e0 l\u2019\u00e9chelle r\u00e9gionale et nationale en mati\u00e8re de soutien officiel. Il existe \u00e9galement des probl\u00e8mes li\u00e9s \u00e0 l&rsquo;int\u00e9gration des enfants et un manque de formation du personnel ce qui a un impact n\u00e9gatif sur l\u2019\u00e9ducation et le parcours d\u2019apprentissage de ces enfants.<\/p>\n<p>Un sondage men\u00e9 par l&rsquo;organisation caritative Young Epilepsy a r\u00e9v\u00e9l\u00e9 que seulement 51 % du personnel scolaire avait \u00e9t\u00e9 form\u00e9 au soutien d\u2019un jeune \u00e9pileptique. Il a \u00e9galement d\u00e9voil\u00e9 que 18 % des jeunes atteints d\u2019\u00e9pilepsie \u00e9taient exclus des activit\u00e9s scolaires telles que les r\u00e9unions g\u00e9n\u00e9rales, les sports, les clubs parascolaires et les excursions1.<\/p>\n<p>Ceci engendre des entraves \u00e0 la r\u00e9ussite scolaire et \u00e0 l&rsquo;int\u00e9gration sociale, selon un rapport de la Campagne mondiale contre l&rsquo;\u00e9pilepsie de l&rsquo;Organisation mondiale de la sant\u00e9. Ce rapport indique que \u00ab Les jeunes atteints d\u2019\u00e9pilepsie ont beaucoup de mal \u00e0 se frayer un chemin dans les syst\u00e8mes \u00e9ducatifs et \u00e0 trouver un emploi. Les obstacles qui les freinent doivent \u00eatre identifi\u00e9s, en concertation avec le corps m\u00e9dical, \u00e0 un stade pr\u00e9coce \u00bb2.<\/p>\n<p>Les experts s&rsquo;accordent \u00e0 dire qu&rsquo;une bonne \u00e9ducation pour un enfant \u00e9pileptique requiert la synergie de l&rsquo;implication des parents et une approche positive de l&rsquo;\u00e9cole. Les enseignants doivent \u00eatre capables de faire face \u00e0 des crises, m\u00eame prolong\u00e9es, et de manipuler des m\u00e9dicaments contre l&rsquo;\u00e9pilepsie, et devront pour cela suivre une formation officielle.<\/p>\n<p>Les enfants atteints d\u2019\u00e9pilepsie sont un groupe vuln\u00e9rable sur le plan \u00e9ducatif et le personnel de l&rsquo;\u00e9ducation et de la sant\u00e9 doit \u00eatre conscient du soutien suppl\u00e9mentaire dont beaucoup d\u2019entre eux ont besoin \u00e0 tous les niveaux de leur \u00e9ducation.<\/p>\n<p>Un rapport souligne que l&rsquo;\u00e9pilepsie peut avoir des r\u00e9percussions profondes sur l&rsquo;\u00e9tudiant-patient, l&rsquo;\u00e9cole et le foyer, en d\u00e9clarant : \u00ab Il existe une interaction complexe entre les capacit\u00e9s d&rsquo;apprentissage et l&rsquo;\u00e9pilepsie, ce qui peut accro\u00eetre le risque d&rsquo;incompr\u00e9hension et d&rsquo;exclusion des enfants \u00e9pileptiques et les priver de l&rsquo;\u00e9galit\u00e9 des chances en mati\u00e8re d&rsquo;apprentissage et de d\u00e9veloppement int\u00e9gral de leur potentiel \u00bb3.<\/p>\n<p><b>Conseils pour les parents\u00a0<\/b><\/p>\n<p><b>Communiquer<\/b><\/p>\n<p>L&rsquo;\u00e9cole doit \u00eatre inform\u00e9e de l&rsquo;\u00e9pilepsie de votre enfant et il est conseill\u00e9 de contacter le chef d&rsquo;\u00e9tablissement et de rester en contact avec son professeur, ainsi qu&rsquo;avec tout membre du personnel charg\u00e9 du bien-\u00eatre des \u00e9l\u00e8ves. Cela vous donnera l&rsquo;occasion de leur fournir des informations sur les crises de votre enfant et sur le soutien dont il a besoin, et de r\u00e9pondre \u00e0 leurs questions.<\/p>\n<p>Afin que les enseignants se sentent \u00e0 l&rsquo;aise pour faire face \u00e0 une crise et l&rsquo;expliquer aux camarades de classe de mani\u00e8re calme et inform\u00e9e, il est essentiel qu&rsquo;ils comprennent ce qui se passe. Cela leur permettra \u00e9galement de prendre en compte et d&rsquo;\u00e9viter tout d\u00e9clencheur de crise.<\/p>\n<p><b>Tenez-les inform\u00e9s<\/b><\/p>\n<p>Tenez l&rsquo;\u00e9cole au courant des informations d\u00e9taill\u00e9es concernant l&rsquo;\u00e9pilepsie et les besoins de votre enfant. Ceci est particuli\u00e8rement important en cas de changement de leur \u00e9tat ou de leur traitement.<\/p>\n<p>Veillez \u00e0 ce que l&rsquo;\u00e9cole puisse facilement vous contacter, vous ou le m\u00e9decin de famille, en cas d&rsquo;urgence. Si votre m\u00e9decin vous a prescrit un m\u00e9dicament d\u2019urgence en cas de crise, assurez-vous que le personnel de l&rsquo;\u00e9cole re\u00e7oive une formation ad\u00e9quate sur la mani\u00e8re de l&rsquo;administrer.<\/p>\n<p><b>Impliquez votre enfant<\/b><\/p>\n<p>Assurez-vous que votre enfant soit conscient des \u00e9v\u00e9nements ou des conditions qui pourraient d\u00e9clencher une crise et donnez-lui les connaissances et la confiance n\u00e9cessaires pour en parler aux enseignants et aux autres enfants.<\/p>\n<p>Il est important de les impliquer dans le processus afin qu&rsquo;ils sachent que les enseignants et le personnel sont inform\u00e9s de leur \u00e9pilepsie et qu\u2019ils savent quoi faire. L&rsquo;\u00e2ge de l&rsquo;enfant d\u00e9terminera le niveau d&rsquo;information que vous pourrez partager avec lui et la mesure dans laquelle vous pourrez l&rsquo;impliquer dans les r\u00e9unions avec l\u2019\u00e9cole. N\u00e9anmoins, les enfants doivent \u00eatre inclus dans la d\u00e9marche afin qu&rsquo;ils n&rsquo;aient pas l&rsquo;impression que les d\u00e9cisions sont prises sans eux ou que leur trouble est honteux.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Conna\u00eetre vos droits<\/b><\/p>\n<p>Il existe un soutien officiel du gouvernement et des autorit\u00e9s \u00e9ducatives, mais le type et le niveau d&rsquo;aide varient selon les \u00e9coles, les localit\u00e9s et les nationalit\u00e9s. Il convient de se renseigner sur le soutien auquel votre famille a droit et des groupes de patients au niveau local peuvent vous aider.<\/p>\n<p>Des aides sont disponibles pour vous assister, vous et l&rsquo;\u00e9cole, mais elles ne sont pas forc\u00e9ment \u00e9videntes \u00e0 conna\u00eetre. Il est donc important de conna\u00eetre vos droits, car ces aides sont l\u00e0 pour faciliter au maximum le parcours scolaire.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Sources :<\/b><\/p>\n<ol>\n<li>Young Epilepsy. Epilepsy Support in Schools. October 2017. Accessed January 2021. <a href=\"https:\/\/youngepilepsy.org.uk\/images\/Epilepsy_support_in_schools_report_-_Oct_17.pdf\">https:\/\/youngepilepsy.org.uk\/images\/Epilepsy_support_in_schools_report_-_Oct_17.pdf<\/a><\/li>\n<li>Cross JH. Epilepsy in the WHO European region: fostering epilepsy care in Europe. Epilepsia. 2011;52(1):187-188. doi:10.1111\/j.1528-1167.2010.02903.x<\/li>\n<li>Marshall RM, Cupoli JM. Epilepsy and education: the pediatrician&rsquo;s expanding role.\u00a0<i>Adv Pediatr<\/i>. 1986;33:159-180.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>La plupart des enfants \u00e9pileptiques devraient pouvoir fr\u00e9quenter une \u00e9cole normale et profiter d\u2019une \u00e9ducation sans probl\u00e8me majeur, \u00e0 condition qu&rsquo;il y ait une bonne communication entre la famille et l&rsquo;\u00e9cole.<\/p>\n","protected":false},"author":11,"featured_media":6831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[22],"tags":[],"class_list":["post-4386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-epilepsie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c9pilepsie et scolarit\u00e9 : votre enfant - Neuraxpharm France<\/title>\n<meta name=\"description\" content=\"Votre enfant \u00e9pileptique peut suivre une scolarit\u00e9 normale. D\u00e9couvrez comment assurer sa r\u00e9ussite \u00e9ducative et son bien-\u00eatre \u00e0 l&#039;\u00e9cole.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9pilepsie et scolarisation : Mon enfant peut-il suivre une scolarit\u00e9 normale si on lui a diagnostiqu\u00e9 une \u00e9pilepsie ?\" \/>\n<meta property=\"og:description\" content=\"Votre enfant \u00e9pileptique peut suivre une scolarit\u00e9 normale. D\u00e9couvrez comment assurer sa r\u00e9ussite \u00e9ducative et son bien-\u00eatre \u00e0 l&#039;\u00e9cole.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/\" \/>\n<meta property=\"og:site_name\" content=\"Neuraxpharm France\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-15T11:22:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-13T09:29:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2021\/02\/epilepsy-school-attendance.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1916\" \/>\n\t<meta property=\"og:image:height\" content=\"824\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Buckland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Buckland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\"},\"author\":{\"name\":\"Danny Buckland\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/#\\\/schema\\\/person\\\/5e98de21df7792c42f65519659dc4ed1\"},\"headline\":\"\u00c9pilepsie et scolarisation : Mon enfant peut-il suivre une scolarit\u00e9 normale si on lui a diagnostiqu\u00e9 une \u00e9pilepsie ?\",\"datePublished\":\"2021-03-15T11:22:56+00:00\",\"dateModified\":\"2022-12-13T09:29:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\"},\"wordCount\":959,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2021\\\/02\\\/epilepsy-school-attendance.jpg\",\"articleSection\":[\"\u00c9pilepsie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\\\/\",\"name\":\"\u00c9pilepsie et scolarit\u00e9 : votre enfant - Neuraxpharm France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2021\\\/02\\\/epilepsy-school-attendance.jpg\",\"datePublished\":\"2021-03-15T11:22:56+00:00\",\"dateModified\":\"2022-12-13T09:29:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/#\\\/schema\\\/person\\\/5e98de21df7792c42f65519659dc4ed1\"},\"description\":\"Votre enfant \u00e9pileptique peut suivre une scolarit\u00e9 normale. D\u00e9couvrez comment assurer sa r\u00e9ussite \u00e9ducative et son bien-\u00eatre \u00e0 l'\u00e9cole.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2021\\\/02\\\/epilepsy-school-attendance.jpg\",\"contentUrl\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2021\\\/02\\\/epilepsy-school-attendance.jpg\",\"width\":1916,\"height\":824,\"caption\":\"Enseignante accueillant une fillette \u00e0 l'\u00e9cole\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/\",\"name\":\"Neuraxpharm France\",\"description\":\"Ein europ\u00e4ischer Marktf\u00fchrer f\u00fcr CNS-Produkte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/#\\\/schema\\\/person\\\/5e98de21df7792c42f65519659dc4ed1\",\"name\":\"Danny Buckland\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g\",\"caption\":\"Danny Buckland\"},\"description\":\"Danny Buckland is an award-winning journalist who writes about health for newspapers, magazines and online outlets across Europe. His work ranges across all healthcare topics with a strong accent on innovation in technology, drug development and system redesign to meet growing challenges. He has produced White Papers and thought leadership articles for a range of clients and charities, moderates panel discussions and generates engaging content.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/danny-buckland-8252a16\\\/\"],\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/blog\\\/auteur\\\/dbuckland\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9pilepsie et scolarit\u00e9 : votre enfant - Neuraxpharm France","description":"Votre enfant \u00e9pileptique peut suivre une scolarit\u00e9 normale. D\u00e9couvrez comment assurer sa r\u00e9ussite \u00e9ducative et son bien-\u00eatre \u00e0 l'\u00e9cole.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9pilepsie et scolarisation : Mon enfant peut-il suivre une scolarit\u00e9 normale si on lui a diagnostiqu\u00e9 une \u00e9pilepsie ?","og_description":"Votre enfant \u00e9pileptique peut suivre une scolarit\u00e9 normale. D\u00e9couvrez comment assurer sa r\u00e9ussite \u00e9ducative et son bien-\u00eatre \u00e0 l'\u00e9cole.","og_url":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/","og_site_name":"Neuraxpharm France","article_published_time":"2021-03-15T11:22:56+00:00","article_modified_time":"2022-12-13T09:29:37+00:00","og_image":[{"width":1916,"height":824,"url":"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2021\/02\/epilepsy-school-attendance.jpg","type":"image\/jpeg"}],"author":"Danny Buckland","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Danny Buckland","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/#article","isPartOf":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie"},"author":{"name":"Danny Buckland","@id":"https:\/\/www.neuraxpharm.com\/fr\/#\/schema\/person\/5e98de21df7792c42f65519659dc4ed1"},"headline":"\u00c9pilepsie et scolarisation : Mon enfant peut-il suivre une scolarit\u00e9 normale si on lui a diagnostiqu\u00e9 une \u00e9pilepsie ?","datePublished":"2021-03-15T11:22:56+00:00","dateModified":"2022-12-13T09:29:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie"},"wordCount":959,"commentCount":0,"image":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2021\/02\/epilepsy-school-attendance.jpg","articleSection":["\u00c9pilepsie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie","url":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/","name":"\u00c9pilepsie et scolarit\u00e9 : votre enfant - Neuraxpharm France","isPartOf":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/#primaryimage"},"image":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2021\/02\/epilepsy-school-attendance.jpg","datePublished":"2021-03-15T11:22:56+00:00","dateModified":"2022-12-13T09:29:37+00:00","author":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/#\/schema\/person\/5e98de21df7792c42f65519659dc4ed1"},"description":"Votre enfant \u00e9pileptique peut suivre une scolarit\u00e9 normale. D\u00e9couvrez comment assurer sa r\u00e9ussite \u00e9ducative et son bien-\u00eatre \u00e0 l'\u00e9cole.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.neuraxpharm.com\/fr\/blog\/epilepsie-et-scolarisation-mon-enfant-peut-il-suivre-une-scolarite-normale-si-on-lui-a-diagnostique-une-epilepsie\/#primaryimage","url":"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2021\/02\/epilepsy-school-attendance.jpg","contentUrl":"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2021\/02\/epilepsy-school-attendance.jpg","width":1916,"height":824,"caption":"Enseignante accueillant une fillette \u00e0 l'\u00e9cole"},{"@type":"WebSite","@id":"https:\/\/www.neuraxpharm.com\/fr\/#website","url":"https:\/\/www.neuraxpharm.com\/fr\/","name":"Neuraxpharm France","description":"Ein europ\u00e4ischer Marktf\u00fchrer f\u00fcr CNS-Produkte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neuraxpharm.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.neuraxpharm.com\/fr\/#\/schema\/person\/5e98de21df7792c42f65519659dc4ed1","name":"Danny Buckland","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g","caption":"Danny Buckland"},"description":"Danny Buckland is an award-winning journalist who writes about health for newspapers, magazines and online outlets across Europe. His work ranges across all healthcare topics with a strong accent on innovation in technology, drug development and system redesign to meet growing challenges. He has produced White Papers and thought leadership articles for a range of clients and charities, moderates panel discussions and generates engaging content.","sameAs":["https:\/\/www.linkedin.com\/in\/danny-buckland-8252a16\/"],"url":"https:\/\/www.neuraxpharm.com\/fr\/blog\/auteur\/dbuckland"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/posts\/4386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/comments?post=4386"}],"version-history":[{"count":5,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/posts\/4386\/revisions"}],"predecessor-version":[{"id":27550,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/posts\/4386\/revisions\/27550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/media\/6831"}],"wp:attachment":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/media?parent=4386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/categories?post=4386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/tags?post=4386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}