{"id":3611,"date":"2021-03-11T11:56:47","date_gmt":"2021-03-11T11:56:47","guid":{"rendered":"https:\/\/www.neuraxpharm.com\/it2\/?page_id=3611"},"modified":"2026-05-11T09:35:59","modified_gmt":"2026-05-11T09:35:59","slug":"parkinson","status":"publish","type":"page","link":"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson","title":{"rendered":"Maladie de Parkinson"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3611\" class=\"elementor elementor-3611\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-060209f elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom banner_top elementor-section-height-default\" data-id=\"060209f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;00936a0&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df365c7\" data-id=\"df365c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9789da9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9789da9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;650699a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0725104 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"0725104\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e025551\" data-id=\"e025551\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3f5ec1 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"c3f5ec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Maladie de Parkinson<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4d3d95 text_disorders elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4d3d95\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;245babd&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3f35c95 sticky-parent\" data-id=\"3f35c95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c38b907 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c38b907\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;87539ac&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c11e767\" data-id=\"c11e767\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b0879d elementor-widget elementor-widget-table-of-contents\" data-id=\"8b0879d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-right&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;no_headings_message&quot;:&quot;Aucun titre n\\u2019a \\u00e9t\\u00e9 trouv\\u00e9 sur cette page.&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tDANS CETTE SECTION\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__8b0879d\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-60a0257 sticky-column elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60a0257\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;87539ac&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ce8acbe\" data-id=\"ce8acbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55fa575 elementor-widget elementor-widget-spacer\" data-id=\"55fa575\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d862fa elementor-widget elementor-widget-heading\" data-id=\"0d862fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Articles connexes<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c99450 elementor-widget elementor-widget-jet-listing-grid\" data-id=\"5c99450\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;1&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-not-found jet-listing-grid__items\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:3204,&quot;posts_num&quot;:3,&quot;columns&quot;:1,&quot;columns_tablet&quot;:1,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-listing-source=\"posts\" data-listing-id=\"3204\" data-query-id=\"\" data-queried-id=\"3611|WP_Post\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"22443\" class=\"elementor elementor-22443\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd8561e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd8561e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;7a0f9f5&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d93a1f\" data-id=\"0d93a1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ae764b elementor-widget elementor-widget-jet-listing-grid\" data-id=\"8ae764b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;1&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-notice\">Please select another listing to show to avoid recursion.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><style>.elementor-22443 .elementor-element.elementor-element-dd8561e .elementor-repeater-item-7a0f9f5.jet-parallax-section__layout .jet-parallax-section__image{background-size:auto;}.elementor-22443 .elementor-element.elementor-element-0d93a1f > .elementor-element-populated{text-align:start;}.elementor-22443 .elementor-element.elementor-element-8ae764b > .elementor-widget-container > .jet-listing-grid > .jet-listing-grid__items, .elementor-22443 .elementor-element.elementor-element-8ae764b > .jet-listing-grid > .jet-listing-grid__items{--columns:1;}:root{--page-title-display:none;}\/* Start custom CSS for jet-listing-grid, class: .elementor-element-8ae764b *\/.elementor-page-title {\r\n    display: block;\r\n}\/* End custom CSS *\/\n\/* Start custom CSS for jet-listing-grid, class: .elementor-element-8ae764b *\/.elementor-page-title {\r\n    display: block;\r\n}\/* End custom CSS *\/\n\/* Start custom CSS for section, class: .elementor-element-dd8561e *\/.elementor-page-title {\r\n    display: block;\r\n}\/* End custom CSS *\/<\/style><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd168e4 elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd168e4\" data-element_type=\"section\" data-e-type=\"section\" id=\"main-navigation\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;87539ac&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-577a847\" data-id=\"577a847\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-985afe0 elementor-widget elementor-widget-table-of-contents\" data-id=\"985afe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-right&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;no_headings_message&quot;:&quot;Aucun titre n\\u2019a \\u00e9t\\u00e9 trouv\\u00e9 sur cette page.&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tDANS CETTE SECTION\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__985afe0\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a1bbc9b elementor-hidden-tablet elementor-hidden-phone\" data-id=\"a1bbc9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-18c77c0 page-health\" data-id=\"18c77c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93b4c45 elementor-widget elementor-widget-spacer\" data-id=\"93b4c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3feddb6 elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"3feddb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/www.neuraxpharm.com\/fr\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Neuraxpharm\">Neuraxpharm <\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90283e7 elementor-widget elementor-widget-text-editor\" data-id=\"90283e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maladie de Parkinson touche principalement les personnes \u00e2g\u00e9es en ralentissant les fonctions du corps et en affectant sa capacit\u00e9 \u00e0 contr\u00f4ler les mouvements.\u00a0D\u00e9couvrez les sympt\u00f4mes, le diagnostic et le traitement de cette maladie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c27b39 no_in_this_section elementor-widget elementor-widget-heading\" data-id=\"7c27b39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qu'est-ce que la maladie de Parkinson ?\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9695e39 elementor-widget elementor-widget-text-editor\" data-id=\"9695e39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maladie de Parkinson (MP) est une affection neurod\u00e9g\u00e9n\u00e9rative progressive. Cela signifie que les sympt\u00f4mes se d\u00e9veloppent progressivement et s&rsquo;aggravent au fil du temps. La maladie de Parkinson touche des cellules nerveuses du cerveau (neurones) qui contr\u00f4lent le mouvement, et par cons\u00e9quent, de nombreuses fonctions corporelles et mouvements sont affect\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e5b93b elementor-widget elementor-widget-heading\" data-id=\"6e5b93b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels sont les principaux types de maladie de Parkinson ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb23c9f elementor-widget elementor-widget-text-editor\" data-id=\"fb23c9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maladie de Parkinson appartient \u00e0 un groupe d&rsquo;affections appel\u00e9 syndrome parkinsonien. Il s&rsquo;agit d&rsquo;un terme g\u00e9n\u00e9rique englobant \u00e9galement d&rsquo;autres affections aux sympt\u00f4mes similaires (notamment les tremblements, la lenteur des mouvements, la rigidit\u00e9 musculaire et des difficult\u00e9s \u00e0 la marche).<\/p><p>La maladie de Parkinson est la cause neurod\u00e9g\u00e9n\u00e9rative la plus courante du syndrome parkinsonien. Les autres types de ce syndrome sont parfois appel\u00e9s syndromes parkinsoniens atypiques ou Parkinson-plus. Ces affections ont tendance \u00e0 avoir un pronostic plus d\u00e9favorable que la MP et ne r\u00e9pondent pas au traitement traditionnel de cette derni\u00e8re, qui agissent en augmentant les niveaux de dopamine.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef9b9bc elementor-widget elementor-widget-heading\" data-id=\"ef9b9bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Combien de personnes sont atteintes de la maladie de Parkinson ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c90f4e lista_1 elementor-widget elementor-widget-text-editor\" data-id=\"1c90f4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En 2016, l&rsquo;\u00e9tude sur la charge mondiale de morbidit\u00e9 a estim\u00e9 qu&rsquo;environ 6,1 millions de personnes dans le monde \u00e9taient atteintes de la maladie de Parkinson. Il s&rsquo;agit d&rsquo;une augmentation significative par rapport aux 2,5 millions de personnes atteintes de maladie de Parkinson en 1990. Dans l&rsquo;UE, on estime qu&rsquo;elle touche 1,2 million de personnes.<\/p><p>Le m\u00eame rapport estimait que d&rsquo;ici 2040, le nombre de personnes vivant avec la maladie de Parkinson serait de pr\u00e8s de 13 millions. Les raisons de cette augmentation :<\/p><ul><li>De nombreuses personnes ne sont pas diagnostiqu\u00e9es<\/li><li>La pr\u00e9valence de la MP augmente consid\u00e9rablement avec l&rsquo;\u00e2ge, et les gens vivent plus longtemps.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0c5f42 elementor-widget elementor-widget-heading\" data-id=\"e0c5f42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sympt\u00f4mes\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf2b926 elementor-widget elementor-widget-text-editor\" data-id=\"cf2b926\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les sympt\u00f4mes de la maladie de Parkinson peuvent varier d&rsquo;une personne \u00e0 l&rsquo;autre. Ils commencent g\u00e9n\u00e9ralement de mani\u00e8re tr\u00e8s subtile et peuvent donc passer inaper\u00e7us pendant un certain temps.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63ceac9 elementor-widget elementor-widget-heading\" data-id=\"63ceac9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels sont les sympt\u00f4mes de la maladie de Parkinson ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e57465 elementor-widget elementor-widget-text-editor\" data-id=\"2e57465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les sympt\u00f4mes peuvent \u00eatre divis\u00e9s en sympt\u00f4mes moteurs (ceux qui impliquent des mouvements) et en sympt\u00f4mes non moteurs, n&rsquo;impliquant pas de mouvements. Il existe trois sympt\u00f4mes primaires et de nombreux autres sympt\u00f4mes secondaires qui sont moins visibles mais qui peuvent n\u00e9anmoins affecter la qualit\u00e9 de vie.<\/p><p>Les sympt\u00f4mes diff\u00e8rent d&rsquo;une personne \u00e0 l&rsquo;autre et il est peu probable qu&rsquo;une personne atteinte de la MP les pr\u00e9sente tous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-709d087 elementor-widget elementor-widget-heading\" data-id=\"709d087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sympt\u00f4mes moteurs\n\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30229f9 lista_1 elementor-widget elementor-widget-text-editor\" data-id=\"30229f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les trois sympt\u00f4mes principaux associ\u00e9s \u00e0 la maladie de Parkinson touchent l\u2019ensemble du corps. Ces sympt\u00f4mes sont les suivants :<\/p><ul><li>Tremblements (des mains, des bras, des jambes ou de la t\u00eate)<\/li><li>Muscles crisp\u00e9s et rigides<\/li><li>Mouvements lents (\u00e9galement appel\u00e9s bradykin\u00e9sie)<\/li><\/ul><p>Les autres sympt\u00f4mes physiques peuvent comprendre :<\/p><ul><li>Probl\u00e8mes d&rsquo;\u00e9quilibre<\/li><li>Perte de l&rsquo;odorat<\/li><li>Constipation, incontinence ou dysfonctionnement sexuel<\/li><li>Probl\u00e8mes de sommeil<\/li><li>Difficult\u00e9 \u00e0 m\u00e2cher, \u00e0 avaler ou \u00e0 parler<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bc1124 elementor-widget elementor-widget-heading\" data-id=\"9bc1124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sympt\u00f4mes non moteurs<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-825b86d lista_1 elementor-widget elementor-widget-text-editor\" data-id=\"825b86d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Sentiments de d\u00e9pression et d&rsquo;anxi\u00e9t\u00e9<\/li><li>Fatigue<\/li><li>Probl\u00e8mes cognitifs tels que les pertes de m\u00e9moire et les difficult\u00e9s \u00e0 r\u00e9fl\u00e9chir ou \u00e0 raisonner<\/li><li>Des probl\u00e8mes comportementaux tels que les r\u00e9actions impulsives et les changements de personnalit\u00e9, par exemple lorsqu&rsquo;une personne extravertie se replie sur elle-m\u00eame<\/li><li>\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e213a7d elementor-widget elementor-widget-heading\" data-id=\"e213a7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels sont les stades de la maladie de Parkinson ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4576dad elementor-widget elementor-widget-text-editor\" data-id=\"4576dad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tout d&rsquo;abord, les sympt\u00f4mes ont tendance \u00e0 \u00eatre tr\u00e8s l\u00e9gers et passent souvent inaper\u00e7us, ce qui peut entra\u00eener un retard dans le diagnostic. En g\u00e9n\u00e9ral, ils commencent sur un seul c\u00f4t\u00e9 du corps mais finissent par toucher les deux c\u00f4t\u00e9s.<\/p><p>L&rsquo;\u00e9volution de la maladie de Parkinson peut varier consid\u00e9rablement d&rsquo;une personne \u00e0 l&rsquo;autre. Il n\u2019est donc pas facile de pr\u00e9dire \u00e0 quelle vitesse un cas de maladie de Parkinson va \u00e9voluer. De nombreuses personnes constatent \u00e9galement que leurs sympt\u00f4mes fluctuent d&rsquo;un jour \u00e0 l&rsquo;autre, ce qui se traduit par de bonnes ou de mauvaises journ\u00e9es.<\/p><p>Au cours des premiers stades, les tremblements ou les secousses de la main ou des doigts sont fr\u00e9quents. Au fil du temps, cette situation peut s&rsquo;aggraver progressivement, jusqu&rsquo;\u00e0 ce qu&rsquo;il devienne difficile d&rsquo;effectuer des t\u00e2ches quotidiennes simples telles que manger. Les tremblements peuvent \u00e9galement se d\u00e9velopper dans d&rsquo;autres parties du corps.<\/p><p>De m\u00eame, les mouvements peuvent se ralentir progressivement. Les personnes atteintes de la maladie de Parkinson \u00e0 un stade avanc\u00e9 ont souvent des difficult\u00e9s \u00e0 marcher et peuvent finir par faire de petits pas en tra\u00eenant les pieds pour se d\u00e9placer.<\/p><p>L&rsquo;autre sympt\u00f4me principal, la rigidit\u00e9 musculaire, peut \u00e9voluer au point de rendre difficile l&rsquo;expression du visage et \u00e9ventuellement provoquer des crampes musculaires douloureuses.<\/p><p>La r\u00e9ponse d&rsquo;un individu aux m\u00e9dicaments peut \u00e9galement changer avec le temps. Les m\u00e9dicaments peuvent produire une nette am\u00e9lioration au d\u00e9part, mais leur efficacit\u00e9 peut diminuer ou devenir irr\u00e9guli\u00e8re au fil du temps, et il peut alors \u00eatre n\u00e9cessaire de les adapter \u00e0 l&rsquo;\u00e9volution de la maladie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee4c349 elementor-widget elementor-widget-heading\" data-id=\"ee4c349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels sont les premiers signes de la maladie de Parkinson ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8482c8 elementor-widget elementor-widget-text-editor\" data-id=\"e8482c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;\u00e9volution de la MP est diff\u00e9rente pour chaque cas, mais il est courant que les sympt\u00f4mes soient l\u00e9gers au d\u00e9but et passent souvent inaper\u00e7us au cours des premiers stades. Les sympt\u00f4mes commencent normalement sur un c\u00f4t\u00e9 du corps et finissent par toucher les deux c\u00f4t\u00e9s. La maladie de Parkinson commence souvent par des tremblements ou des secousses au niveau de la main ou des doigts.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41a878b elementor-widget elementor-widget-heading\" data-id=\"41a878b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Causes, facteurs de risque et esp\u00e9rance de vie\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2db641a elementor-widget elementor-widget-text-editor\" data-id=\"2db641a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>On ne sait pas exactement pourquoi les gens sont atteints de la maladie de Parkinson, mais les sympt\u00f4mes sont d\u00e9clench\u00e9s lorsque les cellules nerveuses qui produisent la dopamine dans le cerveau s&rsquo;affaiblissent et meurent. Les chercheurs pensent que la mort de ces cellules nerveuses est li\u00e9e \u00e0 une association de facteurs de risque tels que l\u2019\u00e2ge, la g\u00e9n\u00e9tique et des facteurs environnementaux comme l&rsquo;exposition \u00e0 certains produits chimiques.<\/p><p>Les facteurs de risque connus pour le d\u00e9veloppement de la MP comprennent l&rsquo;exposition \u00e0 des fongicides et des pesticides, tels que le man\u00e8be, la rot\u00e9none et le paraquat, ainsi que les l\u00e9sions c\u00e9r\u00e9brales traumatiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67a258c elementor-widget elementor-widget-heading\" data-id=\"67a258c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quelles sont les causes de la maladie de Parkinson ?\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba4a066 elementor-widget elementor-widget-text-editor\" data-id=\"ba4a066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Des substances chimiques pr\u00e9sentes dans le cerveau, appel\u00e9es neurotransmetteurs, aident \u00e0 contr\u00f4ler les mouvements du corps en transmettant les messages entre les cellules nerveuses et le reste du corps. L&rsquo;un des neurotransmetteurs les plus importants dans ce processus est la dopamine. Chez les personnes atteintes de la MP, environ 70 \u00e0 80 % des cellules productrices de dopamine se d\u00e9t\u00e9riorent et finissent par mourir.<\/p><p>Ce processus est appel\u00e9 neurod\u00e9g\u00e9n\u00e9rescence. Cela signifie que les personnes atteintes de la MP ont de faibles niveaux de dopamine dans la partie du cerveau qui contr\u00f4le les mouvements et l&rsquo;\u00e9quilibre. Les sympt\u00f4mes de la maladie de Parkinson apparaissent lorsque les cellules nerveuses ne sont plus capables de transmettre les bons messages pour contr\u00f4ler les mouvements du corps.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c86986 elementor-position-inline-start icon_mini_box elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6c86986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLa maladie de Parkinson est-elle h\u00e9r\u00e9ditaire ?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDans certains cas, un g\u00e8ne d\u00e9fectueux peut \u00eatre transmis par les parents aux enfants et leur faire h\u00e9riter de la maladie de Parkinson, mais cela est extr\u00eamement rare ; la maladie n'est g\u00e9n\u00e9ralement pas h\u00e9r\u00e9ditaire. (5).\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b29ae2b elementor-widget elementor-widget-heading\" data-id=\"b29ae2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Qui est atteint de la maladie de Parkinson ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f19e25b elementor-widget elementor-widget-text-editor\" data-id=\"f19e25b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maladie de Parkinson touche des personnes de toutes les ethnies et de toutes les origines. Le risque de contracter la maladie augmente avec l&rsquo;\u00e2ge, mais on estime qu&rsquo;environ 4 % des personnes atteintes de la maladie de Parkinson sont diagnostiqu\u00e9es avant l&rsquo;\u00e2ge de 50 ans.<\/p><p>Les hommes sont plus susceptibles d&rsquo;en \u00eatre atteints que les femmes. D&rsquo;apr\u00e8s certaines recherches, deux fois plus d&rsquo;hommes que de femmes sont diagnostiqu\u00e9s de MP, et les femmes ont en moyenne 2,1 ans de plus que les hommes au moment du diagnostic.(7)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d35b102 elementor-widget elementor-widget-heading\" data-id=\"d35b102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Combien de temps peut-on vivre avec la maladie de Parkinson ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a6fb1b elementor-widget elementor-widget-text-editor\" data-id=\"5a6fb1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maladie de Parkinson est une maladie chronique qui affecte consid\u00e9rablement la vie quotidienne des patients et qui peut les rendre plus vuln\u00e9rables \u00e0 d&rsquo;autres maladies et infections. Toutefois, gr\u00e2ce aux progr\u00e8s des traitements, la plupart d\u2019entre eux ont une esp\u00e9rance de vie normale ou quasi normale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8d1d9d elementor-widget elementor-widget-heading\" data-id=\"a8d1d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Diagnostic<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e3780c elementor-widget elementor-widget-text-editor\" data-id=\"3e3780c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une s\u00e9rie d&rsquo;\u00e9valuations sont utilis\u00e9es pour aider les m\u00e9decins \u00e0 d\u00e9terminer si une personne est atteinte de la maladie de Parkinson. Ces derniers peuvent \u00e9galement avoir recours \u00e0 certains examens m\u00e9dicaux pour \u00e9carter d&rsquo;autres troubles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b344d44 elementor-widget elementor-widget-heading\" data-id=\"b344d44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment la maladie de Parkinson est-elle diagnostiqu\u00e9e ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df939aa lista_1 elementor-widget elementor-widget-text-editor\" data-id=\"df939aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il peut \u00eatre difficile de diagnostiquer la maladie de Parkinson, pour plusieurs raisons. Les sympt\u00f4mes \u00e9tant l\u00e9gers au cours des premiers stades, les m\u00e9decins ne peuvent pas \u00eatre s\u00fbrs qu\u2019ils soient d\u00fbs \u00e0 la maladie de Parkinson. Ces derniers peuvent varier consid\u00e9rablement d&rsquo;une personne \u00e0 l&rsquo;autre, et d&rsquo;autres maladies &#8211; notamment le tremblement essentiel et la maladie d&rsquo;Alzheimer &#8211; ont des sympt\u00f4mes similaires, ce qui peut conduire \u00e0 des erreurs de diagnostic.<\/p><p>L&rsquo;autre facteur qui rend la MP difficile \u00e0 diagnostiquer est le fait qu&rsquo;il n&rsquo;existe pas d\u2019examen m\u00e9dical unique \u00e0 cet effet. Les sp\u00e9cialistes peuvent avoir recours \u00e0 un certain nombre d\u2019examens pour les aider \u00e0 \u00e9carter d&rsquo;autres pathologies, mais le diagnostic est principalement \u00e9tabli sur la base des r\u00e9sultats des diff\u00e9rents tests suivants :<\/p><ul><li>Une \u00e9valuation des sympt\u00f4mes du patient<\/li><li>Une \u00e9valuation des ant\u00e9c\u00e9dents m\u00e9dicaux du patient<\/li><li>Un examen physique approfondi<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f877e6 elementor-widget elementor-widget-heading\" data-id=\"0f877e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Examens m\u00e9dicaux visant \u00e0 diagnostiquer la maladie de Parkinson\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c1ae2a lista_1 elementor-widget elementor-widget-text-editor\" data-id=\"1c1ae2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les m\u00e9decins peuvent utiliser un ou plusieurs des examens suivants pour les aider \u00e0 \u00e9carter d&rsquo;autres pathologies :<\/p><ul><li><b>Tomographie par \u00e9mission monophotonique (TEMP) : <\/b>Elle peut aider \u00e0 d\u00e9terminer s&rsquo;il y a une perte de cellules productrices de dopamine dans le cerveau, ce qui peut indiquer une MP.<\/li><li><b>Tomodensitom\u00e9trie (TDM) : <\/b>Ces radiographies du cerveau permettent d&rsquo;\u00e9carter les maladies vasculaires et les tumeurs.<\/li><li><b>IRM (imagerie par r\u00e9sonance magn\u00e9tique) : <\/b>Les charges magn\u00e9tiques sont utilis\u00e9es pour cr\u00e9er des images du cerveau. Elles peuvent \u00eatre utilis\u00e9es pour aider \u00e0 distinguer la maladie de Parkinson des maladies apparent\u00e9es, telles que la paralysie supranucl\u00e9aire progressive (PSP) et l&rsquo;atrophie multisyst\u00e9mique (AMS).<\/li><li><b>Examens sanguins : <\/b>Une s\u00e9rie d&rsquo;analyses sanguines peut aider \u00e0 \u00e9carter des troubles tels que des niveaux anormaux d&rsquo;hormones thyro\u00efdiennes ou des l\u00e9sions h\u00e9patiques.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0b92d8 elementor-widget elementor-widget-heading\" data-id=\"d0b92d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Traitement et m\u00e9dicaments<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17aa45b elementor-widget elementor-widget-text-editor\" data-id=\"17aa45b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il n&rsquo;existe pas de traitement unique pour gu\u00e9rir la maladie de Parkinson, mais de nombreux m\u00e9dicaments et th\u00e9rapies pouvant aider \u00e0 contr\u00f4ler ses sympt\u00f4mes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbf6b87 elementor-widget elementor-widget-heading\" data-id=\"fbf6b87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment traite-t-on la maladie de Parkinson ?\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5d2b43 elementor-widget elementor-widget-text-editor\" data-id=\"f5d2b43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Plusieurs m\u00e9dicaments sont disponibles pour am\u00e9liorer les sympt\u00f4mes de la MP. Les th\u00e9rapies de soutien telles que la kin\u00e9sith\u00e9rapie, l&rsquo;orthophonie et l&rsquo;ergoth\u00e9rapie peuvent \u00e9galement apporter un b\u00e9n\u00e9fice important en permettant aux personnes atteintes de la maladie de Parkinson de mener une vie ind\u00e9pendante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4827d7c elementor-position-inline-start icon_mini_box lista_1 elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4827d7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tM\u00e9dicaments\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDe nombreux m\u00e9dicaments produisent une nette am\u00e9lioration au d\u00e9part, mais leur efficacit\u00e9 peut diminuer ou devenir irr\u00e9guli\u00e8re au fil du temps, et il peut alors \u00eatre n\u00e9cessaire de les adapter \u00e0 l'\u00e9volution de la maladie.<br><br>\nLes sympt\u00f4mes de la maladie de Parkinson sont li\u00e9s \u00e0 une diminution du taux de dopamine dans le cerveau. Cependant, prendre de la dopamine comme traitement n\u2019est pas envisageable, car elle ne peut pas p\u00e9n\u00e9trer dans le cerveau, l\u00e0 o\u00f9 elle est n\u00e9cessaire. Par cons\u00e9quent, la plupart des m\u00e9dicaments visent \u00e0 augmenter les niveaux de dopamine d'une autre mani\u00e8re.<br><br>\nLes m\u00e9dicaments comprennent :<br><br>\n\n<ul style=\"margin-top: 15px\">\n<li><strong>Agents dopaminergiques :<\/strong>Ceux-ci visent \u00e0 augmenter la dopamine dans le cerveau ou \u00e0 imiter les effets de la dopamine (agonistes de la dopamine).<\/li>\n<li><strong>Inhibiteurs de la monoamine oxydase B :  <\/strong> Ceux-ci aident \u00e0 augmenter les niveaux de dopamine et sont utiles dans les stades pr\u00e9coces de la MP.\n<\/li>\n<li><strong>Inhibiteurs de la cat\u00e9chol-O-m\u00e9thyltransf\u00e9rase (ICOMT) :<\/strong>  Ils sont pris en parall\u00e8le d'un agent dopaminergique pour aider \u00e0 prolonger son efficacit\u00e9 et sont g\u00e9n\u00e9ralement prescrits dans des stades avanc\u00e9s de la maladie de Parkinson.<\/li>\n<\/ul>\nChaque m\u00e9dicament a une s\u00e9rie d'effets secondaires qui doivent toujours \u00eatre pris en compte et discut\u00e9s avec un m\u00e9decin avant la prise du m\u00e9dicament. Les m\u00e9dicaments peuvent se pr\u00e9senter sous diff\u00e9rentes formes, notamment des comprim\u00e9s, des injections et des gels, ce qui offre aux patients un large \u00e9ventail d'options pour r\u00e9pondre \u00e0 leurs besoins individuels.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd6300 elementor-position-inline-start icon_mini_box lista_1 elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7fd6300\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTh\u00e9rapie\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDe nombreuses personnes atteintes de la maladie de Parkinson trouvent que les th\u00e9rapies de soutien sont b\u00e9n\u00e9fiques pour certains sympt\u00f4mes. Dans les premiers stades, les th\u00e9rapies de soutien peuvent suffire \u00e0 aider les patients \u00e0 poursuivre leurs activit\u00e9s quotidiennes sans recourir aux m\u00e9dicaments.<br><br>\nLes s\u00e9ances de physioth\u00e9rapie peuvent \u00eatre b\u00e9n\u00e9fiques pour am\u00e9liorer la souplesse, soulager les rigidit\u00e9s musculaires et r\u00e9duire les douleurs articulaires ; un orthophoniste peut proposer des exercices et des technologies d'assistance pour aider les patients \u00e0 r\u00e9apprendre \u00e0 parler ainsi qu\u2019\u00e0 manger et \u00e0 avaler ; et les \u00e9valuations ergoth\u00e9rapeutiques peuvent identifier les changements \u00e0 apporter \u00e0 la maison, pour aider les patients \u00e0 garder leur ind\u00e9pendance plus longtemps.<br><br>\nApprendre \u00e0 vivre avec la maladie de Parkinson peut \u00eatre extr\u00eamement frustrant. De nombreuses formes de soutien peuvent aider \u00e0 r\u00e9soudre ce probl\u00e8me, notamment les groupes de soutien avec des personnes dans la m\u00eame situation ou les consultations individuelles avec des professionnels. Les m\u00e9decins peuvent fournir de plus amples informations sur les services disponibles \u00e0 l\u2019\u00e9chelon local.<br><br>\n\nTh\u00e9rapies alternatives<br><br>\nDe nombreuses personnes trouvent que les th\u00e9rapies alternatives sont utiles en association avec d'autres traitements pour r\u00e9duire le stress, la d\u00e9pression, la fatigue et la douleur. Par exemple :<br><br>\n<ul>\n<li>Le massage favorise la relaxation et r\u00e9duit les tensions musculaires<\/li>\n<li>Le yoga augmente la souplesse et am\u00e9liore l'\u00e9quilibre<\/li>\n<li>La m\u00e9ditation r\u00e9duit le stress et l'anxi\u00e9t\u00e9<\/li>\n<li>La technique Alexander se concentre sur la posture et l'\u00e9quilibre et peut contribuer \u00e0 r\u00e9duire les tensions et les douleurs musculaires.<\/li><\/ul>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-569457e elementor-position-inline-start icon_mini_box elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"569457e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIntervention\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLa chirurgie utilis\u00e9e pour la maladie de Parkinson est la stimulation c\u00e9r\u00e9brale profonde ou neurostimulation. Elle implique l'implantation d'un neurostimulateur, similaire \u00e0 un stimulateur cardiaque (pacemaker), dans la paroi thoracique. Le stimulateur cardiaque est reli\u00e9 au cerveau via de fines \u00e9lectrodes et un minuscule courant \u00e9lectrique est utilis\u00e9 pour stimuler la partie du cerveau touch\u00e9e par la maladie de Parkinson.<br><br>\nLa stimulation c\u00e9r\u00e9brale profonde n'est pas courante, mais elle est recommand\u00e9e dans certains cas, principalement lorsque les traitements m\u00e9dicamenteux disponibles ne permettent plus de contr\u00f4ler les sympt\u00f4mes.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-845006c elementor-position-inline-start icon_mini_box lista_1 elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"845006c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tR\u00e9gime alimentaire\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLes changements apport\u00e9s au r\u00e9gime alimentaire ne r\u00e9duiront pas les effets de la maladie de Parkinson, mais peuvent participer \u00e0 att\u00e9nuer certains sympt\u00f4mes. Ces derniers comprennent :\n\n<ul style=\"margin-top: 15px\">\n<li>Augmenter la consommation de fibres et boire suffisamment de liquide pour pr\u00e9venir la constipation.\n<\/li>\n<li>\u00c9viter la d\u00e9shydratation (qui peut \u00eatre provoqu\u00e9e par les m\u00e9dicaments de la MP) en buvant assez d'eau et de liquides.\n<\/li>\n<li>S'assurer d\u2019avoir une quantit\u00e9 ad\u00e9quate de sel dans le r\u00e9gime alimentaire pour \u00e9viter l'hypotension et les vertiges. Manger de petits repas plus souvent peut \u00e9galement \u00eatre utile.\n<\/li>\n<\/ul>\nCertaines recherches montrent qu'un r\u00e9gime m\u00e9diterran\u00e9en peut \u00eatre b\u00e9n\u00e9fique pour r\u00e9duire les risques de d\u00e9velopper la maladie de Parkinson. Ces r\u00e9gimes sont g\u00e9n\u00e9ralement riches en l\u00e9gumes, fruits, l\u00e9gumineuses, fruits secs, haricots, c\u00e9r\u00e9ales, grains, poisson et graisses insatur\u00e9es comme l'huile d'olive, et pauvres en viande et en produits laitiers.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75f3403 elementor-position-inline-start icon_mini_box lista_1 elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"75f3403\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFaire du sport\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLe sport peut \u00eatre b\u00e9n\u00e9fique pour les personnes atteintes de la maladie de Parkinson pour plusieurs raisons :\n\n<ul style=\"margin-top: 15px\">\n<li>Il aide \u00e0 augmenter la force musculaire\n<\/li>\n<li>Il am\u00e9liore la flexibilit\u00e9 et l'\u00e9quilibre<\/li>\n<li>Il peut am\u00e9liorer la sant\u00e9 mentale et r\u00e9duire la d\u00e9pression ou l'anxi\u00e9t\u00e9\n<\/li>\n<\/ul>\nLes activit\u00e9s telles que la marche, la natation, le jardinage et le yoga peuvent souvent \u00eatre poursuivies de mani\u00e8re autonome apr\u00e8s le diagnostic de la maladie de Parkinson, ou alors les m\u00e9decins peuvent recommander des s\u00e9ances avec un kin\u00e9sith\u00e9rapeute.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c6a5f3 elementor-widget elementor-widget-heading\" data-id=\"0c6a5f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e9vention\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94d0a4b elementor-widget elementor-widget-text-editor\" data-id=\"94d0a4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aucun traitement ou th\u00e9rapie n&rsquo;a encore \u00e9t\u00e9 trouv\u00e9 pour pr\u00e9venir l&rsquo;apparition de la maladie de Parkinson, bien que des recherches approfondies aient \u00e9t\u00e9 men\u00e9es sur les avantages de l&rsquo;exercice physique \u00e0 un plus jeune \u00e2ge ; il a \u00e9t\u00e9 d\u00e9montr\u00e9 que les personnes faisant du sport ont moins de chances de d\u00e9velopper la maladie de Parkinson.<\/p><p>Toutefois, bien que les recherches associent le sport \u00e0 une diminution du risque de maladie, elles n&rsquo;ont pas prouv\u00e9 que l\u2019activit\u00e9 physique soit la cause de cette r\u00e9duction de risque. Des recherches suppl\u00e9mentaires sont n\u00e9cessaires pour \u00e9tablir s&rsquo;il existe un lien direct.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe8b5d9 elementor-widget elementor-widget-heading\" data-id=\"fe8b5d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9tudes scientifiques\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c864e64 elementor-widget elementor-widget-text-editor\" data-id=\"c864e64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le traitement et la pr\u00e9vention de la maladie de Parkinson constituent un vaste domaine de recherche, et une meilleure compr\u00e9hension de cette affection est un facteur important pour la mise au point de nouveaux m\u00e9dicaments appropri\u00e9s.<\/p><p>Des \u00e9tudes, notamment celle men\u00e9e en Finlande en 2020, portent sur les moyens d&rsquo;augmenter les niveaux de dopamine et de prot\u00e9ger les cellules c\u00e9r\u00e9brales productrices de dopamine contre la mort cellulaire, tandis que d&rsquo;autres recherches se concentrent sur les causes des sympt\u00f4mes moteurs de la maladie de Parkinson. Ces \u00e9tudes donnent aux scientifiques des raisons de croire que de meilleurs moyens de traiter la maladie de Parkinson pourront \u00eatre mis au point \u00e0 l&rsquo;avenir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e67e3fd elementor-widget elementor-widget-heading\" data-id=\"e67e3fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sources\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b8ebe8 lista elementor-widget elementor-widget-text-editor\" data-id=\"6b8ebe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>\u00a0GBD 2015 Neurological Disorders Collaborator Group. Global, regional, and national burden of neurological disorders during 1990\u20132015: a systematic analysis for the Global Burden of Disease Study 2015. <i>Lancet Neurol<\/i>. 2017;16(11):877-897. doi:10.1016\/S1474-4422(17)30299-5<\/li><li>\u00a0European Commission. Health research on Parkinson&rsquo;s disease Accessed February 23, 2021. <a href=\"https:\/\/ec.europa.eu\/research\/health\/pdf\/factsheets\/parkinsons.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/ec.europa.eu\/research\/health\/pdf\/factsheets\/parkinsons.pdf<\/a><\/li><li>\u00a0Aaseth J, Dusek P, Roos PM. Prevention of progression in Parkinson\u2019s disease. <i>Biometals<\/i>. 2018;31(5):737-747. doi:10.1007\/s10534-018-0131-5<\/li><li>\u00a0Delic V, Beck KD, Pang KCH\u00a0et al<i>.<\/i>\u00a0Biological links between traumatic brain injury and Parkinson\u2019s disease.\u00a0<i>Acta Neuropathol Commun.<\/i>\u00a02020;8(1):45. doi:10.1186\/s40478-020-00924-7<\/li><li>\u00a0Parkinson\u2019s causes. The European Parkinson\u2019s Disease Association (EPDA). Updated September 2018. Accessed February 2021 <a href=\"https:\/\/www.epda.eu.com\/about-parkinsons\/causes\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.epda.eu.com\/about-parkinsons\/causes\/<\/a><\/li><li>The European Parkinson\u2019s Disease Association (EPDA). Response to the European Commission\u2019s Consultation on the Green Paper on a Common Strategic. Framework for future EU Research and Innovation Funding. Accessed February 2021.\u00a0<\/li><li>Miller IN, Cronin-Golomb A. Gender differences in Parkinson\u2019s disease: clinical characteristics and cognition. <i>Mov Disord<\/i>. 2010;25(16):2695-2703. doi:10.1002\/mds.23388<\/li><li>\u00a0Alcalay RN, Gu Y, Mejia-Santana H et al. The association between Mediterranean diet adherence and Parkinson\u2019s disease. <i>Mov Disord<\/i>. 2012;27(6):771-4. doi:10.1002\/mds.24918<\/li><li>\u00a0Fan B, Jabeen R, Bo B et al. What and how can physical activity prevention function on Parkinson\u2019s disease? <i>Oxid Med Cell Longev<\/i>. 2020;2020:4293071<\/li><li>\u00a0Mahato AK, Kopra J, Renko J\u2010M et al. Glial cell line\u2013derived neurotrophic factor receptor rearranged during transfection agonist supports dopamine neurons in vitro and enhances dopamine release in vivo. <i>Mov Disord.<\/i> 2020;35:245-255. doi:10.1002\/mds.27943<\/li><li>\u00a0Heo JY, Nam M-H, Yoon HH et al. Aberrant Tonic Inhibition of Dopaminergic Neuronal Activity Causes Motor Symptoms in Animal Models of Parkinson\u2019s Disease. <i>Curr Biol<\/i>. 2020;30(2):276-291.e9. doi:10.1016\/j.cub.2019.11.079<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c55bb2f elementor-widget elementor-widget-spacer\" data-id=\"c55bb2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6166b89 stop-sticky elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6166b89\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;efcf18a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-29241b4\" data-id=\"29241b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7098f8 elementor-widget elementor-widget-heading\" data-id=\"e7098f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Vous pourriez \u00eatre int\u00e9ress\u00e9 par...<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0cc8899\" data-id=\"0cc8899\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f3ab93 elementor-icon-list--layout-inline elementor-align-end read_more_reverse elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8f3ab93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.neuraxpharm.com\/fr\/blog\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aller sur au blog Neuraxpharm<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fe4344 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fe4344\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;426e004&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf0f07c\" data-id=\"cf0f07c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75135bf blog-category elementor-widget elementor-widget-jet-listing-grid\" data-id=\"75135bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-not-found jet-listing-grid__items\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:3578,&quot;posts_num&quot;:3,&quot;columns&quot;:3,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-listing-source=\"posts\" data-listing-id=\"3578\" data-query-id=\"\" data-queried-id=\"3611|WP_Post\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"22519\" class=\"elementor elementor-22519\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd8561e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd8561e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;7a0f9f5&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d93a1f\" data-id=\"0d93a1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-037f64f blog-category elementor-widget elementor-widget-jet-listing-grid\" data-id=\"037f64f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-notice\">Please select another listing to show to avoid recursion.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><style>.elementor-22519 .elementor-element.elementor-element-dd8561e .elementor-repeater-item-7a0f9f5.jet-parallax-section__layout .jet-parallax-section__image{background-size:auto;}.elementor-22519 .elementor-element.elementor-element-0d93a1f > .elementor-element-populated{text-align:start;padding:0px 0px 0px 0px;}.elementor-22519 .elementor-element.elementor-element-037f64f > .elementor-widget-container > .jet-listing-grid > .jet-listing-grid__items, .elementor-22519 .elementor-element.elementor-element-037f64f > .jet-listing-grid > .jet-listing-grid__items{--columns:3;}:root{--page-title-display:none;}@media(max-width:1024px){.elementor-22519 .elementor-element.elementor-element-037f64f > .elementor-widget-container > .jet-listing-grid > .jet-listing-grid__items, .elementor-22519 .elementor-element.elementor-element-037f64f > .jet-listing-grid > .jet-listing-grid__items{--columns:2;}}@media(max-width:767px){.elementor-22519 .elementor-element.elementor-element-037f64f > .elementor-widget-container > .jet-listing-grid > .jet-listing-grid__items, .elementor-22519 .elementor-element.elementor-element-037f64f > .jet-listing-grid > .jet-listing-grid__items{--columns:1;}}<\/style><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-196ac74 elementor-widget elementor-widget-spacer\" data-id=\"196ac74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DANS CETTE SECTION Articles connexes DANS CETTE SECTION Neuraxpharm La maladie de Parkinson touche principalement les personnes \u00e2g\u00e9es en ralentissant les fonctions du corps et en affectant sa capacit\u00e9 \u00e0 contr\u00f4ler les mouvements.\u00a0D\u00e9couvrez les sympt\u00f4mes, le diagnostic et le traitement de cette maladie. Qu&rsquo;est-ce que la maladie de Parkinson ? La maladie de Parkinson (MP) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":28911,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-3611","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Maladie de Parkinson : sympt\u00f4mes, diagnostic - Neuraxpharm France<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les sympt\u00f4mes, le diagnostic et les traitements de la maladie de Parkinson, une affection neurod\u00e9g\u00e9n\u00e9rative qui affecte le contr\u00f4le des mouvements. Apprenez-en plus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maladie de Parkinson\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les sympt\u00f4mes, le diagnostic et les traitements de la maladie de Parkinson, une affection neurod\u00e9g\u00e9n\u00e9rative qui affecte le contr\u00f4le des mouvements. Apprenez-en plus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson\/\" \/>\n<meta property=\"og:site_name\" content=\"Neuraxpharm France\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T09:35:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/specialisation-snc\\\/troubles-neurologiques\\\/parkinson\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/specialisation-snc\\\/troubles-neurologiques\\\/parkinson\\\/\",\"name\":\"Maladie de Parkinson : sympt\u00f4mes, diagnostic - Neuraxpharm France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-03-11T11:56:47+00:00\",\"dateModified\":\"2026-05-11T09:35:59+00:00\",\"description\":\"D\u00e9couvrez les sympt\u00f4mes, le diagnostic et les traitements de la maladie de Parkinson, une affection neurod\u00e9g\u00e9n\u00e9rative qui affecte le contr\u00f4le des mouvements. Apprenez-en plus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/specialisation-snc\\\/troubles-neurologiques\\\/parkinson\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/specialisation-snc\\\/troubles-neurologiques\\\/parkinson\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/specialisation-snc\\\/troubles-neurologiques\\\/parkinson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Sp\u00e9cialisation SNC\",\"item\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/specialisation-snc\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Troubles neurologiques\",\"item\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/specialisation-snc\\\/troubles-neurologiques\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maladie de Parkinson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/\",\"name\":\"Neuraxpharm France\",\"description\":\"Ein europ\u00e4ischer Marktf\u00fchrer f\u00fcr CNS-Produkte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Maladie de Parkinson : sympt\u00f4mes, diagnostic - Neuraxpharm France","description":"D\u00e9couvrez les sympt\u00f4mes, le diagnostic et les traitements de la maladie de Parkinson, une affection neurod\u00e9g\u00e9n\u00e9rative qui affecte le contr\u00f4le des mouvements. Apprenez-en plus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson","og_locale":"fr_FR","og_type":"article","og_title":"Maladie de Parkinson","og_description":"D\u00e9couvrez les sympt\u00f4mes, le diagnostic et les traitements de la maladie de Parkinson, une affection neurod\u00e9g\u00e9n\u00e9rative qui affecte le contr\u00f4le des mouvements. Apprenez-en plus.","og_url":"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson\/","og_site_name":"Neuraxpharm France","article_modified_time":"2026-05-11T09:35:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson","url":"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson\/","name":"Maladie de Parkinson : sympt\u00f4mes, diagnostic - Neuraxpharm France","isPartOf":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/#website"},"datePublished":"2021-03-11T11:56:47+00:00","dateModified":"2026-05-11T09:35:59+00:00","description":"D\u00e9couvrez les sympt\u00f4mes, le diagnostic et les traitements de la maladie de Parkinson, une affection neurod\u00e9g\u00e9n\u00e9rative qui affecte le contr\u00f4le des mouvements. Apprenez-en plus.","breadcrumb":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques\/parkinson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Sp\u00e9cialisation SNC","item":"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc"},{"@type":"ListItem","position":2,"name":"Troubles neurologiques","item":"https:\/\/www.neuraxpharm.com\/fr\/specialisation-snc\/troubles-neurologiques"},{"@type":"ListItem","position":3,"name":"Maladie de Parkinson"}]},{"@type":"WebSite","@id":"https:\/\/www.neuraxpharm.com\/fr\/#website","url":"https:\/\/www.neuraxpharm.com\/fr\/","name":"Neuraxpharm France","description":"Ein europ\u00e4ischer Marktf\u00fchrer f\u00fcr CNS-Produkte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neuraxpharm.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/pages\/3611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/comments?post=3611"}],"version-history":[{"count":5,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/pages\/3611\/revisions"}],"predecessor-version":[{"id":28241,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/pages\/3611\/revisions\/28241"}],"up":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/pages\/28911"}],"wp:attachment":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/media?parent=3611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}