{"id":2171,"date":"2021-03-02T15:18:45","date_gmt":"2021-03-02T15:18:45","guid":{"rendered":"https:\/\/www.neuraxpharm.com\/it2\/?page_id=2171"},"modified":"2026-07-28T07:48:27","modified_gmt":"2026-07-28T07:48:27","slug":"notre-responsabilite","status":"publish","type":"page","link":"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite","title":{"rendered":"Notre responsabilit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2171\" class=\"elementor elementor-2171\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25b3bac elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom banner_top elementor-section-height-default\" data-id=\"25b3bac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;00936a0&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19630a2\" data-id=\"19630a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a5efab3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5efab3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;650699a&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b57c5c1\" data-id=\"b57c5c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-bec3035\" data-id=\"bec3035\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31684a7 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"31684a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Notre responsabilit\u00e9<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bb59c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bb59c9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;245babd&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b8963b8 sticky-parent\" data-id=\"b8963b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c9963e5 sticky-column elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9963e5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;87539ac&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b2e1078\" data-id=\"b2e1078\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f2467c elementor-widget elementor-widget-heading\" data-id=\"9f2467c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">TOUT SUR NOTRE RESPONSABILIT\u00c9\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e031819 elementor-position-inline-end box-readmore sidebar elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e031819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#responsibility\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u00c0 propos de la responsabilit\u00e9\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#responsibility\" >\n\t\t\t\t\t\t\t\u00c0 propos de la responsabilit\u00e9\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edee852 elementor-position-inline-end box-readmore sidebar elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"edee852\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#ESG\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Faire avancer une strat\u00e9gie ESG\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#ESG\" >\n\t\t\t\t\t\t\tFaire avancer une strat\u00e9gie ESG\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc99e3a elementor-position-inline-end box-readmore sidebar elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"dc99e3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#Pillars\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Nos piliers ESG \">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#Pillars\" >\n\t\t\t\t\t\t\tNos piliers ESG \t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4f6fd8 elementor-position-inline-end box-readmore sidebar elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f4f6fd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#Diversity\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Diversit\u00e9, \u00e9galit\u00e9 et inclusion\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#Diversity\" >\n\t\t\t\t\t\t\tDiversit\u00e9, \u00e9galit\u00e9 et inclusion\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3cdff1 elementor-position-inline-end box-readmore sidebar elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a3cdff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#Ethics\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"\u00c9thique et conformit\u00e9\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#Ethics\" >\n\t\t\t\t\t\t\t\u00c9thique et conformit\u00e9\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4cb66a3\" data-id=\"4cb66a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ce19ba4\" data-id=\"ce19ba4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-756ff9e elementor-widget elementor-widget-spacer\" data-id=\"756ff9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b3e93c elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"5b3e93c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/www.neuraxpharm.com\/fr\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Neuraxpharm\">Neuraxpharm <\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c3c0e0 elementor-widget elementor-widget-text-editor\" data-id=\"2c3c0e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En tant qu&rsquo;entreprise de soins de sant\u00e9 sp\u00e9cialis\u00e9e dans le syst\u00e8me nerveux central (SNC), nous avons la responsabilit\u00e9 d&rsquo;am\u00e9liorer la qualit\u00e9 de vie et le bien-\u00eatre mental des personnes atteintes de maladies mentales et de troubles neurologiques.<\/p><p>Nous visons \u00e0 le faire en construisant un avenir durable, en prenant des mesures int\u00e9gr\u00e9es pour g\u00e9rer une entreprise responsable et en soutenant les familles dans le besoin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1da20ad elementor-widget elementor-widget-heading\" data-id=\"1da20ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Chez Neuraxpharm<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68e4c4b elementor-widget elementor-widget-menu-anchor\" data-id=\"68e4c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"responsibility\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97cbafc no_in_this_section elementor-widget elementor-widget-heading\" data-id=\"97cbafc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les patients et leurs familles avant tout<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd0cbdd elementor-widget elementor-widget-text-editor\" data-id=\"cd0cbdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous collaborons avec des partenaires du secteur de la sant\u00e9 et de l\u2019industrie pharmaceutique pour construire un mod\u00e8le \u00e9conomique plus durable. Ensemble, nous \u0153uvrons pour prot\u00e9ger la sant\u00e9 des individus et pr\u00e9server le monde dans lequel nous vivons, tout en soutenant les familles de nos patients.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dad8aa0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dad8aa0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;1124abe&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bcbd455\" data-id=\"bcbd455\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24f5e48 elementor-widget elementor-widget-text-editor\" data-id=\"24f5e48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans cette optique, nous nous engageons \u00e9galement \u00e0 sensibiliser la soci\u00e9t\u00e9 \u00e0 l&rsquo;importance de d\u00e9passer les id\u00e9es re\u00e7ues et la stigmatisation associ\u00e9e.<\/p><p>Nos \u00e9quipes travaillent sans rel\u00e2che \u00e0 la cr\u00e9ation de campagnes de sensibilisation et de contenus scientifiques fiables, diffus\u00e9s sur notre site web et nos r\u00e9seaux sociaux. Nous collaborons \u00e9galement avec les professionnels de sant\u00e9 et les associations de patients, afin d&rsquo;apporter des am\u00e9liorations significatives \u00e0 la vie et au bien-\u00eatre des personnes vivant avec une maladie mentale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-32160f5\" data-id=\"32160f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c15d01 elementor-widget elementor-widget-image\" data-id=\"1c15d01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"464\" height=\"261\" src=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081957\/imgi-7-group-111.jpg\" class=\"attachment-large size-large wp-image-28979\" alt=\"Strat\u00e9gie patient centr\u00e9e innovation et engagement social\" srcset=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081957\/imgi-7-group-111.jpg 464w, https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081957\/imgi-7-group-111-300x169.jpg 300w\" sizes=\"(max-width: 464px) 100vw, 464px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f31b71b elementor-widget elementor-widget-spacer\" data-id=\"f31b71b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2cff47 elementor-widget elementor-widget-menu-anchor\" data-id=\"d2cff47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ESG\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9b8b7d no_in_this_section elementor-widget elementor-widget-heading\" data-id=\"c9b8b7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Promouvoir une strat\u00e9gie ESG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-756490d elementor-widget elementor-widget-heading\" data-id=\"756490d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Faire progresser une strat\u00e9gie ESG ayant un impact positif sur notre communaut\u00e9 et sur le monde qui nous entoure.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e50c08b elementor-widget elementor-widget-text-editor\" data-id=\"e50c08b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0Nous proposons des solutions de premier plan sur le march\u00e9 du SNC et nous nous engageons \u00e0 contribuer \u00e0 un monde meilleur, conscients de l&rsquo;importance croissante d&rsquo;aborder un spectre plus large de th\u00e9matiques li\u00e9es \u00e0 la durabilit\u00e9, essentielles pour notre activit\u00e9 et pour nos parties prenantes.<\/p><p>\u00a0C\u2019est pourquoi nous envisageons de mener nos actions dans le domaine du SNC sous l\u2019angle de l\u2019ESG (Environnement, Social et Gouvernance), notre mission \u00e9tant d\u2019avoir un impact positif sur le monde et sur la vie du plus grand nombre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6ce66e elementor-widget elementor-widget-spacer\" data-id=\"e6ce66e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c2f5058 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2f5058\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dc369df\" data-id=\"dc369df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ee1cb0 elementor-widget elementor-widget-image\" data-id=\"9ee1cb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"451\" src=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2026\/07\/28074623\/neuraxpharm-sustainability-report-2025-cover-1024x577.jpg\" class=\"attachment-large size-large wp-image-29190\" alt=\"\" srcset=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2026\/07\/28074623\/neuraxpharm-sustainability-report-2025-cover-1024x577.jpg 1024w, https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2026\/07\/28074623\/neuraxpharm-sustainability-report-2025-cover-300x169.jpg 300w, https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2026\/07\/28074623\/neuraxpharm-sustainability-report-2025-cover-768x433.jpg 768w, https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2026\/07\/28074623\/neuraxpharm-sustainability-report-2025-cover-1536x866.jpg 1536w, https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2026\/07\/28074623\/neuraxpharm-sustainability-report-2025-cover-2048x1154.jpg 2048w, https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2026\/07\/28074623\/neuraxpharm-sustainability-report-2025-cover-600x338.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec01d15 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ec01d15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2026\/07\/28074734\/neuraxpharm-sustainability-report-2025.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger le rapport ESG<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-51c4a64 elementor-widget elementor-widget-spacer\" data-id=\"51c4a64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57b225d elementor-widget elementor-widget-menu-anchor\" data-id=\"57b225d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Pillars\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30ea626 no_in_this_section elementor-widget elementor-widget-heading\" data-id=\"30ea626\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos Pilliers ESG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03e790c elementor-widget elementor-widget-text-editor\" data-id=\"03e790c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le cadre ESG de Neuraxpharm repose sur cinq piliers strat\u00e9giques :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1249b4 elementor-widget elementor-widget-n-accordion\" data-id=\"a1249b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1680\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1680\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Notre communaut\u00e9 SNC <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"#00B2E3\"><\/circle><path d=\"M23.4288 35.4949C22.7906 34.7858 21.7108 34.6502 20.9171 35.1793C20.4771 35.4726 20.1824 35.9205 20.0871 36.4406C19.9918 36.9605 20.1085 37.4839 20.4158 37.9142L23.0959 41.6663C23.2934 41.9429 23.678 42.007 23.9546 41.8094C24.2313 41.6117 24.2953 41.2273 24.0977 40.9507L21.4177 37.1986C21.3059 37.0422 21.2634 36.8518 21.2981 36.6627C21.3327 36.4735 21.44 36.3105 21.6 36.2038C21.8888 36.0114 22.2815 36.0607 22.5136 36.3187L26.574 40.8302C27.3918 41.7388 27.8421 42.9124 27.8421 44.1347V51.7249C27.8421 52.0649 28.1177 52.3405 28.4577 52.3405C28.7977 52.3405 29.0733 52.0649 29.0733 51.7249V44.1347C29.0733 42.6077 28.5107 41.1416 27.4892 40.0066L23.4288 35.4949Z\" fill=\"white\"><\/path><path d=\"M18.6056 38.9718C17.9457 38.1496 17.4374 37.2272 17.0948 36.2303L14.2764 28.0272C14.199 27.802 14.219 27.5628 14.3326 27.3536C14.4462 27.1444 14.636 26.9974 14.867 26.9396C15.2749 26.8378 15.698 27.0557 15.8519 27.4465L18.5084 34.1879C18.633 34.5042 18.9906 34.6596 19.3068 34.5349C19.6232 34.4103 19.7785 34.0528 19.6539 33.7366L16.9973 26.9951C16.6176 26.0312 15.5731 25.4939 14.5683 25.7452C14.0069 25.8855 13.5267 26.2576 13.2506 26.7661C12.9744 27.2746 12.924 27.8801 13.1119 28.4273L15.9304 36.6304C16.3193 37.7622 16.8963 38.8093 17.6454 39.7426L22.3506 45.6041C22.7561 46.1093 22.9795 46.7444 22.9795 47.3922V51.7264C22.9795 52.0664 23.2551 52.342 23.5951 52.342C23.935 52.342 24.2107 52.0664 24.2107 51.7264V47.3922C24.2107 46.4651 23.8911 45.5564 23.3107 44.8333L18.6056 38.9718Z\" fill=\"white\"><\/path><path d=\"M46.4245 36.2039C46.5846 36.3106 46.6918 36.4735 46.7264 36.6627C46.7611 36.8519 46.7186 37.0422 46.6068 37.1987L43.9268 40.9507C43.7291 41.2274 43.7932 41.6119 44.0699 41.8094C44.3466 42.0071 44.7311 41.943 44.9286 41.6663L47.6087 37.9143C47.916 37.484 48.0327 36.9607 47.9374 36.4406C47.8421 35.9205 47.5474 35.4726 47.1074 35.1794C46.3137 34.6501 45.2338 34.7859 44.5957 35.495L40.5353 40.0065C39.5137 41.1416 38.9512 42.6077 38.9512 44.1347V51.7248C38.9512 52.0648 39.2268 52.3404 39.5668 52.3404C39.9067 52.3404 40.1824 52.0648 40.1824 51.7248V44.1347C40.1824 42.9123 40.6327 41.7388 41.4505 40.8301L45.5109 36.3185C45.7429 36.0607 46.1358 36.0113 46.4245 36.2039Z\" fill=\"white\"><\/path><path d=\"M54.7725 26.7661C54.4965 26.2577 54.0162 25.8856 53.4548 25.7452C52.4498 25.4939 51.4055 26.0313 51.0258 26.9951L48.3693 33.7366C48.2447 34.0529 48.4001 34.4103 48.7164 34.535C49.0327 34.6596 49.3902 34.5042 49.5148 34.1879L52.1713 27.4465C52.3253 27.0557 52.7488 26.8378 53.1563 26.9396C53.3872 26.9974 53.577 27.1444 53.6906 27.3536C53.8042 27.5629 53.8242 27.802 53.7469 28.0273L50.9284 36.2304C50.5859 37.2274 50.0776 38.1498 49.4176 38.9719L44.7125 44.8334C44.1321 45.5564 43.8125 46.4651 43.8125 47.3922V51.7264C43.8125 52.0664 44.0881 52.342 44.4281 52.342C44.7681 52.342 45.0437 52.0664 45.0437 51.7264V47.3922C45.0437 46.7443 45.267 46.1093 45.6726 45.6041L50.3777 39.7426C51.1269 38.8094 51.7039 37.7623 52.0928 36.6305L54.9112 28.4273C55.0992 27.8801 55.0487 27.2746 54.7725 26.7661Z\" fill=\"white\"><\/path><path d=\"M40.1818 28.809V23.9479C40.1818 22.0769 38.6596 20.5547 36.7885 20.5547H31.2331C29.362 20.5547 27.8398 22.0769 27.8398 23.9479V28.809C27.8398 29.9142 28.739 30.8134 29.8442 30.8134C30.1182 30.8134 30.3794 30.758 30.6175 30.6581V37.8365C30.6175 38.9417 31.5167 39.8409 32.6219 39.8409C33.1607 39.8409 33.6502 39.6268 34.0108 39.2797C34.3713 39.6268 34.8608 39.8409 35.3996 39.8409C36.5048 39.8409 37.404 38.9417 37.404 37.8365V30.6581C37.6421 30.758 37.9033 30.8134 38.1773 30.8134C39.2826 30.8134 40.1818 29.9142 40.1818 28.809ZM37.404 28.809V24.6424C37.404 24.3024 37.1284 24.0268 36.7884 24.0268C36.4485 24.0268 36.1728 24.3024 36.1728 24.6424V37.8365C36.1728 38.2629 35.826 38.6097 35.3996 38.6097C34.9732 38.6097 34.6264 38.2628 34.6264 37.8365V28.809C34.6264 28.469 34.3507 28.1934 34.0108 28.1934C33.6708 28.1934 33.3952 28.469 33.3952 28.809V37.8365C33.3952 38.2629 33.0483 38.6097 32.6219 38.6097C32.1956 38.6097 31.8487 38.2628 31.8487 37.8365V24.6425C31.8487 24.3025 31.5731 24.0269 31.2331 24.0269C30.8931 24.0269 30.6175 24.3025 30.6175 24.6425V28.809C30.6175 29.2354 30.2706 29.5823 29.8442 29.5823C29.4179 29.5823 29.071 29.2354 29.071 28.809V23.948C29.071 22.7559 30.041 21.786 31.2331 21.786H36.7885C37.9806 21.786 38.9506 22.7558 38.9506 23.948V28.809C38.9506 29.2354 38.6037 29.5823 38.1774 29.5823C37.7509 29.5822 37.404 29.2354 37.404 28.809Z\" fill=\"white\"><\/path><path d=\"M34.0118 19.7033C35.3085 19.7033 36.3635 18.6484 36.3635 17.3517C36.3635 16.055 35.3085 15 34.0118 15C32.7151 15 31.6602 16.055 31.6602 17.3517C31.6602 18.6484 32.7151 19.7033 34.0118 19.7033ZM34.0118 16.2312C34.6296 16.2312 35.1323 16.7339 35.1323 17.3517C35.1323 17.9695 34.6296 18.4721 34.0118 18.4721C33.394 18.4721 32.8914 17.9695 32.8914 17.3517C32.8914 16.7339 33.394 16.2312 34.0118 16.2312Z\" fill=\"white\"><\/path><path d=\"M25.0625 30.1976V34.677C25.0625 35.017 25.3381 35.2926 25.6781 35.2926C26.0181 35.2926 26.2937 35.017 26.2937 34.677V30.1976C26.2937 29.8577 26.0181 29.582 25.6781 29.582C25.3381 29.582 25.0625 29.8577 25.0625 30.1976Z\" fill=\"white\"><\/path><path d=\"M28.4554 32.3613C28.1155 32.3613 27.8398 32.637 27.8398 32.9769V37.8379C27.8398 38.1779 28.1155 38.4535 28.4554 38.4535C28.7954 38.4535 29.071 38.1779 29.071 37.8379V32.9769C29.071 32.637 28.7955 32.3613 28.4554 32.3613Z\" fill=\"white\"><\/path><path d=\"M21.5123 32.2032C21.7862 32.2032 22.0474 32.1478 22.2855 32.0478V32.9764C22.2855 33.3164 22.5611 33.592 22.9011 33.592C23.241 33.592 23.5167 33.3164 23.5167 32.9764V25.3377C23.5167 24.9978 23.241 24.7221 22.9011 24.7221C22.5611 24.7221 22.2855 24.9978 22.2855 25.3377V30.1988C22.2855 30.6251 21.9386 30.972 21.5122 30.972C21.0859 30.972 20.739 30.6251 20.739 30.1988V24.6433C20.739 23.4511 21.7089 22.4812 22.9011 22.4812H26.3732C26.7132 22.4812 26.9888 22.2057 26.9888 21.8656C26.9888 21.5256 26.7132 21.25 26.3732 21.25H22.9011C21.03 21.25 19.5078 22.7723 19.5078 24.6433V30.1988C19.5078 31.304 20.407 32.2032 21.5123 32.2032Z\" fill=\"white\"><\/path><path d=\"M25.6778 20.3986C26.9745 20.3986 28.0295 19.3437 28.0295 18.047C28.0295 16.7503 26.9745 15.6953 25.6778 15.6953C24.3811 15.6953 23.3262 16.7503 23.3262 18.047C23.3262 19.3437 24.3811 20.3986 25.6778 20.3986ZM25.6778 16.9265C26.2957 16.9265 26.7983 17.4292 26.7983 18.047C26.7983 18.6648 26.2957 19.1675 25.6778 19.1675C25.06 19.1675 24.5574 18.6648 24.5574 18.047C24.5574 17.4292 25.0599 16.9265 25.6778 16.9265Z\" fill=\"white\"><\/path><path d=\"M41.7285 30.1976V34.677C41.7285 35.017 42.0041 35.2926 42.3441 35.2926C42.6841 35.2926 42.9597 35.017 42.9597 34.677V30.1976C42.9597 29.8577 42.6841 29.582 42.3441 29.582C42.0041 29.582 41.7285 29.8577 41.7285 30.1976Z\" fill=\"white\"><\/path><path d=\"M38.9512 32.9769V37.8379C38.9512 38.1779 39.2268 38.4535 39.5668 38.4535C39.9067 38.4535 40.1824 38.1779 40.1824 37.8379V32.9769C40.1824 32.637 39.9067 32.3613 39.5668 32.3613C39.2268 32.3613 38.9512 32.637 38.9512 32.9769Z\" fill=\"white\"><\/path><path d=\"M41.0352 21.8656C41.0352 22.2057 41.3108 22.4812 41.6508 22.4812H45.1229C46.315 22.4812 47.285 23.4511 47.285 24.6433V30.1988C47.285 30.6251 46.9381 30.972 46.5117 30.972C46.0854 30.972 45.7385 30.6251 45.7385 30.1988V25.3377C45.7385 24.9978 45.4629 24.7221 45.1229 24.7221C44.7829 24.7221 44.5073 24.9978 44.5073 25.3377V32.9764C44.5073 33.3164 44.7829 33.592 45.1229 33.592C45.4629 33.592 45.7385 33.3164 45.7385 32.9764V32.0478C45.9766 32.1478 46.2378 32.2032 46.5118 32.2032C47.617 32.2032 48.5162 31.304 48.5162 30.1988V24.6433C48.5162 22.7723 46.994 21.25 45.1229 21.25H41.6508C41.3108 21.25 41.0352 21.5256 41.0352 21.8656Z\" fill=\"white\"><\/path><path d=\"M42.3439 20.3986C43.6406 20.3986 44.6955 19.3437 44.6955 18.047C44.6955 16.7503 43.6406 15.6953 42.3439 15.6953C41.0472 15.6953 39.9922 16.7503 39.9922 18.047C39.9922 19.3437 41.0472 20.3986 42.3439 20.3986ZM42.3439 16.9265C42.9617 16.9265 43.4643 17.4292 43.4643 18.047C43.4643 18.6648 42.9617 19.1675 42.3439 19.1675C41.726 19.1675 41.2234 18.6648 41.2234 18.047C41.2234 17.4292 41.726 16.9265 42.3439 16.9265Z\" fill=\"white\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"white\"><\/circle><path d=\"M23.4288 35.4949C22.7906 34.7858 21.7108 34.6502 20.9171 35.1793C20.4771 35.4726 20.1824 35.9205 20.0871 36.4406C19.9918 36.9605 20.1085 37.4839 20.4158 37.9142L23.0959 41.6663C23.2934 41.9429 23.678 42.007 23.9546 41.8094C24.2313 41.6117 24.2953 41.2273 24.0977 40.9507L21.4177 37.1986C21.3059 37.0422 21.2634 36.8518 21.2981 36.6627C21.3327 36.4735 21.44 36.3105 21.6 36.2038C21.8888 36.0114 22.2815 36.0607 22.5136 36.3187L26.574 40.8302C27.3918 41.7388 27.8421 42.9124 27.8421 44.1347V51.7249C27.8421 52.0649 28.1177 52.3405 28.4577 52.3405C28.7977 52.3405 29.0733 52.0649 29.0733 51.7249V44.1347C29.0733 42.6077 28.5107 41.1416 27.4892 40.0066L23.4288 35.4949Z\" fill=\"#00B2E3\"><\/path><path d=\"M18.6056 38.9718C17.9457 38.1496 17.4374 37.2272 17.0948 36.2303L14.2764 28.0272C14.199 27.802 14.219 27.5628 14.3326 27.3536C14.4462 27.1444 14.636 26.9974 14.867 26.9396C15.2749 26.8378 15.698 27.0557 15.8519 27.4465L18.5084 34.1879C18.633 34.5042 18.9906 34.6596 19.3068 34.5349C19.6232 34.4103 19.7785 34.0528 19.6539 33.7366L16.9973 26.9951C16.6176 26.0312 15.5731 25.4939 14.5683 25.7452C14.0069 25.8855 13.5267 26.2576 13.2506 26.7661C12.9744 27.2746 12.924 27.8801 13.1119 28.4273L15.9304 36.6304C16.3193 37.7622 16.8963 38.8093 17.6454 39.7426L22.3506 45.6041C22.7561 46.1093 22.9795 46.7444 22.9795 47.3922V51.7264C22.9795 52.0664 23.2551 52.342 23.5951 52.342C23.935 52.342 24.2107 52.0664 24.2107 51.7264V47.3922C24.2107 46.4651 23.8911 45.5564 23.3107 44.8333L18.6056 38.9718Z\" fill=\"#00B2E3\"><\/path><path d=\"M46.4245 36.2039C46.5846 36.3106 46.6918 36.4735 46.7264 36.6627C46.7611 36.8519 46.7186 37.0422 46.6068 37.1987L43.9268 40.9507C43.7291 41.2274 43.7932 41.6119 44.0699 41.8094C44.3466 42.0071 44.7311 41.943 44.9286 41.6663L47.6087 37.9143C47.916 37.484 48.0327 36.9607 47.9374 36.4406C47.8421 35.9205 47.5474 35.4726 47.1074 35.1794C46.3137 34.6501 45.2338 34.7859 44.5957 35.495L40.5353 40.0065C39.5137 41.1416 38.9512 42.6077 38.9512 44.1347V51.7248C38.9512 52.0648 39.2268 52.3404 39.5668 52.3404C39.9067 52.3404 40.1824 52.0648 40.1824 51.7248V44.1347C40.1824 42.9123 40.6327 41.7388 41.4505 40.8301L45.5109 36.3185C45.7429 36.0607 46.1358 36.0113 46.4245 36.2039Z\" fill=\"#00B2E3\"><\/path><path d=\"M54.7725 26.7661C54.4965 26.2577 54.0162 25.8856 53.4548 25.7452C52.4498 25.4939 51.4055 26.0313 51.0258 26.9951L48.3693 33.7366C48.2447 34.0529 48.4001 34.4103 48.7164 34.535C49.0327 34.6596 49.3902 34.5042 49.5148 34.1879L52.1713 27.4465C52.3253 27.0557 52.7488 26.8378 53.1563 26.9396C53.3872 26.9974 53.577 27.1444 53.6906 27.3536C53.8042 27.5629 53.8242 27.802 53.7469 28.0273L50.9284 36.2304C50.5859 37.2274 50.0776 38.1498 49.4176 38.9719L44.7125 44.8334C44.1321 45.5564 43.8125 46.4651 43.8125 47.3922V51.7264C43.8125 52.0664 44.0881 52.342 44.4281 52.342C44.7681 52.342 45.0437 52.0664 45.0437 51.7264V47.3922C45.0437 46.7443 45.267 46.1093 45.6726 45.6041L50.3777 39.7426C51.1269 38.8094 51.7039 37.7623 52.0928 36.6305L54.9112 28.4273C55.0992 27.8801 55.0487 27.2746 54.7725 26.7661Z\" fill=\"#00B2E3\"><\/path><path d=\"M40.1818 28.809V23.9479C40.1818 22.0769 38.6596 20.5547 36.7885 20.5547H31.2331C29.362 20.5547 27.8398 22.0769 27.8398 23.9479V28.809C27.8398 29.9142 28.739 30.8134 29.8442 30.8134C30.1182 30.8134 30.3794 30.758 30.6175 30.6581V37.8365C30.6175 38.9417 31.5167 39.8409 32.6219 39.8409C33.1607 39.8409 33.6502 39.6268 34.0108 39.2797C34.3713 39.6268 34.8608 39.8409 35.3996 39.8409C36.5048 39.8409 37.404 38.9417 37.404 37.8365V30.6581C37.6421 30.758 37.9033 30.8134 38.1773 30.8134C39.2826 30.8134 40.1818 29.9142 40.1818 28.809ZM37.404 28.809V24.6424C37.404 24.3024 37.1284 24.0268 36.7884 24.0268C36.4485 24.0268 36.1728 24.3024 36.1728 24.6424V37.8365C36.1728 38.2629 35.826 38.6097 35.3996 38.6097C34.9732 38.6097 34.6264 38.2628 34.6264 37.8365V28.809C34.6264 28.469 34.3507 28.1934 34.0108 28.1934C33.6708 28.1934 33.3952 28.469 33.3952 28.809V37.8365C33.3952 38.2629 33.0483 38.6097 32.6219 38.6097C32.1956 38.6097 31.8487 38.2628 31.8487 37.8365V24.6425C31.8487 24.3025 31.5731 24.0269 31.2331 24.0269C30.8931 24.0269 30.6175 24.3025 30.6175 24.6425V28.809C30.6175 29.2354 30.2706 29.5823 29.8442 29.5823C29.4179 29.5823 29.071 29.2354 29.071 28.809V23.948C29.071 22.7559 30.041 21.786 31.2331 21.786H36.7885C37.9806 21.786 38.9506 22.7558 38.9506 23.948V28.809C38.9506 29.2354 38.6037 29.5823 38.1774 29.5823C37.7509 29.5822 37.404 29.2354 37.404 28.809Z\" fill=\"#00B2E3\"><\/path><path d=\"M34.0118 19.7033C35.3085 19.7033 36.3635 18.6484 36.3635 17.3517C36.3635 16.055 35.3085 15 34.0118 15C32.7151 15 31.6602 16.055 31.6602 17.3517C31.6602 18.6484 32.7151 19.7033 34.0118 19.7033ZM34.0118 16.2312C34.6296 16.2312 35.1323 16.7339 35.1323 17.3517C35.1323 17.9695 34.6296 18.4721 34.0118 18.4721C33.394 18.4721 32.8914 17.9695 32.8914 17.3517C32.8914 16.7339 33.394 16.2312 34.0118 16.2312Z\" fill=\"#00B2E3\"><\/path><path d=\"M25.0625 30.1976V34.677C25.0625 35.017 25.3381 35.2926 25.6781 35.2926C26.0181 35.2926 26.2937 35.017 26.2937 34.677V30.1976C26.2937 29.8577 26.0181 29.582 25.6781 29.582C25.3381 29.582 25.0625 29.8577 25.0625 30.1976Z\" fill=\"#00B2E3\"><\/path><path d=\"M28.4554 32.3613C28.1155 32.3613 27.8398 32.637 27.8398 32.9769V37.8379C27.8398 38.1779 28.1155 38.4535 28.4554 38.4535C28.7954 38.4535 29.071 38.1779 29.071 37.8379V32.9769C29.071 32.637 28.7955 32.3613 28.4554 32.3613Z\" fill=\"#00B2E3\"><\/path><path d=\"M21.5123 32.2032C21.7862 32.2032 22.0474 32.1478 22.2855 32.0478V32.9764C22.2855 33.3164 22.5611 33.592 22.9011 33.592C23.241 33.592 23.5167 33.3164 23.5167 32.9764V25.3377C23.5167 24.9978 23.241 24.7221 22.9011 24.7221C22.5611 24.7221 22.2855 24.9978 22.2855 25.3377V30.1988C22.2855 30.6251 21.9386 30.972 21.5122 30.972C21.0859 30.972 20.739 30.6251 20.739 30.1988V24.6433C20.739 23.4511 21.7089 22.4812 22.9011 22.4812H26.3732C26.7132 22.4812 26.9888 22.2057 26.9888 21.8656C26.9888 21.5256 26.7132 21.25 26.3732 21.25H22.9011C21.03 21.25 19.5078 22.7723 19.5078 24.6433V30.1988C19.5078 31.304 20.407 32.2032 21.5123 32.2032Z\" fill=\"#00B2E3\"><\/path><path d=\"M25.6778 20.3986C26.9745 20.3986 28.0295 19.3437 28.0295 18.047C28.0295 16.7503 26.9745 15.6953 25.6778 15.6953C24.3811 15.6953 23.3262 16.7503 23.3262 18.047C23.3262 19.3437 24.3811 20.3986 25.6778 20.3986ZM25.6778 16.9265C26.2957 16.9265 26.7983 17.4292 26.7983 18.047C26.7983 18.6648 26.2957 19.1675 25.6778 19.1675C25.06 19.1675 24.5574 18.6648 24.5574 18.047C24.5574 17.4292 25.0599 16.9265 25.6778 16.9265Z\" fill=\"#00B2E3\"><\/path><path d=\"M41.7285 30.1976V34.677C41.7285 35.017 42.0041 35.2926 42.3441 35.2926C42.6841 35.2926 42.9597 35.017 42.9597 34.677V30.1976C42.9597 29.8577 42.6841 29.582 42.3441 29.582C42.0041 29.582 41.7285 29.8577 41.7285 30.1976Z\" fill=\"#00B2E3\"><\/path><path d=\"M38.9512 32.9769V37.8379C38.9512 38.1779 39.2268 38.4535 39.5668 38.4535C39.9067 38.4535 40.1824 38.1779 40.1824 37.8379V32.9769C40.1824 32.637 39.9067 32.3613 39.5668 32.3613C39.2268 32.3613 38.9512 32.637 38.9512 32.9769Z\" fill=\"#00B2E3\"><\/path><path d=\"M41.0352 21.8656C41.0352 22.2057 41.3108 22.4812 41.6508 22.4812H45.1229C46.315 22.4812 47.285 23.4511 47.285 24.6433V30.1988C47.285 30.6251 46.9381 30.972 46.5117 30.972C46.0854 30.972 45.7385 30.6251 45.7385 30.1988V25.3377C45.7385 24.9978 45.4629 24.7221 45.1229 24.7221C44.7829 24.7221 44.5073 24.9978 44.5073 25.3377V32.9764C44.5073 33.3164 44.7829 33.592 45.1229 33.592C45.4629 33.592 45.7385 33.3164 45.7385 32.9764V32.0478C45.9766 32.1478 46.2378 32.2032 46.5118 32.2032C47.617 32.2032 48.5162 31.304 48.5162 30.1988V24.6433C48.5162 22.7723 46.994 21.25 45.1229 21.25H41.6508C41.3108 21.25 41.0352 21.5256 41.0352 21.8656Z\" fill=\"#00B2E3\"><\/path><path d=\"M42.3439 20.3986C43.6406 20.3986 44.6955 19.3437 44.6955 18.047C44.6955 16.7503 43.6406 15.6953 42.3439 15.6953C41.0472 15.6953 39.9922 16.7503 39.9922 18.047C39.9922 19.3437 41.0472 20.3986 42.3439 20.3986ZM42.3439 16.9265C42.9617 16.9265 43.4643 17.4292 43.4643 18.047C43.4643 18.6648 42.9617 19.1675 42.3439 19.1675C41.726 19.1675 41.2234 18.6648 41.2234 18.047C41.2234 17.4292 41.726 16.9265 42.3439 16.9265Z\" fill=\"#00B2E3\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1680\" class=\"elementor-element elementor-element-2bb69f2 e-con-full e-flex e-con e-child\" data-id=\"2bb69f2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b95860 elementor-widget elementor-widget-heading\" data-id=\"8b95860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Nous nous effor\u00e7ons d'am\u00e9liorer la qualit\u00e9 de la vie de notre communaut\u00e9 de patients atteints de troubles du SNC. Conform\u00e9ment \u00e0 notre activit\u00e9 principale, qui consiste \u00e0 am\u00e9liorer les r\u00e9sultats en mati\u00e8re de sant\u00e9 gr\u00e2ce \u00e0 des m\u00e9dicaments innovants, nous sommes motiv\u00e9s pour sensibiliser le public \u00e0 notre principal domaine d'activit\u00e9, \u00e0 savoir les troubles du SNC : les troubles du SNC. C'est pourquoi nous nous effor\u00e7ons de former des alliances sociales, de nous engager aupr\u00e8s d'\u00e9tablissements d'enseignement et de sensibiliser l'opinion publique par le biais de diff\u00e9rentes actions et initiatives, apportant ainsi une contribution positive \u00e0 la soci\u00e9t\u00e9.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dafd2cf elementor-widget elementor-widget-heading\" data-id=\"dafd2cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>Domaines potentiels d'int\u00e9r\u00eat :<\/b><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1680\" class=\"elementor-element elementor-element-685e187 e-flex e-con-boxed e-con e-child\" data-id=\"685e187\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ace3623 elementor-widget elementor-widget-heading\" data-id=\"ace3623\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Engagement actif, sensibilisation et engagement social<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d927aea elementor-widget elementor-widget-n-accordion\" data-id=\"d927aea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2270\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2270\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Nos patients <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"#00B2E3\"><\/circle><path d=\"M36.375 42.25H37.75V56H36.375V42.25Z\" fill=\"white\"><\/path><path d=\"M32.9375 46.375H34.3125V56H32.9375V46.375Z\" fill=\"white\"><\/path><path d=\"M33.625 29.1875C32.5313 29.1864 31.4827 28.7515 30.7094 27.9781C29.936 27.2048 29.5011 26.1562 29.5 25.0625V24.375C29.5 23.281 29.9346 22.2318 30.7082 21.4582C31.4818 20.6846 32.531 20.25 33.625 20.25C34.719 20.25 35.7682 20.6846 36.5418 21.4582C37.3154 22.2318 37.75 23.281 37.75 24.375V25.0625C37.7489 26.1562 37.314 27.2048 36.5406 27.9781C35.7673 28.7515 34.7187 29.1864 33.625 29.1875ZM33.625 21.625C32.8957 21.625 32.1962 21.9147 31.6805 22.4305C31.1647 22.9462 30.875 23.6457 30.875 24.375V25.0625C30.875 25.7918 31.1647 26.4913 31.6805 27.007C32.1962 27.5228 32.8957 27.8125 33.625 27.8125C34.3543 27.8125 35.0538 27.5228 35.5695 27.007C36.0853 26.4913 36.375 25.7918 36.375 25.0625V24.375C36.375 23.6457 36.0853 22.9462 35.5695 22.4305C35.0538 21.9147 34.3543 21.625 33.625 21.625Z\" fill=\"white\"><\/path><path d=\"M38.7812 45C38.1431 45 37.531 44.7465 37.0798 44.2952C36.6285 43.844 36.375 43.2319 36.375 42.5938V36.0625H37.75V42.5938C37.75 42.8673 37.8586 43.1296 38.052 43.323C38.2454 43.5164 38.5077 43.625 38.7812 43.625C39.0548 43.625 39.3171 43.5164 39.5105 43.323C39.7039 43.1296 39.8125 42.8673 39.8125 42.5938V33.3125C39.8125 32.7655 39.5952 32.2409 39.2084 31.8541C38.8216 31.4673 38.297 31.25 37.75 31.25H29.5C28.953 31.25 28.4284 31.4673 28.0416 31.8541C27.6548 32.2409 27.4375 32.7655 27.4375 33.3125V42.5938C27.4375 42.8673 27.5461 43.1296 27.7395 43.323C27.9329 43.5164 28.1952 43.625 28.4688 43.625C28.7423 43.625 29.0046 43.5164 29.198 43.323C29.3914 43.1296 29.5 42.8673 29.5 42.5938V36.0625H30.875V42.5938C30.875 43.2319 30.6215 43.844 30.1702 44.2952C29.719 44.7465 29.1069 45 28.4688 45C27.8306 45 27.2185 44.7465 26.7673 44.2952C26.316 43.844 26.0625 43.2319 26.0625 42.5938V33.3125C26.0636 32.4012 26.4261 31.5274 27.0705 30.883C27.7149 30.2386 28.5887 29.8761 29.5 29.875H37.75C38.6613 29.8761 39.5351 30.2386 40.1795 30.883C40.8239 31.5274 41.1864 32.4012 41.1875 33.3125V42.5938C41.1875 43.2319 40.934 43.844 40.4827 44.2952C40.0315 44.7465 39.4194 45 38.7812 45Z\" fill=\"white\"><\/path><path d=\"M29.5 42.25H30.875V56H29.5V42.25Z\" fill=\"white\"><\/path><path d=\"M49.4375 40.1875H50.8125V53.9375H49.4375V40.1875Z\" fill=\"white\"><\/path><path d=\"M46 44.3125H47.375V53.9375H46V44.3125Z\" fill=\"white\"><\/path><path d=\"M46.6875 27.125C45.5938 27.1239 44.5452 26.689 43.7719 25.9156C42.9985 25.1423 42.5636 24.0937 42.5625 23V22.3125C42.5625 21.2185 42.9971 20.1693 43.7707 19.3957C44.5443 18.6221 45.5935 18.1875 46.6875 18.1875C47.7815 18.1875 48.8307 18.6221 49.6043 19.3957C50.3779 20.1693 50.8125 21.2185 50.8125 22.3125V23C50.8114 24.0937 50.3765 25.1423 49.6031 25.9156C48.8298 26.689 47.7812 27.1239 46.6875 27.125ZM46.6875 19.5625C45.9582 19.5625 45.2587 19.8522 44.743 20.368C44.2272 20.8837 43.9375 21.5832 43.9375 22.3125V23C43.9375 23.7293 44.2272 24.4288 44.743 24.9445C45.2587 25.4603 45.9582 25.75 46.6875 25.75C47.4168 25.75 48.1163 25.4603 48.632 24.9445C49.1478 24.4288 49.4375 23.7293 49.4375 23V22.3125C49.4375 21.5832 49.1478 20.8837 48.632 20.368C48.1163 19.8522 47.4168 19.5625 46.6875 19.5625Z\" fill=\"white\"><\/path><path d=\"M51.8426 42.9375C51.2044 42.9375 50.5924 42.684 50.1411 42.2327C49.6899 41.7815 49.4364 41.1694 49.4364 40.5312V34H50.8114V40.5312C50.8114 40.8048 50.92 41.0671 51.1134 41.2605C51.3068 41.4539 51.5691 41.5625 51.8426 41.5625C52.1161 41.5625 52.3784 41.4539 52.5718 41.2605C52.7652 41.0671 52.8739 40.8048 52.8739 40.5312V31.25C52.8739 30.703 52.6566 30.1784 52.2698 29.7916C51.883 29.4048 51.3584 29.1875 50.8114 29.1875H42.5614C42.0592 29.187 41.5742 29.3704 41.198 29.7031L40.2871 28.6719C40.9152 28.1179 41.7239 27.8124 42.5614 27.8125H50.8114C51.7227 27.8136 52.5964 28.1761 53.2408 28.8205C53.8853 29.4649 54.2478 30.3387 54.2489 31.25V40.5312C54.2489 41.1694 53.9953 41.7815 53.5441 42.2327C53.0928 42.684 52.4808 42.9375 51.8426 42.9375Z\" fill=\"white\"><\/path><path d=\"M42.5625 34H43.9375V53.9375H42.5625V34Z\" fill=\"white\"><\/path><path d=\"M19.875 44.3125H21.25V53.9375H19.875V44.3125Z\" fill=\"white\"><\/path><path d=\"M20.5625 27.125C19.4688 27.1239 18.4202 26.689 17.6469 25.9156C16.8735 25.1423 16.4386 24.0937 16.4375 23V22.3125C16.4375 21.2185 16.8721 20.1693 17.6457 19.3957C18.4193 18.6221 19.4685 18.1875 20.5625 18.1875C21.6565 18.1875 22.7057 18.6221 23.4793 19.3957C24.2529 20.1693 24.6875 21.2185 24.6875 22.3125V23C24.6864 24.0937 24.2515 25.1423 23.4781 25.9156C22.7048 26.689 21.6562 27.1239 20.5625 27.125ZM20.5625 19.5625C19.8332 19.5625 19.1337 19.8522 18.618 20.368C18.1022 20.8837 17.8125 21.5832 17.8125 22.3125V23C17.8125 23.7293 18.1022 24.4288 18.618 24.9445C19.1337 25.4603 19.8332 25.75 20.5625 25.75C21.2918 25.75 21.9913 25.4603 22.507 24.9445C23.0228 24.4288 23.3125 23.7293 23.3125 23V22.3125C23.3125 21.5832 23.0228 20.8837 22.507 20.368C21.9913 19.8522 21.2918 19.5625 20.5625 19.5625Z\" fill=\"white\"><\/path><path d=\"M28.125 20.9375C27.0313 20.9364 25.9827 20.5015 25.2094 19.7281C24.436 18.9548 24.0011 17.9062 24 16.8125V16.125C24 15.031 24.4346 13.9818 25.2082 13.2082C25.9818 12.4346 27.031 12 28.125 12C29.219 12 30.2682 12.4346 31.0418 13.2082C31.8154 13.9818 32.25 15.031 32.25 16.125V16.8125C32.2489 17.9062 31.814 18.9548 31.0406 19.7281C30.2673 20.5015 29.2187 20.9364 28.125 20.9375ZM28.125 13.375C27.3957 13.375 26.6962 13.6647 26.1805 14.1805C25.6647 14.6962 25.375 15.3957 25.375 16.125V16.8125C25.375 17.5418 25.6647 18.2413 26.1805 18.757C26.6962 19.2728 27.3957 19.5625 28.125 19.5625C28.8543 19.5625 29.5538 19.2728 30.0695 18.757C30.5853 18.2413 30.875 17.5418 30.875 16.8125V16.125C30.875 15.3957 30.5853 14.6962 30.0695 14.1805C29.5538 13.6647 28.8543 13.375 28.125 13.375Z\" fill=\"white\"><\/path><path d=\"M39.125 20.9375C38.0313 20.9364 36.9827 20.5015 36.2094 19.7281C35.436 18.9548 35.0011 17.9062 35 16.8125V16.125C35 15.031 35.4346 13.9818 36.2082 13.2082C36.9818 12.4346 38.031 12 39.125 12C40.219 12 41.2682 12.4346 42.0418 13.2082C42.8154 13.9818 43.25 15.031 43.25 16.125V16.8125C43.2489 17.9062 42.814 18.9548 42.0406 19.7281C41.2673 20.5015 40.2187 20.9364 39.125 20.9375ZM39.125 13.375C38.3957 13.375 37.6962 13.6647 37.1805 14.1805C36.6647 14.6962 36.375 15.3957 36.375 16.125V16.8125C36.375 17.5418 36.6647 18.2413 37.1805 18.757C37.6962 19.2728 38.3957 19.5625 39.125 19.5625C39.8543 19.5625 40.5538 19.2728 41.0695 18.757C41.5853 18.2413 41.875 17.5418 41.875 16.8125V16.125C41.875 15.3957 41.5853 14.6962 41.0695 14.1805C40.5538 13.6647 39.8543 13.375 39.125 13.375Z\" fill=\"white\"><\/path><path d=\"M15.4062 42.9375C14.7681 42.9375 14.156 42.684 13.7048 42.2327C13.2535 41.7815 13 41.1694 13 40.5312V31.25C13.0011 30.3387 13.3636 29.4649 14.008 28.8205C14.6524 28.1761 15.5262 27.8136 16.4375 27.8125H24.6875C25.525 27.8124 26.3337 28.1179 26.9618 28.6719L26.0508 29.7031C25.6746 29.3704 25.1897 29.187 24.6875 29.1875H16.4375C15.8905 29.1875 15.3659 29.4048 14.9791 29.7916C14.5923 30.1784 14.375 30.703 14.375 31.25V40.5312C14.375 40.8048 14.4836 41.0671 14.677 41.2605C14.8704 41.4539 15.1327 41.5625 15.4062 41.5625C15.6798 41.5625 15.9421 41.4539 16.1355 41.2605C16.3289 41.0671 16.4375 40.8048 16.4375 40.5312V34H17.8125V40.5312C17.8125 41.1694 17.559 41.7815 17.1077 42.2327C16.6565 42.684 16.0444 42.9375 15.4062 42.9375Z\" fill=\"white\"><\/path><path d=\"M16.4375 40.1875H17.8125V53.9375H16.4375V40.1875Z\" fill=\"white\"><\/path><path d=\"M23.3125 34H24.6875V53.9375H23.3125V34Z\" fill=\"white\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"white\"><\/circle><path d=\"M36.375 42.25H37.75V56H36.375V42.25Z\" fill=\"#00B2E3\"><\/path><path d=\"M32.9375 46.375H34.3125V56H32.9375V46.375Z\" fill=\"#00B2E3\"><\/path><path d=\"M33.625 29.1875C32.5313 29.1864 31.4827 28.7515 30.7094 27.9781C29.936 27.2048 29.5011 26.1562 29.5 25.0625V24.375C29.5 23.281 29.9346 22.2318 30.7082 21.4582C31.4818 20.6846 32.531 20.25 33.625 20.25C34.719 20.25 35.7682 20.6846 36.5418 21.4582C37.3154 22.2318 37.75 23.281 37.75 24.375V25.0625C37.7489 26.1562 37.314 27.2048 36.5406 27.9781C35.7673 28.7515 34.7187 29.1864 33.625 29.1875ZM33.625 21.625C32.8957 21.625 32.1962 21.9147 31.6805 22.4305C31.1647 22.9462 30.875 23.6457 30.875 24.375V25.0625C30.875 25.7918 31.1647 26.4913 31.6805 27.007C32.1962 27.5228 32.8957 27.8125 33.625 27.8125C34.3543 27.8125 35.0538 27.5228 35.5695 27.007C36.0853 26.4913 36.375 25.7918 36.375 25.0625V24.375C36.375 23.6457 36.0853 22.9462 35.5695 22.4305C35.0538 21.9147 34.3543 21.625 33.625 21.625Z\" fill=\"#00B2E3\"><\/path><path d=\"M38.7812 45C38.1431 45 37.531 44.7465 37.0798 44.2952C36.6285 43.844 36.375 43.2319 36.375 42.5938V36.0625H37.75V42.5938C37.75 42.8673 37.8586 43.1296 38.052 43.323C38.2454 43.5164 38.5077 43.625 38.7812 43.625C39.0548 43.625 39.3171 43.5164 39.5105 43.323C39.7039 43.1296 39.8125 42.8673 39.8125 42.5938V33.3125C39.8125 32.7655 39.5952 32.2409 39.2084 31.8541C38.8216 31.4673 38.297 31.25 37.75 31.25H29.5C28.953 31.25 28.4284 31.4673 28.0416 31.8541C27.6548 32.2409 27.4375 32.7655 27.4375 33.3125V42.5938C27.4375 42.8673 27.5461 43.1296 27.7395 43.323C27.9329 43.5164 28.1952 43.625 28.4688 43.625C28.7423 43.625 29.0046 43.5164 29.198 43.323C29.3914 43.1296 29.5 42.8673 29.5 42.5938V36.0625H30.875V42.5938C30.875 43.2319 30.6215 43.844 30.1702 44.2952C29.719 44.7465 29.1069 45 28.4688 45C27.8306 45 27.2185 44.7465 26.7673 44.2952C26.316 43.844 26.0625 43.2319 26.0625 42.5938V33.3125C26.0636 32.4012 26.4261 31.5274 27.0705 30.883C27.7149 30.2386 28.5887 29.8761 29.5 29.875H37.75C38.6613 29.8761 39.5351 30.2386 40.1795 30.883C40.8239 31.5274 41.1864 32.4012 41.1875 33.3125V42.5938C41.1875 43.2319 40.934 43.844 40.4827 44.2952C40.0315 44.7465 39.4194 45 38.7812 45Z\" fill=\"#00B2E3\"><\/path><path d=\"M29.5 42.25H30.875V56H29.5V42.25Z\" fill=\"#00B2E3\"><\/path><path d=\"M49.4375 40.1875H50.8125V53.9375H49.4375V40.1875Z\" fill=\"#00B2E3\"><\/path><path d=\"M46 44.3125H47.375V53.9375H46V44.3125Z\" fill=\"#00B2E3\"><\/path><path d=\"M46.6875 27.125C45.5938 27.1239 44.5452 26.689 43.7719 25.9156C42.9985 25.1423 42.5636 24.0937 42.5625 23V22.3125C42.5625 21.2185 42.9971 20.1693 43.7707 19.3957C44.5443 18.6221 45.5935 18.1875 46.6875 18.1875C47.7815 18.1875 48.8307 18.6221 49.6043 19.3957C50.3779 20.1693 50.8125 21.2185 50.8125 22.3125V23C50.8114 24.0937 50.3765 25.1423 49.6031 25.9156C48.8298 26.689 47.7812 27.1239 46.6875 27.125ZM46.6875 19.5625C45.9582 19.5625 45.2587 19.8522 44.743 20.368C44.2272 20.8837 43.9375 21.5832 43.9375 22.3125V23C43.9375 23.7293 44.2272 24.4288 44.743 24.9445C45.2587 25.4603 45.9582 25.75 46.6875 25.75C47.4168 25.75 48.1163 25.4603 48.632 24.9445C49.1478 24.4288 49.4375 23.7293 49.4375 23V22.3125C49.4375 21.5832 49.1478 20.8837 48.632 20.368C48.1163 19.8522 47.4168 19.5625 46.6875 19.5625Z\" fill=\"#00B2E3\"><\/path><path d=\"M51.8426 42.9375C51.2044 42.9375 50.5924 42.684 50.1411 42.2327C49.6899 41.7815 49.4364 41.1694 49.4364 40.5312V34H50.8114V40.5312C50.8114 40.8048 50.92 41.0671 51.1134 41.2605C51.3068 41.4539 51.5691 41.5625 51.8426 41.5625C52.1161 41.5625 52.3784 41.4539 52.5718 41.2605C52.7652 41.0671 52.8739 40.8048 52.8739 40.5312V31.25C52.8739 30.703 52.6566 30.1784 52.2698 29.7916C51.883 29.4048 51.3584 29.1875 50.8114 29.1875H42.5614C42.0592 29.187 41.5742 29.3704 41.198 29.7031L40.2871 28.6719C40.9152 28.1179 41.7239 27.8124 42.5614 27.8125H50.8114C51.7227 27.8136 52.5964 28.1761 53.2408 28.8205C53.8853 29.4649 54.2478 30.3387 54.2489 31.25V40.5312C54.2489 41.1694 53.9953 41.7815 53.5441 42.2327C53.0928 42.684 52.4808 42.9375 51.8426 42.9375Z\" fill=\"#00B2E3\"><\/path><path d=\"M42.5625 34H43.9375V53.9375H42.5625V34Z\" fill=\"#00B2E3\"><\/path><path d=\"M19.875 44.3125H21.25V53.9375H19.875V44.3125Z\" fill=\"#00B2E3\"><\/path><path d=\"M20.5625 27.125C19.4688 27.1239 18.4202 26.689 17.6469 25.9156C16.8735 25.1423 16.4386 24.0937 16.4375 23V22.3125C16.4375 21.2185 16.8721 20.1693 17.6457 19.3957C18.4193 18.6221 19.4685 18.1875 20.5625 18.1875C21.6565 18.1875 22.7057 18.6221 23.4793 19.3957C24.2529 20.1693 24.6875 21.2185 24.6875 22.3125V23C24.6864 24.0937 24.2515 25.1423 23.4781 25.9156C22.7048 26.689 21.6562 27.1239 20.5625 27.125ZM20.5625 19.5625C19.8332 19.5625 19.1337 19.8522 18.618 20.368C18.1022 20.8837 17.8125 21.5832 17.8125 22.3125V23C17.8125 23.7293 18.1022 24.4288 18.618 24.9445C19.1337 25.4603 19.8332 25.75 20.5625 25.75C21.2918 25.75 21.9913 25.4603 22.507 24.9445C23.0228 24.4288 23.3125 23.7293 23.3125 23V22.3125C23.3125 21.5832 23.0228 20.8837 22.507 20.368C21.9913 19.8522 21.2918 19.5625 20.5625 19.5625Z\" fill=\"#00B2E3\"><\/path><path d=\"M28.125 20.9375C27.0313 20.9364 25.9827 20.5015 25.2094 19.7281C24.436 18.9548 24.0011 17.9062 24 16.8125V16.125C24 15.031 24.4346 13.9818 25.2082 13.2082C25.9818 12.4346 27.031 12 28.125 12C29.219 12 30.2682 12.4346 31.0418 13.2082C31.8154 13.9818 32.25 15.031 32.25 16.125V16.8125C32.2489 17.9062 31.814 18.9548 31.0406 19.7281C30.2673 20.5015 29.2187 20.9364 28.125 20.9375ZM28.125 13.375C27.3957 13.375 26.6962 13.6647 26.1805 14.1805C25.6647 14.6962 25.375 15.3957 25.375 16.125V16.8125C25.375 17.5418 25.6647 18.2413 26.1805 18.757C26.6962 19.2728 27.3957 19.5625 28.125 19.5625C28.8543 19.5625 29.5538 19.2728 30.0695 18.757C30.5853 18.2413 30.875 17.5418 30.875 16.8125V16.125C30.875 15.3957 30.5853 14.6962 30.0695 14.1805C29.5538 13.6647 28.8543 13.375 28.125 13.375Z\" fill=\"#00B2E3\"><\/path><path d=\"M39.125 20.9375C38.0313 20.9364 36.9827 20.5015 36.2094 19.7281C35.436 18.9548 35.0011 17.9062 35 16.8125V16.125C35 15.031 35.4346 13.9818 36.2082 13.2082C36.9818 12.4346 38.031 12 39.125 12C40.219 12 41.2682 12.4346 42.0418 13.2082C42.8154 13.9818 43.25 15.031 43.25 16.125V16.8125C43.2489 17.9062 42.814 18.9548 42.0406 19.7281C41.2673 20.5015 40.2187 20.9364 39.125 20.9375ZM39.125 13.375C38.3957 13.375 37.6962 13.6647 37.1805 14.1805C36.6647 14.6962 36.375 15.3957 36.375 16.125V16.8125C36.375 17.5418 36.6647 18.2413 37.1805 18.757C37.6962 19.2728 38.3957 19.5625 39.125 19.5625C39.8543 19.5625 40.5538 19.2728 41.0695 18.757C41.5853 18.2413 41.875 17.5418 41.875 16.8125V16.125C41.875 15.3957 41.5853 14.6962 41.0695 14.1805C40.5538 13.6647 39.8543 13.375 39.125 13.375Z\" fill=\"#00B2E3\"><\/path><path d=\"M15.4062 42.9375C14.7681 42.9375 14.156 42.684 13.7048 42.2327C13.2535 41.7815 13 41.1694 13 40.5312V31.25C13.0011 30.3387 13.3636 29.4649 14.008 28.8205C14.6524 28.1761 15.5262 27.8136 16.4375 27.8125H24.6875C25.525 27.8124 26.3337 28.1179 26.9618 28.6719L26.0508 29.7031C25.6746 29.3704 25.1897 29.187 24.6875 29.1875H16.4375C15.8905 29.1875 15.3659 29.4048 14.9791 29.7916C14.5923 30.1784 14.375 30.703 14.375 31.25V40.5312C14.375 40.8048 14.4836 41.0671 14.677 41.2605C14.8704 41.4539 15.1327 41.5625 15.4062 41.5625C15.6798 41.5625 15.9421 41.4539 16.1355 41.2605C16.3289 41.0671 16.4375 40.8048 16.4375 40.5312V34H17.8125V40.5312C17.8125 41.1694 17.559 41.7815 17.1077 42.2327C16.6565 42.684 16.0444 42.9375 15.4062 42.9375Z\" fill=\"#00B2E3\"><\/path><path d=\"M16.4375 40.1875H17.8125V53.9375H16.4375V40.1875Z\" fill=\"#00B2E3\"><\/path><path d=\"M23.3125 34H24.6875V53.9375H23.3125V34Z\" fill=\"#00B2E3\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2270\" class=\"elementor-element elementor-element-f631bb9 e-con-full e-flex e-con e-child\" data-id=\"f631bb9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7c65b1 elementor-widget elementor-widget-heading\" data-id=\"a7c65b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">En tant qu'entreprise pharmaceutique, nous reconnaissons le r\u00f4le essentiel que nous jouons dans la sant\u00e9 et le bien-\u00eatre des patients atteints de pathologies du SNC dans le monde entier, et cela se refl\u00e8te dans la qualit\u00e9, la s\u00e9curit\u00e9 et la fiabilit\u00e9 des produits que nous fournissons \u00e0 nos patients atteints du SNC. En explorant de nouvelles alliances industrielles strat\u00e9giques, nous nous effor\u00e7ons d'offrir les th\u00e9rapies les plus efficaces pour le SNC et des solutions avanc\u00e9es pour les besoins m\u00e9dicaux non satisfaits.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ab31c1 elementor-widget elementor-widget-heading\" data-id=\"5ab31c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>Domaines potentiels d'int\u00e9r\u00eat :\n<\/b><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2270\" class=\"elementor-element elementor-element-64797d3 e-flex e-con-boxed e-con e-child\" data-id=\"64797d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba5b570 elementor-widget elementor-widget-heading\" data-id=\"ba5b570\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Qualit\u00e9 et s\u00e9curit\u00e9 des produits<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2270\" class=\"elementor-element elementor-element-596f430 e-flex e-con-boxed e-con e-child\" data-id=\"596f430\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1df404 elementor-widget elementor-widget-heading\" data-id=\"c1df404\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Recherche et innovation<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b65619 elementor-widget elementor-widget-n-accordion\" data-id=\"0b65619\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1190\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1190\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Notre \u00e9quipe <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"#00B2E3\"><\/circle><path d=\"M51.9067 16.679C51.4312 16.6308 50.9523 16.7289 50.5341 16.9604C50.3299 16.298 49.8387 15.7625 49.1964 15.5019C48.5541 15.2414 47.8287 15.2834 47.2207 15.6164C46.8823 14.5683 45.857 13.8996 44.7614 14.0124C44.0485 14.0934 43.4136 14.5008 43.0427 15.115C42.4885 14.7047 41.7788 14.5662 41.1109 14.738C40.443 14.9098 39.8882 15.3735 39.6007 16.0004H33.0354C32.9138 15.9995 32.7947 15.9656 32.6907 15.9024L29.9954 14.2897C29.6855 14.1024 29.3308 14.0025 28.9687 14.0004H19.0961C17.8761 13.984 16.8373 14.8839 16.6794 16.0937C16.6312 16.5694 16.7294 17.0485 16.9607 17.467C16.2982 17.6709 15.7625 18.1621 15.502 18.8046C15.2415 19.447 15.2839 20.1726 15.6174 20.7804C14.5677 21.1176 13.8981 22.1445 14.0127 23.241C14.0935 23.9541 14.5009 24.5891 15.1154 24.9597C14.7771 25.4263 14.6219 26.0009 14.6794 26.5744C14.7747 27.3715 15.2741 28.0632 16.0007 28.4044V34.967C15.9996 35.0881 15.9655 35.2066 15.9021 35.3097L14.2754 38.019C14.0984 38.3279 14.0038 38.6771 14.0007 39.033V48.9057C13.9854 50.1254 14.8852 51.1636 16.0947 51.3217C16.5702 51.3686 17.0487 51.2705 17.4674 51.0404C17.6715 51.703 18.1628 52.2387 18.8054 52.4991C19.4479 52.7596 20.1735 52.7172 20.7814 52.3837C21.0903 53.3483 21.9879 54.0022 23.0007 54.0004C23.8044 54.0005 24.5487 53.5772 24.9594 52.8864C25.5142 53.2966 26.2243 53.4351 26.8926 53.2632C27.5609 53.0913 28.1161 52.6274 28.4041 52.0004H34.9661C35.0877 52.0013 35.2068 52.0351 35.3107 52.0984L38.0061 53.7124C38.3161 53.8989 38.6709 53.9982 39.0327 53.9997H48.9054C50.1254 54.016 51.1642 53.1162 51.3221 51.9064C51.3701 51.4308 51.272 50.952 51.0407 50.5337C51.7033 50.3298 52.239 49.8386 52.4995 49.1961C52.76 48.5537 52.7176 47.8281 52.3841 47.2204C53.4332 46.8832 54.1027 45.8571 53.9887 44.761C53.908 44.048 53.5006 43.413 52.8861 43.0424C53.2244 42.5758 53.3795 42.0012 53.3221 41.4277C53.2261 40.6315 52.7267 39.941 52.0007 39.6004V33.0337C52.0022 32.9123 52.036 32.7936 52.0987 32.6897L53.7134 29.995C53.9 29.6847 53.9992 29.3298 54.0007 28.9677V19.095C54.0161 17.8753 53.1163 16.8371 51.9067 16.679ZM15.3394 23.109C15.3085 22.8265 15.3993 22.5441 15.5891 22.3326C15.779 22.121 16.0498 22.0002 16.3341 22.0004H20.6674C21.0356 22.0004 21.3341 21.7019 21.3341 21.3337C21.3341 20.9655 21.0356 20.667 20.6674 20.667H17.6674C17.3832 20.6677 17.1121 20.5474 16.922 20.3362C16.7318 20.1251 16.6404 19.8429 16.6707 19.5604C16.756 19.029 17.2251 18.6454 17.7627 18.667H22.0007C22.3689 18.667 22.6674 18.3686 22.6674 18.0004C22.6674 17.6322 22.3689 17.3337 22.0007 17.3337H19.0007C18.7165 17.3344 18.4455 17.2141 18.2553 17.0029C18.0651 16.7917 17.9738 16.5096 18.0041 16.227C18.0891 15.6956 18.5583 15.3117 19.0961 15.3337H28.9687C29.0903 15.3346 29.2092 15.3687 29.3127 15.4324L32.0087 17.047C32.319 17.2331 32.6736 17.3321 33.0354 17.3337H39.3341V23.2597L38.1794 22.3144C37.3129 21.653 36.0942 21.72 35.3054 22.4724C34.7197 23.0403 34.5162 23.8962 34.7834 24.667H32.5481C32.0234 24.6692 31.5206 24.8775 31.1481 25.247L24.8741 31.4697L24.8607 31.483L24.5834 31.7577C24.2582 32.0756 23.7375 32.0721 23.4167 31.7497C23.1239 31.4557 23.0954 30.9899 23.3501 30.6624L25.1834 28.4224C25.3464 28.223 25.38 27.9475 25.2697 27.7148C25.1594 27.4821 24.9249 27.3337 24.6674 27.3337H17.0961C16.5593 27.3547 16.0913 26.9714 16.0061 26.441C15.9756 26.1587 16.0666 25.8767 16.2564 25.6654C16.4461 25.4542 16.7168 25.3336 17.0007 25.3337H20.6674C21.0356 25.3337 21.3341 25.0352 21.3341 24.667C21.3341 24.2988 21.0356 24.0004 20.6674 24.0004H16.4294C15.8931 24.0211 15.4255 23.6388 15.3394 23.109ZM42.0007 35.7717L35.9141 41.8077C35.7916 41.93 35.6258 41.9991 35.4527 41.9997H32.2287L26.1934 35.9157C26.0707 35.7932 26.0014 35.6271 26.0007 35.4537V32.227L32.0854 26.193C32.208 26.0701 32.3744 26.0008 32.5481 26.0004H35.7747L41.8101 32.0844C41.9318 32.2076 42.0003 32.3738 42.0007 32.547V35.7717ZM26.4354 51.995C26.1547 52.0253 25.8745 51.9341 25.6654 51.7444C25.4554 51.5539 25.3351 51.2839 25.3341 51.0004V50.9904V47.3337C25.3341 46.9655 25.0356 46.667 24.6674 46.667C24.2992 46.667 24.0007 46.9655 24.0007 47.3337V51.0004V51.0097V51.573C24.019 52.1117 23.6326 52.5795 23.1001 52.663C22.82 52.6935 22.5403 52.6022 22.3321 52.4124C22.1216 52.2217 22.0012 51.9511 22.0007 51.667V50.3337V50.3204V47.3337C22.0007 46.9655 21.7023 46.667 21.3341 46.667C20.9659 46.667 20.6674 46.9655 20.6674 47.3337V50.3337V50.3417C20.6656 50.6244 20.5443 50.8931 20.3334 51.0814C20.1225 51.2696 19.8418 51.3599 19.5607 51.3297C19.0295 51.2447 18.6458 50.7759 18.6674 50.2384V49.0004V48.9904V46.0004C18.6674 45.6322 18.3689 45.3337 18.0007 45.3337C17.6325 45.3337 17.3341 45.6322 17.3341 46.0004V49.0004V49.0064C17.3328 49.2893 17.2118 49.5584 17.001 49.7471C16.7902 49.9358 16.5094 50.0264 16.2281 49.9964C15.697 49.9114 15.3131 49.4431 15.3341 48.9057V39.033C15.3351 38.9129 15.3665 38.795 15.4254 38.6904L17.0474 35.993C17.233 35.6828 17.332 35.3285 17.3341 34.967V28.667H23.2594L22.3134 29.8224C21.7035 30.5642 21.6601 31.6207 22.2072 32.41C22.7542 33.1993 23.7587 33.5296 24.6674 33.219V35.4537C24.6696 35.9784 24.8779 36.4812 25.2474 36.8537L31.4647 43.1204C31.4721 43.1284 31.4794 43.1357 31.4874 43.143L31.7587 43.4164C31.9923 43.6541 32.0603 44.0089 31.931 44.3162C31.8018 44.6234 31.5007 44.823 31.1674 44.8224C30.986 44.8232 30.8097 44.7623 30.6674 44.6497L28.4281 42.817C28.2287 42.6505 27.9509 42.615 27.716 42.7259C27.4812 42.8368 27.3321 43.074 27.3341 43.3337V50.905C27.3525 51.4431 26.9671 51.9106 26.4354 51.995ZM52.6621 44.8917C52.693 45.1742 52.6021 45.4566 52.4123 45.6682C52.2225 45.8797 51.9516 46.0005 51.6674 46.0004H47.3341C46.9659 46.0004 46.6674 46.2988 46.6674 46.667C46.6674 47.0352 46.9659 47.3337 47.3341 47.3337H50.3341C50.6183 47.333 50.8893 47.4533 51.0795 47.6645C51.2697 47.8757 51.3611 48.1578 51.3307 48.4404C51.2454 48.9717 50.7764 49.3554 50.2387 49.3337H46.0007C45.6325 49.3337 45.3341 49.6322 45.3341 50.0004C45.3341 50.3686 45.6325 50.667 46.0007 50.667H49.0007C49.2849 50.6664 49.556 50.7866 49.7462 50.9978C49.9364 51.209 50.0277 51.4911 49.9974 51.7737C49.9124 52.3052 49.4432 52.689 48.9054 52.667H39.0327C38.9112 52.6661 38.7923 52.632 38.6887 52.5684L35.9927 50.9537C35.6825 50.7677 35.3278 50.6686 34.9661 50.667H28.6674V44.7397L29.8221 45.685C30.6878 46.349 31.9084 46.2818 32.6961 45.527C33.2819 44.9597 33.4862 44.1045 33.2201 43.3337H35.4534C35.9781 43.3315 36.4809 43.1232 36.8534 42.7537L43.1254 36.5337L43.1487 36.511L43.4201 36.2444C43.7453 35.9264 44.2659 35.93 44.5867 36.2524C44.8795 36.5463 44.9081 37.0122 44.6534 37.3397L42.8201 39.5797C42.6581 39.7788 42.6248 40.0532 42.7345 40.2853C42.8442 40.5173 43.0774 40.6658 43.3341 40.667H50.9054C51.4422 40.6461 51.9102 41.0293 51.9954 41.5597C52.0259 41.842 51.9349 42.124 51.7451 42.3353C51.5554 42.5465 51.2847 42.6672 51.0007 42.667H47.3341C46.9659 42.667 46.6674 42.9655 46.6674 43.3337C46.6674 43.7019 46.9659 44.0004 47.3341 44.0004H51.5741C52.1096 43.9806 52.576 44.3628 52.6621 44.8917ZM52.6674 28.9677C52.6664 29.0891 52.6325 29.208 52.5694 29.3117L50.9541 32.0077C50.7681 32.3178 50.6691 32.6722 50.6674 33.0337V39.3337H44.7401L45.6861 38.1784C46.3727 37.3201 46.3041 36.0827 45.5267 35.3057C44.9444 34.7469 44.1023 34.5528 43.3341 34.8004V32.547C43.3319 32.0223 43.1236 31.5195 42.7541 31.147L36.5341 24.871L36.5214 24.8584L36.2461 24.581C36.0899 24.4267 36.0026 24.2159 36.0041 23.9963C36.0056 23.7768 36.0958 23.5672 36.2541 23.415C36.5521 23.1307 37.0116 23.1026 37.3421 23.3484L39.5814 25.181C39.7805 25.3422 40.0544 25.3749 40.286 25.2654C40.5175 25.1558 40.6658 24.9232 40.6674 24.667V17.0957C40.6468 16.5588 41.0302 16.0909 41.5607 16.0057C41.843 15.9754 42.1248 16.0665 42.3359 16.2562C42.547 16.446 42.6675 16.7165 42.6674 17.0004V20.667C42.6674 21.0352 42.9659 21.3337 43.3341 21.3337C43.7023 21.3337 44.0007 21.0352 44.0007 20.667V16.429C43.9798 15.892 44.3634 15.424 44.8941 15.339C45.1763 15.3088 45.4581 15.3998 45.6692 15.5896C45.8803 15.7793 46.0008 16.0498 46.0007 16.3337V20.667C46.0007 21.0352 46.2992 21.3337 46.6674 21.3337C47.0356 21.3337 47.3341 21.0352 47.3341 20.667V17.667C47.3336 17.3829 47.454 17.1121 47.6651 16.922C47.8763 16.732 48.1583 16.6407 48.4407 16.671C48.9719 16.756 49.3557 17.2248 49.3341 17.7624V22.0004C49.3341 22.3686 49.6325 22.667 50.0007 22.667C50.3689 22.667 50.6674 22.3686 50.6674 22.0004V19.0004C50.6669 18.7163 50.7873 18.4454 50.9984 18.2554C51.2096 18.0653 51.4916 17.9741 51.7741 18.0044C52.3049 18.0896 52.6884 18.5578 52.6674 19.095V28.9677Z\" fill=\"white\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"white\"><\/circle><path d=\"M51.9067 16.679C51.4312 16.6308 50.9523 16.7289 50.5341 16.9604C50.3299 16.298 49.8387 15.7625 49.1964 15.5019C48.5541 15.2414 47.8287 15.2834 47.2207 15.6164C46.8823 14.5683 45.857 13.8996 44.7614 14.0124C44.0485 14.0934 43.4136 14.5008 43.0427 15.115C42.4885 14.7047 41.7788 14.5662 41.1109 14.738C40.443 14.9098 39.8882 15.3735 39.6007 16.0004H33.0354C32.9138 15.9995 32.7947 15.9656 32.6907 15.9024L29.9954 14.2897C29.6855 14.1024 29.3308 14.0025 28.9687 14.0004H19.0961C17.8761 13.984 16.8373 14.8839 16.6794 16.0937C16.6312 16.5694 16.7294 17.0485 16.9607 17.467C16.2982 17.6709 15.7625 18.1621 15.502 18.8046C15.2415 19.447 15.2839 20.1726 15.6174 20.7804C14.5677 21.1176 13.8981 22.1445 14.0127 23.241C14.0935 23.9541 14.5009 24.5891 15.1154 24.9597C14.7771 25.4263 14.6219 26.0009 14.6794 26.5744C14.7747 27.3715 15.2741 28.0632 16.0007 28.4044V34.967C15.9996 35.0881 15.9655 35.2066 15.9021 35.3097L14.2754 38.019C14.0984 38.3279 14.0038 38.6771 14.0007 39.033V48.9057C13.9854 50.1254 14.8852 51.1636 16.0947 51.3217C16.5702 51.3686 17.0487 51.2705 17.4674 51.0404C17.6715 51.703 18.1628 52.2387 18.8054 52.4991C19.4479 52.7596 20.1735 52.7172 20.7814 52.3837C21.0903 53.3483 21.9879 54.0022 23.0007 54.0004C23.8044 54.0005 24.5487 53.5772 24.9594 52.8864C25.5142 53.2966 26.2243 53.4351 26.8926 53.2632C27.5609 53.0913 28.1161 52.6274 28.4041 52.0004H34.9661C35.0877 52.0013 35.2068 52.0351 35.3107 52.0984L38.0061 53.7124C38.3161 53.8989 38.6709 53.9982 39.0327 53.9997H48.9054C50.1254 54.016 51.1642 53.1162 51.3221 51.9064C51.3701 51.4308 51.272 50.952 51.0407 50.5337C51.7033 50.3298 52.239 49.8386 52.4995 49.1961C52.76 48.5537 52.7176 47.8281 52.3841 47.2204C53.4332 46.8832 54.1027 45.8571 53.9887 44.761C53.908 44.048 53.5006 43.413 52.8861 43.0424C53.2244 42.5758 53.3795 42.0012 53.3221 41.4277C53.2261 40.6315 52.7267 39.941 52.0007 39.6004V33.0337C52.0022 32.9123 52.036 32.7936 52.0987 32.6897L53.7134 29.995C53.9 29.6847 53.9992 29.3298 54.0007 28.9677V19.095C54.0161 17.8753 53.1163 16.8371 51.9067 16.679ZM15.3394 23.109C15.3085 22.8265 15.3993 22.5441 15.5891 22.3326C15.779 22.121 16.0498 22.0002 16.3341 22.0004H20.6674C21.0356 22.0004 21.3341 21.7019 21.3341 21.3337C21.3341 20.9655 21.0356 20.667 20.6674 20.667H17.6674C17.3832 20.6677 17.1121 20.5474 16.922 20.3362C16.7318 20.1251 16.6404 19.8429 16.6707 19.5604C16.756 19.029 17.2251 18.6454 17.7627 18.667H22.0007C22.3689 18.667 22.6674 18.3686 22.6674 18.0004C22.6674 17.6322 22.3689 17.3337 22.0007 17.3337H19.0007C18.7165 17.3344 18.4455 17.2141 18.2553 17.0029C18.0651 16.7917 17.9738 16.5096 18.0041 16.227C18.0891 15.6956 18.5583 15.3117 19.0961 15.3337H28.9687C29.0903 15.3346 29.2092 15.3687 29.3127 15.4324L32.0087 17.047C32.319 17.2331 32.6736 17.3321 33.0354 17.3337H39.3341V23.2597L38.1794 22.3144C37.3129 21.653 36.0942 21.72 35.3054 22.4724C34.7197 23.0403 34.5162 23.8962 34.7834 24.667H32.5481C32.0234 24.6692 31.5206 24.8775 31.1481 25.247L24.8741 31.4697L24.8607 31.483L24.5834 31.7577C24.2582 32.0756 23.7375 32.0721 23.4167 31.7497C23.1239 31.4557 23.0954 30.9899 23.3501 30.6624L25.1834 28.4224C25.3464 28.223 25.38 27.9475 25.2697 27.7148C25.1594 27.4821 24.9249 27.3337 24.6674 27.3337H17.0961C16.5593 27.3547 16.0913 26.9714 16.0061 26.441C15.9756 26.1587 16.0666 25.8767 16.2564 25.6654C16.4461 25.4542 16.7168 25.3336 17.0007 25.3337H20.6674C21.0356 25.3337 21.3341 25.0352 21.3341 24.667C21.3341 24.2988 21.0356 24.0004 20.6674 24.0004H16.4294C15.8931 24.0211 15.4255 23.6388 15.3394 23.109ZM42.0007 35.7717L35.9141 41.8077C35.7916 41.93 35.6258 41.9991 35.4527 41.9997H32.2287L26.1934 35.9157C26.0707 35.7932 26.0014 35.6271 26.0007 35.4537V32.227L32.0854 26.193C32.208 26.0701 32.3744 26.0008 32.5481 26.0004H35.7747L41.8101 32.0844C41.9318 32.2076 42.0003 32.3738 42.0007 32.547V35.7717ZM26.4354 51.995C26.1547 52.0253 25.8745 51.9341 25.6654 51.7444C25.4554 51.5539 25.3351 51.2839 25.3341 51.0004V50.9904V47.3337C25.3341 46.9655 25.0356 46.667 24.6674 46.667C24.2992 46.667 24.0007 46.9655 24.0007 47.3337V51.0004V51.0097V51.573C24.019 52.1117 23.6326 52.5795 23.1001 52.663C22.82 52.6935 22.5403 52.6022 22.3321 52.4124C22.1216 52.2217 22.0012 51.9511 22.0007 51.667V50.3337V50.3204V47.3337C22.0007 46.9655 21.7023 46.667 21.3341 46.667C20.9659 46.667 20.6674 46.9655 20.6674 47.3337V50.3337V50.3417C20.6656 50.6244 20.5443 50.8931 20.3334 51.0814C20.1225 51.2696 19.8418 51.3599 19.5607 51.3297C19.0295 51.2447 18.6458 50.7759 18.6674 50.2384V49.0004V48.9904V46.0004C18.6674 45.6322 18.3689 45.3337 18.0007 45.3337C17.6325 45.3337 17.3341 45.6322 17.3341 46.0004V49.0004V49.0064C17.3328 49.2893 17.2118 49.5584 17.001 49.7471C16.7902 49.9358 16.5094 50.0264 16.2281 49.9964C15.697 49.9114 15.3131 49.4431 15.3341 48.9057V39.033C15.3351 38.9129 15.3665 38.795 15.4254 38.6904L17.0474 35.993C17.233 35.6828 17.332 35.3285 17.3341 34.967V28.667H23.2594L22.3134 29.8224C21.7035 30.5642 21.6601 31.6207 22.2072 32.41C22.7542 33.1993 23.7587 33.5296 24.6674 33.219V35.4537C24.6696 35.9784 24.8779 36.4812 25.2474 36.8537L31.4647 43.1204C31.4721 43.1284 31.4794 43.1357 31.4874 43.143L31.7587 43.4164C31.9923 43.6541 32.0603 44.0089 31.931 44.3162C31.8018 44.6234 31.5007 44.823 31.1674 44.8224C30.986 44.8232 30.8097 44.7623 30.6674 44.6497L28.4281 42.817C28.2287 42.6505 27.9509 42.615 27.716 42.7259C27.4812 42.8368 27.3321 43.074 27.3341 43.3337V50.905C27.3525 51.4431 26.9671 51.9106 26.4354 51.995ZM52.6621 44.8917C52.693 45.1742 52.6021 45.4566 52.4123 45.6682C52.2225 45.8797 51.9516 46.0005 51.6674 46.0004H47.3341C46.9659 46.0004 46.6674 46.2988 46.6674 46.667C46.6674 47.0352 46.9659 47.3337 47.3341 47.3337H50.3341C50.6183 47.333 50.8893 47.4533 51.0795 47.6645C51.2697 47.8757 51.3611 48.1578 51.3307 48.4404C51.2454 48.9717 50.7764 49.3554 50.2387 49.3337H46.0007C45.6325 49.3337 45.3341 49.6322 45.3341 50.0004C45.3341 50.3686 45.6325 50.667 46.0007 50.667H49.0007C49.2849 50.6664 49.556 50.7866 49.7462 50.9978C49.9364 51.209 50.0277 51.4911 49.9974 51.7737C49.9124 52.3052 49.4432 52.689 48.9054 52.667H39.0327C38.9112 52.6661 38.7923 52.632 38.6887 52.5684L35.9927 50.9537C35.6825 50.7677 35.3278 50.6686 34.9661 50.667H28.6674V44.7397L29.8221 45.685C30.6878 46.349 31.9084 46.2818 32.6961 45.527C33.2819 44.9597 33.4862 44.1045 33.2201 43.3337H35.4534C35.9781 43.3315 36.4809 43.1232 36.8534 42.7537L43.1254 36.5337L43.1487 36.511L43.4201 36.2444C43.7453 35.9264 44.2659 35.93 44.5867 36.2524C44.8795 36.5463 44.9081 37.0122 44.6534 37.3397L42.8201 39.5797C42.6581 39.7788 42.6248 40.0532 42.7345 40.2853C42.8442 40.5173 43.0774 40.6658 43.3341 40.667H50.9054C51.4422 40.6461 51.9102 41.0293 51.9954 41.5597C52.0259 41.842 51.9349 42.124 51.7451 42.3353C51.5554 42.5465 51.2847 42.6672 51.0007 42.667H47.3341C46.9659 42.667 46.6674 42.9655 46.6674 43.3337C46.6674 43.7019 46.9659 44.0004 47.3341 44.0004H51.5741C52.1096 43.9806 52.576 44.3628 52.6621 44.8917ZM52.6674 28.9677C52.6664 29.0891 52.6325 29.208 52.5694 29.3117L50.9541 32.0077C50.7681 32.3178 50.6691 32.6722 50.6674 33.0337V39.3337H44.7401L45.6861 38.1784C46.3727 37.3201 46.3041 36.0827 45.5267 35.3057C44.9444 34.7469 44.1023 34.5528 43.3341 34.8004V32.547C43.3319 32.0223 43.1236 31.5195 42.7541 31.147L36.5341 24.871L36.5214 24.8584L36.2461 24.581C36.0899 24.4267 36.0026 24.2159 36.0041 23.9963C36.0056 23.7768 36.0958 23.5672 36.2541 23.415C36.5521 23.1307 37.0116 23.1026 37.3421 23.3484L39.5814 25.181C39.7805 25.3422 40.0544 25.3749 40.286 25.2654C40.5175 25.1558 40.6658 24.9232 40.6674 24.667V17.0957C40.6468 16.5588 41.0302 16.0909 41.5607 16.0057C41.843 15.9754 42.1248 16.0665 42.3359 16.2562C42.547 16.446 42.6675 16.7165 42.6674 17.0004V20.667C42.6674 21.0352 42.9659 21.3337 43.3341 21.3337C43.7023 21.3337 44.0007 21.0352 44.0007 20.667V16.429C43.9798 15.892 44.3634 15.424 44.8941 15.339C45.1763 15.3088 45.4581 15.3998 45.6692 15.5896C45.8803 15.7793 46.0008 16.0498 46.0007 16.3337V20.667C46.0007 21.0352 46.2992 21.3337 46.6674 21.3337C47.0356 21.3337 47.3341 21.0352 47.3341 20.667V17.667C47.3336 17.3829 47.454 17.1121 47.6651 16.922C47.8763 16.732 48.1583 16.6407 48.4407 16.671C48.9719 16.756 49.3557 17.2248 49.3341 17.7624V22.0004C49.3341 22.3686 49.6325 22.667 50.0007 22.667C50.3689 22.667 50.6674 22.3686 50.6674 22.0004V19.0004C50.6669 18.7163 50.7873 18.4454 50.9984 18.2554C51.2096 18.0653 51.4916 17.9741 51.7741 18.0044C52.3049 18.0896 52.6884 18.5578 52.6674 19.095V28.9677Z\" fill=\"#00B2E3\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1190\" class=\"elementor-element elementor-element-e8d5eec e-con-full e-flex e-con e-child\" data-id=\"e8d5eec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-355585a elementor-widget elementor-widget-heading\" data-id=\"355585a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Notre \u00e9quipe est notre principal atout et veiller au bien-\u00eatre de ses membres fait partie de notre ADN. Nous offrons \u00e0 chacun un espace de travail s\u00fbr et sain o\u00f9 il peut se sentir \u00e9panoui, en bonne sant\u00e9 et \u00e0 l'aise. Cela implique un \u00e9tat d'esprit accueillant, non discriminatoire et sans jugement, o\u00f9 tout le monde est trait\u00e9 de la m\u00eame mani\u00e8re. En outre, le talent et le travail d'\u00e9quipe de nos employ\u00e9s sont ce qui fait avancer nos projets et remplit notre mission, c'est pourquoi nous accordons \u00e9galement de l'importance \u00e0 leur d\u00e9veloppement professionnel, \u00e0 leur formation et \u00e0 une communication transparente, tant en interne qu'en externe.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7b36c7 elementor-widget elementor-widget-heading\" data-id=\"e7b36c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>Domaines potentiels d'int\u00e9r\u00eat :\n<\/b><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1190\" class=\"elementor-element elementor-element-5ce49b1 e-flex e-con-boxed e-con e-child\" data-id=\"5ce49b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db03fec elementor-widget elementor-widget-heading\" data-id=\"db03fec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Nos collaborateurs, notre atout le plus pr\u00e9cieux<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1190\" class=\"elementor-element elementor-element-956ed02 e-flex e-con-boxed e-con e-child\" data-id=\"956ed02\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6fea0c4 elementor-widget elementor-widget-heading\" data-id=\"6fea0c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Diversit\u00e9 et inclusion<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1190\" class=\"elementor-element elementor-element-93539cd e-flex e-con-boxed e-con e-child\" data-id=\"93539cd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79075f0 elementor-widget elementor-widget-heading\" data-id=\"79075f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Bien-\u00eatre, sant\u00e9 et s\u00e9curit\u00e9 des employ\u00e9s<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1190\" class=\"elementor-element elementor-element-f2432a3 e-flex e-con-boxed e-con e-child\" data-id=\"f2432a3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e7fd1a elementor-widget elementor-widget-heading\" data-id=\"5e7fd1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Formation et perfectionnement professionnel<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3476571 elementor-widget elementor-widget-n-accordion\" data-id=\"3476571\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5500\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5500\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Notre plan\u00e8te <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"#00B2E3\"><\/circle><path d=\"M24.3873 54.2502C24.2069 54.2494 24.0341 54.1778 23.906 54.0508L14.2034 44.4258C14.1389 44.3619 14.0878 44.2859 14.0529 44.2021C14.018 44.1183 14 44.0285 14 43.9377C14 43.8469 14.018 43.7571 14.0529 43.6733C14.0878 43.5895 14.1389 43.5135 14.2034 43.4496L17.6684 40.0121C17.7971 39.8842 17.9712 39.8125 18.1527 39.8125C18.3342 39.8125 18.5083 39.8842 18.637 40.0121L28.339 49.6371C28.4035 49.701 28.4546 49.777 28.4895 49.8608C28.5244 49.9446 28.5424 50.0344 28.5424 50.1252C28.5424 50.216 28.5244 50.3058 28.4895 50.3896C28.4546 50.4734 28.4035 50.5494 28.339 50.6133L24.874 54.0508C24.7446 54.1792 24.5696 54.2509 24.3873 54.2502ZM15.6609 43.9377L24.3873 52.5947L26.876 50.1252L18.1503 41.4682L15.6609 43.9377Z\" fill=\"white\"><\/path><path d=\"M19.5381 42.5625C19.4022 42.562 19.2694 42.5211 19.1567 42.4451C19.0439 42.3691 18.9563 42.2613 18.9048 42.1355C18.8532 42.0097 18.8402 41.8714 18.8673 41.7381C18.8944 41.6049 18.9603 41.4827 19.0569 41.3869L22.8581 37.616C23.6946 36.7832 24.6871 36.1235 25.7787 35.6747C26.8704 35.2258 28.0398 34.9966 29.2202 35H42.4085C43.1379 35 43.8373 35.2898 44.3531 35.8055C44.8688 36.3212 45.1585 37.0207 45.1585 37.75C45.1585 38.4794 44.8688 39.1789 44.3531 39.6946C43.8373 40.2103 43.1379 40.5 42.4085 40.5H32.0114C31.8291 40.5 31.6542 40.4276 31.5253 40.2987C31.3964 40.1697 31.3239 39.9949 31.3239 39.8125C31.3239 39.6302 31.3964 39.4553 31.5253 39.3264C31.6542 39.1975 31.8291 39.125 32.0114 39.125H42.4085C42.7732 39.125 43.1229 38.9802 43.3808 38.7223C43.6386 38.4644 43.7835 38.1147 43.7835 37.75C43.7835 37.3854 43.6386 37.0356 43.3808 36.7778C43.1229 36.5199 42.7732 36.375 42.4085 36.375H29.2202C28.219 36.3717 27.2271 36.5658 26.301 36.9463C25.3749 37.3267 24.533 37.886 23.8233 38.5922L20.0221 42.3632C19.8934 42.4908 19.7194 42.5625 19.5381 42.5625Z\" fill=\"white\"><\/path><path d=\"M26.4659 49.4371C26.3299 49.4365 26.1972 49.3956 26.0844 49.3196C25.9717 49.2436 25.884 49.1359 25.8325 49.01C25.781 48.8842 25.7679 48.7459 25.795 48.6127C25.8221 48.4794 25.8881 48.3572 25.9846 48.2615L28.0643 46.199C28.1924 46.0719 28.3652 46.0003 28.5456 45.9996H39.5352C40.3545 46.0024 41.1663 45.8436 41.9242 45.5323C42.682 45.221 43.371 44.7632 43.9517 44.1853L53.3574 34.8552C53.5203 34.6943 53.6496 34.5027 53.7379 34.2914C53.8262 34.0802 53.8716 33.8535 53.8716 33.6246C53.8716 33.3956 53.8262 33.169 53.7379 32.9577C53.6496 32.7465 53.5203 32.5548 53.3574 32.394C53.0247 32.0658 52.5762 31.8818 52.1089 31.8818C51.6416 31.8818 51.1931 32.0658 50.8604 32.394L44.9692 38.2377C44.9055 38.303 44.8294 38.355 44.7454 38.3907C44.6614 38.4263 44.5712 38.4449 44.4799 38.4452C44.3886 38.4456 44.2982 38.4278 44.2139 38.3929C44.1296 38.358 44.0531 38.3066 43.9888 38.2418C43.9246 38.177 43.8739 38.1001 43.8396 38.0155C43.8054 37.9309 43.7884 37.8403 43.7896 37.749C43.7907 37.6578 43.81 37.5677 43.8464 37.484C43.8827 37.4003 43.9354 37.3246 44.0012 37.2615L49.8917 31.4177C50.4824 30.8347 51.279 30.5078 52.1089 30.5078C52.9389 30.5078 53.7354 30.8347 54.3261 31.4177C54.6179 31.7064 54.8495 32.0501 55.0076 32.4289C55.1656 32.8077 55.247 33.2141 55.247 33.6246C55.247 34.035 55.1656 34.4414 55.0076 34.8202C54.8495 35.199 54.6179 35.5427 54.3261 35.8315L44.9197 45.1615C44.2118 45.8662 43.3718 46.4244 42.4478 46.8042C41.5239 47.1839 40.5342 47.3778 39.5352 47.3746H28.8281L26.9499 49.2377C26.8211 49.3654 26.6472 49.437 26.4659 49.4371Z\" fill=\"white\"><\/path><path d=\"M40.9698 29.3165C40.048 29.3401 39.1382 29.1032 38.3449 28.6331C36.4288 27.3558 34.8015 24.678 35.7558 21.8159C36.7712 18.7703 38.6137 17.9343 40.747 16.967C41.1863 16.7676 41.647 16.5586 42.1282 16.318C43.7558 15.4977 45.2572 14.4482 46.5867 13.2015C46.6707 13.1174 46.7752 13.0565 46.8898 13.0248C47.0045 12.9932 47.1254 12.9918 47.2407 13.0208C47.3561 13.0498 47.4619 13.1083 47.5479 13.1904C47.6339 13.2726 47.6971 13.3757 47.7313 13.4896C48.5892 17.0009 48.426 20.6842 47.2611 24.106C46.2037 27.2781 44.3213 28.5135 42.9298 28.9913C42.2989 29.2073 41.6366 29.3172 40.9698 29.3165ZM46.6472 14.9876C45.4459 15.9848 44.1362 16.8436 42.7428 17.5479C42.2458 17.7968 41.7693 18.0133 41.3149 18.2189C39.2524 19.156 37.8857 19.7747 37.06 22.2511C36.2247 24.7577 38.0335 26.7735 39.1073 27.4891C39.6253 27.7546 40.1927 27.9096 40.7736 27.9444C41.3545 27.9792 41.9364 27.893 42.4823 27.6913C44.0587 27.1502 45.2598 25.7601 45.9562 23.6708C46.8775 20.8733 47.1144 17.8956 46.6472 14.9876Z\" fill=\"white\"><\/path><path d=\"M35.4796 34.313C35.4414 34.3132 35.4032 34.31 35.3655 34.3034C35.2764 34.2886 35.1912 34.2563 35.1146 34.2085C35.038 34.1607 34.9715 34.0983 34.919 34.0248C34.8666 33.9513 34.8291 33.8682 34.8087 33.7803C34.7884 33.6923 34.7855 33.6012 34.8004 33.5121C35.7813 28.1858 38.6859 23.4059 42.9617 20.0818C43.1101 19.9776 43.2936 19.9363 43.4724 19.9668C43.6511 19.9974 43.8105 20.0972 43.9159 20.2447C44.0214 20.3922 44.0643 20.5754 44.0353 20.7544C44.0063 20.9333 43.9078 21.0936 43.7613 21.2003C43.6973 21.2505 37.4823 25.788 36.1568 33.739C36.13 33.8993 36.0473 34.0449 35.9233 34.15C35.7993 34.255 35.6422 34.3128 35.4796 34.313Z\" fill=\"white\"><\/path><path d=\"M29.5045 27.6515C28.9707 27.6518 28.4406 27.5638 27.9356 27.3909C26.8205 27.0087 25.3142 26.0221 24.4727 23.4969C23.5575 20.8074 23.4296 17.9125 24.1042 15.1527C24.1382 15.0387 24.2013 14.9355 24.2872 14.8532C24.3732 14.7709 24.479 14.7123 24.5944 14.6831C24.7097 14.6539 24.8307 14.6552 24.9454 14.6868C25.0601 14.7184 25.1647 14.7792 25.2489 14.8633C26.2713 15.8219 27.4253 16.6296 28.676 17.262C29.048 17.4476 29.4041 17.6057 29.7437 17.7632C31.435 18.5304 32.8959 19.1925 33.7065 21.6242C34.0006 22.6373 33.9574 23.7187 33.5834 24.7051C33.2094 25.6916 32.5249 26.5298 31.633 27.0933C30.99 27.4757 30.2523 27.6692 29.5045 27.6515ZM25.2042 16.6481C24.901 18.8015 25.0967 20.9959 25.7762 23.0617C26.3021 24.6389 27.2027 25.6866 28.3811 26.0909C28.7836 26.238 29.2118 26.3017 29.6396 26.2781C30.0675 26.2544 30.4861 26.144 30.8699 25.9534C31.6708 25.4199 33.021 23.9184 32.4009 22.0573C31.7808 20.1962 30.744 19.726 29.1752 19.0144C28.8211 18.8536 28.4485 18.6844 28.0607 18.4906C27.0469 17.9778 26.0895 17.3602 25.2042 16.6481Z\" fill=\"white\"><\/path><path d=\"M35.9981 31.5625C35.858 31.5626 35.7213 31.5199 35.6062 31.4402C35.4911 31.3605 35.403 31.2475 35.3539 31.1163C33.4034 25.9133 27.4731 22.5714 27.4139 22.5384C27.335 22.4945 27.2655 22.4355 27.2094 22.3648C27.1533 22.2941 27.1117 22.213 27.0869 22.1261C27.0622 22.0393 27.0547 21.9485 27.0651 21.8588C27.0754 21.7691 27.1033 21.6823 27.1472 21.6034C27.1911 21.5245 27.2501 21.455 27.3208 21.3989C27.3915 21.3428 27.4726 21.3012 27.5595 21.2764C27.6463 21.2516 27.7371 21.2442 27.8268 21.2545C27.9165 21.2649 28.0033 21.2928 28.0822 21.3367C28.3434 21.4817 34.5151 24.9618 36.6423 30.6337C36.674 30.7183 36.6888 30.8083 36.6857 30.8986C36.6826 30.9889 36.6618 31.0777 36.6244 31.16C36.5869 31.2422 36.5337 31.3163 36.4676 31.3779C36.4016 31.4396 36.324 31.4876 36.2394 31.5192C36.1621 31.5476 36.0804 31.5622 35.9981 31.5625Z\" fill=\"white\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"white\"><\/circle><path d=\"M24.3873 54.2502C24.2069 54.2494 24.0341 54.1778 23.906 54.0508L14.2034 44.4258C14.1389 44.3619 14.0878 44.2859 14.0529 44.2021C14.018 44.1183 14 44.0285 14 43.9377C14 43.8469 14.018 43.7571 14.0529 43.6733C14.0878 43.5895 14.1389 43.5135 14.2034 43.4496L17.6684 40.0121C17.7971 39.8842 17.9712 39.8125 18.1527 39.8125C18.3342 39.8125 18.5083 39.8842 18.637 40.0121L28.339 49.6371C28.4035 49.701 28.4546 49.777 28.4895 49.8608C28.5244 49.9446 28.5424 50.0344 28.5424 50.1252C28.5424 50.216 28.5244 50.3058 28.4895 50.3896C28.4546 50.4734 28.4035 50.5494 28.339 50.6133L24.874 54.0508C24.7446 54.1792 24.5696 54.2509 24.3873 54.2502ZM15.6609 43.9377L24.3873 52.5947L26.876 50.1252L18.1503 41.4682L15.6609 43.9377Z\" fill=\"#00B2E3\"><\/path><path d=\"M19.5381 42.5625C19.4022 42.562 19.2694 42.5211 19.1567 42.4451C19.0439 42.3691 18.9563 42.2613 18.9048 42.1355C18.8532 42.0097 18.8402 41.8714 18.8673 41.7381C18.8944 41.6049 18.9603 41.4827 19.0569 41.3869L22.8581 37.616C23.6946 36.7832 24.6871 36.1235 25.7787 35.6747C26.8704 35.2258 28.0398 34.9966 29.2202 35H42.4085C43.1379 35 43.8373 35.2898 44.3531 35.8055C44.8688 36.3212 45.1585 37.0207 45.1585 37.75C45.1585 38.4794 44.8688 39.1789 44.3531 39.6946C43.8373 40.2103 43.1379 40.5 42.4085 40.5H32.0114C31.8291 40.5 31.6542 40.4276 31.5253 40.2987C31.3964 40.1697 31.3239 39.9949 31.3239 39.8125C31.3239 39.6302 31.3964 39.4553 31.5253 39.3264C31.6542 39.1975 31.8291 39.125 32.0114 39.125H42.4085C42.7732 39.125 43.1229 38.9802 43.3808 38.7223C43.6386 38.4644 43.7835 38.1147 43.7835 37.75C43.7835 37.3854 43.6386 37.0356 43.3808 36.7778C43.1229 36.5199 42.7732 36.375 42.4085 36.375H29.2202C28.219 36.3717 27.2271 36.5658 26.301 36.9463C25.3749 37.3267 24.533 37.886 23.8233 38.5922L20.0221 42.3632C19.8934 42.4908 19.7194 42.5625 19.5381 42.5625Z\" fill=\"#00B2E3\"><\/path><path d=\"M26.4659 49.4371C26.3299 49.4365 26.1972 49.3956 26.0844 49.3196C25.9717 49.2436 25.884 49.1359 25.8325 49.01C25.781 48.8842 25.7679 48.7459 25.795 48.6127C25.8221 48.4794 25.8881 48.3572 25.9846 48.2615L28.0643 46.199C28.1924 46.0719 28.3652 46.0003 28.5456 45.9996H39.5352C40.3545 46.0024 41.1663 45.8436 41.9242 45.5323C42.682 45.221 43.371 44.7632 43.9517 44.1853L53.3574 34.8552C53.5203 34.6943 53.6496 34.5027 53.7379 34.2914C53.8262 34.0802 53.8716 33.8535 53.8716 33.6246C53.8716 33.3956 53.8262 33.169 53.7379 32.9577C53.6496 32.7465 53.5203 32.5548 53.3574 32.394C53.0247 32.0658 52.5762 31.8818 52.1089 31.8818C51.6416 31.8818 51.1931 32.0658 50.8604 32.394L44.9692 38.2377C44.9055 38.303 44.8294 38.355 44.7454 38.3907C44.6614 38.4263 44.5712 38.4449 44.4799 38.4452C44.3886 38.4456 44.2982 38.4278 44.2139 38.3929C44.1296 38.358 44.0531 38.3066 43.9888 38.2418C43.9246 38.177 43.8739 38.1001 43.8396 38.0155C43.8054 37.9309 43.7884 37.8403 43.7896 37.749C43.7907 37.6578 43.81 37.5677 43.8464 37.484C43.8827 37.4003 43.9354 37.3246 44.0012 37.2615L49.8917 31.4177C50.4824 30.8347 51.279 30.5078 52.1089 30.5078C52.9389 30.5078 53.7354 30.8347 54.3261 31.4177C54.6179 31.7064 54.8495 32.0501 55.0076 32.4289C55.1656 32.8077 55.247 33.2141 55.247 33.6246C55.247 34.035 55.1656 34.4414 55.0076 34.8202C54.8495 35.199 54.6179 35.5427 54.3261 35.8315L44.9197 45.1615C44.2118 45.8662 43.3718 46.4244 42.4478 46.8042C41.5239 47.1839 40.5342 47.3778 39.5352 47.3746H28.8281L26.9499 49.2377C26.8211 49.3654 26.6472 49.437 26.4659 49.4371Z\" fill=\"#00B2E3\"><\/path><path d=\"M40.9698 29.3165C40.048 29.3401 39.1382 29.1032 38.3449 28.6331C36.4288 27.3558 34.8015 24.678 35.7558 21.8159C36.7712 18.7703 38.6137 17.9343 40.747 16.967C41.1863 16.7676 41.647 16.5586 42.1282 16.318C43.7558 15.4977 45.2572 14.4482 46.5867 13.2015C46.6707 13.1174 46.7752 13.0565 46.8898 13.0248C47.0045 12.9932 47.1254 12.9918 47.2407 13.0208C47.3561 13.0498 47.4619 13.1083 47.5479 13.1904C47.6339 13.2726 47.6971 13.3757 47.7313 13.4896C48.5892 17.0009 48.426 20.6842 47.2611 24.106C46.2037 27.2781 44.3213 28.5135 42.9298 28.9913C42.2989 29.2073 41.6366 29.3172 40.9698 29.3165ZM46.6472 14.9876C45.4459 15.9848 44.1362 16.8436 42.7428 17.5479C42.2458 17.7968 41.7693 18.0133 41.3149 18.2189C39.2524 19.156 37.8857 19.7747 37.06 22.2511C36.2247 24.7577 38.0335 26.7735 39.1073 27.4891C39.6253 27.7546 40.1927 27.9096 40.7736 27.9444C41.3545 27.9792 41.9364 27.893 42.4823 27.6913C44.0587 27.1502 45.2598 25.7601 45.9562 23.6708C46.8775 20.8733 47.1144 17.8956 46.6472 14.9876Z\" fill=\"#00B2E3\"><\/path><path d=\"M35.4796 34.313C35.4414 34.3132 35.4032 34.31 35.3655 34.3034C35.2764 34.2886 35.1912 34.2563 35.1146 34.2085C35.038 34.1607 34.9715 34.0983 34.919 34.0248C34.8666 33.9513 34.8291 33.8682 34.8087 33.7803C34.7884 33.6923 34.7855 33.6012 34.8004 33.5121C35.7813 28.1858 38.6859 23.4059 42.9617 20.0818C43.1101 19.9776 43.2936 19.9363 43.4724 19.9668C43.6511 19.9974 43.8105 20.0972 43.9159 20.2447C44.0214 20.3922 44.0643 20.5754 44.0353 20.7544C44.0063 20.9333 43.9078 21.0936 43.7613 21.2003C43.6973 21.2505 37.4823 25.788 36.1568 33.739C36.13 33.8993 36.0473 34.0449 35.9233 34.15C35.7993 34.255 35.6422 34.3128 35.4796 34.313Z\" fill=\"#00B2E3\"><\/path><path d=\"M29.5045 27.6515C28.9707 27.6518 28.4406 27.5638 27.9356 27.3909C26.8205 27.0087 25.3142 26.0221 24.4727 23.4969C23.5575 20.8074 23.4296 17.9125 24.1042 15.1527C24.1382 15.0387 24.2013 14.9355 24.2872 14.8532C24.3732 14.7709 24.479 14.7123 24.5944 14.6831C24.7097 14.6539 24.8307 14.6552 24.9454 14.6868C25.0601 14.7184 25.1647 14.7792 25.2489 14.8633C26.2713 15.8219 27.4253 16.6296 28.676 17.262C29.048 17.4476 29.4041 17.6057 29.7437 17.7632C31.435 18.5304 32.8959 19.1925 33.7065 21.6242C34.0006 22.6373 33.9574 23.7187 33.5834 24.7051C33.2094 25.6916 32.5249 26.5298 31.633 27.0933C30.99 27.4757 30.2523 27.6692 29.5045 27.6515ZM25.2042 16.6481C24.901 18.8015 25.0967 20.9959 25.7762 23.0617C26.3021 24.6389 27.2027 25.6866 28.3811 26.0909C28.7836 26.238 29.2118 26.3017 29.6396 26.2781C30.0675 26.2544 30.4861 26.144 30.8699 25.9534C31.6708 25.4199 33.021 23.9184 32.4009 22.0573C31.7808 20.1962 30.744 19.726 29.1752 19.0144C28.8211 18.8536 28.4485 18.6844 28.0607 18.4906C27.0469 17.9778 26.0895 17.3602 25.2042 16.6481Z\" fill=\"#00B2E3\"><\/path><path d=\"M35.9981 31.5625C35.858 31.5626 35.7213 31.5199 35.6062 31.4402C35.4911 31.3605 35.403 31.2475 35.3539 31.1163C33.4034 25.9133 27.4731 22.5714 27.4139 22.5384C27.335 22.4945 27.2655 22.4355 27.2094 22.3648C27.1533 22.2941 27.1117 22.213 27.0869 22.1261C27.0622 22.0393 27.0547 21.9485 27.0651 21.8588C27.0754 21.7691 27.1033 21.6823 27.1472 21.6034C27.1911 21.5245 27.2501 21.455 27.3208 21.3989C27.3915 21.3428 27.4726 21.3012 27.5595 21.2764C27.6463 21.2516 27.7371 21.2442 27.8268 21.2545C27.9165 21.2649 28.0033 21.2928 28.0822 21.3367C28.3434 21.4817 34.5151 24.9618 36.6423 30.6337C36.674 30.7183 36.6888 30.8083 36.6857 30.8986C36.6826 30.9889 36.6618 31.0777 36.6244 31.16C36.5869 31.2422 36.5337 31.3163 36.4676 31.3779C36.4016 31.4396 36.324 31.4876 36.2394 31.5192C36.1621 31.5476 36.0804 31.5622 35.9981 31.5625Z\" fill=\"#00B2E3\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5500\" class=\"elementor-element elementor-element-c0e87a2 e-con-full e-flex e-con e-child\" data-id=\"c0e87a2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed4b163 elementor-widget elementor-widget-heading\" data-id=\"ed4b163\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Les questions environnementales sont une r\u00e9alit\u00e9 difficile qui devient de plus en plus pertinente pour nous. Nous nous engageons \u00e0 prendre soin de l'environnement en adaptant notre mod\u00e8le d'entreprise et nos activit\u00e9s \u00e0 tous les niveaux de l'organisation gr\u00e2ce \u00e0 des politiques, des processus et des initiatives respectueux de l'environnement afin d'att\u00e9nuer les effets du changement climatique, d'utiliser des ressources efficaces et de r\u00e9duire nos \u00e9missions carbone, d\u00e9montrant ainsi notre responsabilit\u00e9 \u00e0 l'\u00e9gard de l'environnement.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48f32cc elementor-widget elementor-widget-heading\" data-id=\"48f32cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>Domaines potentiels d'int\u00e9r\u00eat :<\/b><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5500\" class=\"elementor-element elementor-element-33a4572 e-flex e-con-boxed e-con e-child\" data-id=\"33a4572\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-871eb5f elementor-widget elementor-widget-heading\" data-id=\"871eb5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Engagement environnemental<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5500\" class=\"elementor-element elementor-element-e81a48b e-flex e-con-boxed e-con e-child\" data-id=\"e81a48b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a6d7e2 elementor-widget elementor-widget-heading\" data-id=\"7a6d7e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Changement climatique et \u00e9missions<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5500\" class=\"elementor-element elementor-element-1c49791 e-flex e-con-boxed e-con e-child\" data-id=\"1c49791\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae01619 elementor-widget elementor-widget-heading\" data-id=\"ae01619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00c9conomie circulaire et d\u00e9chets<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5500\" class=\"elementor-element elementor-element-94d3de4 e-flex e-con-boxed e-con e-child\" data-id=\"94d3de4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b2ef76 elementor-widget elementor-widget-heading\" data-id=\"8b2ef76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Eau et \u00e9nergie<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7994875 elementor-widget elementor-widget-n-accordion\" data-id=\"7994875\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1270\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1270\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Notre m\u00e9thode <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"#00B2E3\"><\/circle><path d=\"M34.5379 34.9397C35.0255 34.9396 35.5164 34.8437 35.981 34.6474L37.0938 36.2729C36.6402 37.2188 36.7133 38.3552 37.321 39.243C38.2509 40.6013 40.1023 40.9477 41.4604 40.0179L47.6094 35.808C48.9642 34.8804 49.3118 33.0235 48.3842 31.6688C47.768 30.7687 46.7431 30.3036 45.6979 30.3834L38.0867 19.2662C38.5405 18.3203 38.4673 17.1839 37.8595 16.2961C36.9303 14.9388 35.0779 14.5917 33.7203 15.5212C33.7202 15.5212 33.7202 15.5212 33.7202 15.5212L27.5712 19.7311C26.2133 20.6608 25.8664 22.5123 26.7965 23.8705C27.3926 24.7411 28.4146 25.2396 29.4831 25.1565L30.5955 26.7812C30.0893 27.3013 29.7466 27.9585 29.61 28.6881C29.5228 29.154 29.5256 29.6225 29.6121 30.0745L16.1343 39.302C14.946 40.1156 14.6429 41.735 15.4564 42.9234C16.2699 44.1116 17.8894 44.4149 19.0777 43.6012L32.5578 34.3722C33.1541 34.7443 33.8422 34.9397 34.5379 34.9397ZM47.1595 32.5072C47.6258 33.1884 47.452 34.1167 46.7709 34.5832L40.6219 38.793C39.9424 39.2581 39.0112 39.084 38.5458 38.4045C38.0813 37.7259 38.2541 36.7944 38.9344 36.3284L45.0834 32.1185C45.7532 31.66 46.6868 31.817 47.1595 32.5072ZM38.0933 35.1053L36.8292 33.2589C36.829 33.2587 36.8289 33.2584 36.8287 33.2582C36.8286 33.258 36.8284 33.2577 36.8282 33.2575L32.198 26.4944L32.1979 26.4942C32.1978 26.4942 32.1978 26.4941 32.1978 26.4941L30.9332 24.647C30.9615 24.6281 37.0408 20.4648 37.0872 20.4338L44.2475 30.892C44.1611 30.9491 38.1047 35.0987 38.0933 35.1053ZM28.0211 23.0319C27.5547 22.3506 27.7286 21.4223 28.4097 20.9559L34.5587 16.746L34.5586 16.746C35.2375 16.2813 36.1676 16.4524 36.6347 17.1346C37.0993 17.8132 36.9264 18.7445 36.2461 19.2107L30.0971 23.4205C29.4166 23.8866 28.4861 23.7109 28.0211 23.0319ZM35.113 33.3795C34.2213 33.6182 33.2356 33.2865 32.6852 32.4825L31.4222 30.6378C31.0844 30.1444 30.959 29.5489 31.069 28.9612C31.1318 28.6258 31.2672 28.316 31.4633 28.0489L35.113 33.3795ZM30.1974 31.4763L31.4604 33.321C31.461 33.3218 31.4616 33.3226 31.4622 33.3234L19.774 41.3257L18.5076 39.476L30.1957 31.4738C30.1963 31.4746 30.1968 31.4755 30.1974 31.4763ZM16.6812 42.0848C16.3312 41.5735 16.4614 40.8769 16.9729 40.5268L17.2828 40.3146L18.5492 42.1642L18.2392 42.3765C17.7292 42.7257 17.0322 42.5973 16.6812 42.0848Z\" fill=\"white\"><\/path><path d=\"M50.7642 48.6255V47.0312C50.7642 45.3943 49.4324 44.0625 47.7955 44.0625H33.6184C31.9815 44.0625 30.6497 45.3943 30.6497 47.0312V48.6255C29.3662 48.9528 28.4141 50.1184 28.4141 51.5024V52.2567C28.4141 52.6666 28.7464 52.9989 29.1562 52.9989H52.2576C52.6676 52.9989 52.9998 52.6665 52.9998 52.2567V51.5024C52.9998 50.1185 52.0477 48.9528 50.7642 48.6255ZM33.6183 45.5469H47.7954C48.6139 45.5469 49.2797 46.2127 49.2797 47.0312V48.5337H32.134V47.0312C32.134 46.2127 32.7999 45.5469 33.6183 45.5469ZM51.5154 51.5145H29.8983V51.5024C29.8983 50.684 30.5642 50.0181 31.3827 50.0181H50.031C50.8495 50.0181 51.5154 50.684 51.5154 51.5024V51.5145Z\" fill=\"white\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"68\" viewBox=\"0 0 68 68\" fill=\"none\"><circle cx=\"34\" cy=\"34\" r=\"34\" fill=\"white\"><\/circle><path d=\"M34.5379 34.9397C35.0255 34.9396 35.5164 34.8437 35.981 34.6474L37.0938 36.2729C36.6402 37.2188 36.7133 38.3552 37.321 39.243C38.2509 40.6013 40.1023 40.9477 41.4604 40.0179L47.6094 35.808C48.9642 34.8804 49.3118 33.0235 48.3842 31.6688C47.768 30.7687 46.7431 30.3036 45.6979 30.3834L38.0867 19.2662C38.5405 18.3203 38.4673 17.1839 37.8595 16.2961C36.9303 14.9388 35.0779 14.5917 33.7203 15.5212C33.7202 15.5212 33.7202 15.5212 33.7202 15.5212L27.5712 19.7311C26.2133 20.6608 25.8664 22.5123 26.7965 23.8705C27.3926 24.7411 28.4146 25.2396 29.4831 25.1565L30.5955 26.7812C30.0893 27.3013 29.7466 27.9585 29.61 28.6881C29.5228 29.154 29.5256 29.6225 29.6121 30.0745L16.1343 39.302C14.946 40.1156 14.6429 41.735 15.4564 42.9234C16.2699 44.1116 17.8894 44.4149 19.0777 43.6012L32.5578 34.3722C33.1541 34.7443 33.8422 34.9397 34.5379 34.9397ZM47.1595 32.5072C47.6258 33.1884 47.452 34.1167 46.7709 34.5832L40.6219 38.793C39.9424 39.2581 39.0112 39.084 38.5458 38.4045C38.0813 37.7259 38.2541 36.7944 38.9344 36.3284L45.0834 32.1185C45.7532 31.66 46.6868 31.817 47.1595 32.5072ZM38.0933 35.1053L36.8292 33.2589C36.829 33.2587 36.8289 33.2584 36.8287 33.2582C36.8286 33.258 36.8284 33.2577 36.8282 33.2575L32.198 26.4944L32.1979 26.4942C32.1978 26.4942 32.1978 26.4941 32.1978 26.4941L30.9332 24.647C30.9615 24.6281 37.0408 20.4648 37.0872 20.4338L44.2475 30.892C44.1611 30.9491 38.1047 35.0987 38.0933 35.1053ZM28.0211 23.0319C27.5547 22.3506 27.7286 21.4223 28.4097 20.9559L34.5587 16.746L34.5586 16.746C35.2375 16.2813 36.1676 16.4524 36.6347 17.1346C37.0993 17.8132 36.9264 18.7445 36.2461 19.2107L30.0971 23.4205C29.4166 23.8866 28.4861 23.7109 28.0211 23.0319ZM35.113 33.3795C34.2213 33.6182 33.2356 33.2865 32.6852 32.4825L31.4222 30.6378C31.0844 30.1444 30.959 29.5489 31.069 28.9612C31.1318 28.6258 31.2672 28.316 31.4633 28.0489L35.113 33.3795ZM30.1974 31.4763L31.4604 33.321C31.461 33.3218 31.4616 33.3226 31.4622 33.3234L19.774 41.3257L18.5076 39.476L30.1957 31.4738C30.1963 31.4746 30.1968 31.4755 30.1974 31.4763ZM16.6812 42.0848C16.3312 41.5735 16.4614 40.8769 16.9729 40.5268L17.2828 40.3146L18.5492 42.1642L18.2392 42.3765C17.7292 42.7257 17.0322 42.5973 16.6812 42.0848Z\" fill=\"#00B2E3\"><\/path><path d=\"M50.7642 48.6255V47.0312C50.7642 45.3943 49.4324 44.0625 47.7955 44.0625H33.6184C31.9815 44.0625 30.6497 45.3943 30.6497 47.0312V48.6255C29.3662 48.9528 28.4141 50.1184 28.4141 51.5024V52.2567C28.4141 52.6666 28.7464 52.9989 29.1562 52.9989H52.2576C52.6676 52.9989 52.9998 52.6665 52.9998 52.2567V51.5024C52.9998 50.1185 52.0477 48.9528 50.7642 48.6255ZM33.6183 45.5469H47.7954C48.6139 45.5469 49.2797 46.2127 49.2797 47.0312V48.5337H32.134V47.0312C32.134 46.2127 32.7999 45.5469 33.6183 45.5469ZM51.5154 51.5145H29.8983V51.5024C29.8983 50.684 30.5642 50.0181 31.3827 50.0181H50.031C50.8495 50.0181 51.5154 50.684 51.5154 51.5024V51.5145Z\" fill=\"#00B2E3\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-99e07d7 e-con-full e-flex e-con e-child\" data-id=\"99e07d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8cd78b elementor-widget elementor-widget-heading\" data-id=\"b8cd78b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Chez Neuraxpharm, nous avons une forte culture d'entreprise \u00e0 laquelle nous demandons de se conformer \u00e9troitement et nous avons une tol\u00e9rance z\u00e9ro pour les infractions de toute nature li\u00e9es au risque ou \u00e0 l'\u00e9thique. Nous promouvons un environnement favorable et juste pour tous par l'adh\u00e9sion \u00e0 nos normes et politiques et par une gouvernance responsable. Nous accordons \u00e9galement la priorit\u00e9 aux pratiques \u00e9thiques et responsables tout au long de notre cha\u00eene d'approvisionnement, notamment en ce qui concerne la sant\u00e9 de nos patients, la durabilit\u00e9 environnementale, l'approvisionnement \u00e9thique et la responsabilit\u00e9 sociale.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-499c32d elementor-widget elementor-widget-heading\" data-id=\"499c32d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>\nDomaines potentiels d'int\u00e9r\u00eat :<\/b><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-78c3171 e-flex e-con-boxed e-con e-child\" data-id=\"78c3171\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b010810 elementor-widget elementor-widget-heading\" data-id=\"b010810\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Gouvernance, conformit\u00e9 et \u00e9thique<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-a6406ed e-flex e-con-boxed e-con e-child\" data-id=\"a6406ed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23e23e6 elementor-widget elementor-widget-heading\" data-id=\"23e23e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Cha\u00eene d'approvisionnement responsable<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e73d57a elementor-widget elementor-widget-html\" data-id=\"e73d57a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\n  document.addEventListener('DOMContentLoaded', function() {\n    function setupToggle(toggleClass, plegadoClass, desplegadoClass) {\n        var cuadroPlegado = document.querySelector(plegadoClass);\n        var cuadroDesplegado = document.querySelector(desplegadoClass);\n\n        \/\/ Aplicar el estilo del cursor al cargar la p\u00e1gina\n        cuadroPlegado.style.cursor = 'pointer';\n        cuadroDesplegado.style.cursor = 'pointer';\n\n        cuadroPlegado.addEventListener('click', function() {\n            cuadroPlegado.style.display = 'none';\n            cuadroDesplegado.style.display = 'block';\n        });\n\n        cuadroDesplegado.addEventListener('click', function() {\n            cuadroPlegado.style.display = 'block';\n            cuadroDesplegado.style.display = 'none';\n        });\n    }\n\n    \/\/ Llamar a la funci\u00f3n para cada conjunto de elementos\n    for (let i = 1; i <= 5; i++) {\n        setupToggle(`.toggle${i}-cuadro`, `.d${i}plegado`, `.d${i}desplegado`);\n    }\n});\n\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ee6622 d3desplegado toggle3-cuadro elementor-widget elementor-widget-template\" data-id=\"9ee6622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66292ad d4desplegado toggle4-cuadro elementor-widget elementor-widget-template\" data-id=\"66292ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f87c472 d5desplegado toggle5-cuadro elementor-widget elementor-widget-template\" data-id=\"f87c472\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a0491d elementor-widget elementor-widget-spacer\" data-id=\"1a0491d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4195714 no_in_this_section elementor-widget elementor-widget-heading\" data-id=\"4195714\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Faits marquants ESG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5df2ec0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5df2ec0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a0822c\" data-id=\"7a0822c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9303816 elementor-position-right elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"9303816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081952\/imgi-37-ecovaldi-silver-medal-1-300x300-1.png\" class=\"attachment-full size-full wp-image-28978\" alt=\"M\u00e9daille argent EcoVadis 2024 notation durabilit\u00e9\" srcset=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081952\/imgi-37-ecovaldi-silver-medal-1-300x300-1.png 300w, https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081952\/imgi-37-ecovaldi-silver-medal-1-300x300-1-150x150.png 150w, https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081952\/imgi-37-ecovaldi-silver-medal-1-300x300-1-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">En septembre 2024, Neuraxpharm Pharmaceuticals a renouvel\u00e9 sa m\u00e9daille d\u2019argent, d\u00e9cern\u00e9e par l\u2019agence internationale de notation RSE, EcoVadis.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-09f8cbc\" data-id=\"09f8cbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77c92bd elementor-position-right elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"77c92bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"218\" height=\"227\" src=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081945\/imgi-22-solar-panels-1.png\" class=\"attachment-full size-full wp-image-28977\" alt=\"Panneaux solaires sur toit urbain au coucher de soleil\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Plus de 400 panneaux solaires ont \u00e9t\u00e9 install\u00e9s dans notre usine de production de Sant Joan Desp\u00ed, \u00e0 Barcelone, pour produire de l'\u00e9nergie renouvelable.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb1a0d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb1a0d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fbd1bee\" data-id=\"fbd1bee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0a567c elementor-position-right elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"e0a567c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"141\" height=\"171\" src=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081938\/imgi-23-ghg-emissions-2024-1.jpg\" class=\"attachment-full size-full wp-image-28976\" alt=\"\u00c9missions GHG 2024 par scope\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Neuraxpharm a r\u00e9ussi \u00e0 calculer l\u2019empreinte carbone compl\u00e8te (scopes 1, 2 et 3) pour l\u2019ensemble de ses filiales en 2024, avec l\u2019aide d\u2019un organisme externe sp\u00e9cialis\u00e9.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a926996\" data-id=\"a926996\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d85fc32 elementor-position-right elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"d85fc32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"145\" height=\"163\" src=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081933\/imgi-24-kiss-mental-health-1.png\" class=\"attachment-full size-full wp-image-28974\" alt=\"Portrait\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Neuraxpharm a lanc\u00e9 \u00ab Un baiser pour la sant\u00e9 mentale \u00bb, notre initiative sociale en Espagne et au Portugal, pour sensibiliser \u00e0 l'importance de prendre soin de la sant\u00e9 mentale.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0f53d6 elementor-widget elementor-widget-spacer\" data-id=\"c0f53d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01909a3 elementor-widget elementor-widget-menu-anchor\" data-id=\"01909a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Diversity\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32591be no_in_this_section elementor-widget elementor-widget-heading\" data-id=\"32591be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diversit\u00e9, \u00e9galit\u00e9 et inclusion<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1062804 elementor-widget elementor-widget-text-editor\" data-id=\"1062804\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez Neuraxpharm, nous garantissons un environnement de travail inclusif, diversifi\u00e9, s\u00fbr et respectueux pour tous les membres de notre organisation. Nous prenons soin de nos collaborateurs autant que de nos patients et nous nous engageons donc \u00e0 garantir un lieu de travail sain, inclusif et offrant l&rsquo;\u00e9galit\u00e9 des chances, qui permette aux employ\u00e9s de d\u00e9velopper leur potentiel professionnel, tout en assurant leur satisfaction individuelle et collective.<\/p><p><!--We are guided by a Diversity &amp; Inclusion policy to ensure a business culture based on the principles of diversity, equality and inclusion. Our policy complies with European legal regulations and includes the necessary standards, processes and measures that need to be taken in the event of discrimination or harassment against any employee of the company.--><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b30f0f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"5b30f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2025\/11\/diversity-nx.png\" class=\"attachment-full size-full wp-image-28973\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d1d6b8 elementor-widget elementor-widget-text-editor\" data-id=\"8d1d6b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes guid\u00e9s par une politique de diversit\u00e9 et d&rsquo;inclusion afin de garantir une culture d&rsquo;entreprise fond\u00e9e sur les principes de diversit\u00e9, d&rsquo;\u00e9galit\u00e9 et d&rsquo;inclusion. Notre politique est conforme aux r\u00e9glementations juridiques europ\u00e9ennes et comprend les normes, processus et mesures n\u00e9cessaires \u00e0 prendre en cas de discrimination ou de harc\u00e8lement \u00e0 l&rsquo;encontre d&rsquo;un employ\u00e9 de l&rsquo;entreprise.<\/p><p><!--Additionally, in 2024, our plan is to further evaluate our HR data in respect of selection and talent development, with the objective of promoting best practice in Diversity, Equality &amp; Inclusion (DEI)\u00a0principles, as well as promoting awareness of the cultural drivers behind our decision taking.--><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4bef4b3 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"4bef4b3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;96bf8d3&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f849187\" data-id=\"f849187\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-759be38 elementor-widget elementor-widget-counter\" data-id=\"759be38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Salari\u00e9s du groupe<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">~<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1000\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d23832b\" data-id=\"d23832b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75a4d7a elementor-widget elementor-widget-counter\" data-id=\"75a4d7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Nationalit\u00e9s<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"30\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c09384c\" data-id=\"c09384c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-951b2e4 elementor-widget elementor-widget-counter\" data-id=\"951b2e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">De femmes<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"56\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adb82bf elementor-widget elementor-widget-counter\" data-id=\"adb82bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">D'hommes<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"44\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-36d2a21\" data-id=\"36d2a21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e96554 elementor-widget elementor-widget-counter\" data-id=\"3e96554\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">de postes de direction occup\u00e9s par des femmes<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"40\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd9d4da elementor-widget elementor-widget-spacer\" data-id=\"dd9d4da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24a47b8 elementor-widget elementor-widget-menu-anchor\" data-id=\"24a47b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"Ethics\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3306859 no_in_this_section elementor-widget elementor-widget-heading\" data-id=\"3306859\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9thique et conformit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-829bc92 elementor-widget elementor-widget-text-editor\" data-id=\"829bc92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Neuraxpharm op\u00e8re dans le strict respect des l\u00e9gislations et des r\u00e9glementations, et nous avons une tol\u00e9rance z\u00e9ro pour les infractions de toute nature li\u00e9es au risque ou \u00e0 l&rsquo;\u00e9thique. Nous promouvons un environnement favorable et juste pour tous, \u00e0 travers la formalisation de nos normes et politiques, et une gouvernance responsable au sein de notre organisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebf60ab elementor-widget elementor-widget-spacer\" data-id=\"ebf60ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35827c0 elementor-widget elementor-widget-heading\" data-id=\"35827c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fili\u00e8re d\u00e9ontologie et conformit\u00e9<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c08eb0e elementor-widget elementor-widget-text-editor\" data-id=\"c08eb0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous pensons que la transparence et la confiance sont essentielles \u00e0 la durabilit\u00e9 et au succ\u00e8s \u00e0 long terme de notre entreprise. Dans cette optique, Neuraxpharm a mis en place un processus de contact s\u00e9curis\u00e9 et confidentiel, le canal d\u00e9ontologie et conformit\u00e9.<\/p><p>Ce canal permet aux employ\u00e9s, aux clients, aux fournisseurs et aux autres partenaires externes de signaler des comportements ill\u00e9gaux tels que des pratiques anticoncurrentielles, des violations des r\u00e9glementations environnementales, des cas de harc\u00e8lement, de corruption et de discrimination, ainsi que des activit\u00e9s douteuses dans leur environnement ou des comportements qui ne sont pas conformes \u00e0 notre code d&rsquo;\u00e9thique.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ad8a99 elementor-widget elementor-widget-button\" data-id=\"3ad8a99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/ethique-et-conformite\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vers le Canal d\u00e9ontologie et conformit\u00e9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a5efec elementor-widget elementor-widget-spacer\" data-id=\"9a5efec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3aedd33 elementor-widget elementor-widget-heading\" data-id=\"3aedd33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Notre code de d\u00e9ontologie <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-757421a elementor-widget elementor-widget-text-editor\" data-id=\"757421a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Neuraxpharm dispose d&rsquo;un Code de d\u00e9ontologie qui fonctionne comme un r\u00e8glement interne d&rsquo;entreprise du plus haut niveau et \u00e9tablit les principes et les valeurs \u00e9thiques, ainsi que les lignes de conduite, qui doivent \u00eatre respect\u00e9s dans toutes les activit\u00e9s auxquelles une soci\u00e9t\u00e9 du groupe participe ou qui affectent une soci\u00e9t\u00e9 du groupe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cda0ac elementor-widget elementor-widget-button\" data-id=\"2cda0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/2025\/04\/29133544\/neuraxpharm-code-of-ethics.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger notre code de d\u00e9ontologie<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cac1a92 elementor-widget elementor-widget-spacer\" data-id=\"cac1a92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-742fa32 elementor-widget elementor-widget-heading\" data-id=\"742fa32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Notre code de d\u00e9ontologie pour les tiers <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c7ae64 elementor-widget elementor-widget-text-editor\" data-id=\"9c7ae64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le Code de d\u00e9ontologie de Neuraxpharm pour les tiers est une extension du code de d\u00e9ontologie de Neuraxpharm. Il a pour but d&rsquo;\u00e9tablir des lignes directrices et des normes \u00e9thiques pour les fournisseurs, les clients, les sous-traitants et les collaborateurs externes, conform\u00e9ment \u00e0 la culture d&rsquo;entreprise et au syst\u00e8me r\u00e9glementaire de Neuraxpharm, ainsi qu&rsquo;aux lois de chacun des pays o\u00f9 Neuraxpharm exerce ses activit\u00e9s, dans le respect des valeurs de leurs cultures respectives.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9fe764 elementor-widget elementor-widget-button\" data-id=\"c9fe764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/2025\/04\/29133557\/neuraxpharm-code-of-ethics-third-parties.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger notre Code de d\u00e9ontologie pour les tiers<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6556489 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6556489\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;692ff0c&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6dcd1f7\" data-id=\"6dcd1f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae0cad4 elementor-widget elementor-widget-spacer\" data-id=\"ae0cad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>TOUT SUR NOTRE RESPONSABILIT\u00c9 \u00c0 propos de la responsabilit\u00e9 Faire avancer une strat\u00e9gie ESG Nos piliers ESG Diversit\u00e9, \u00e9galit\u00e9 et inclusion \u00c9thique et conformit\u00e9 Neuraxpharm En tant qu&rsquo;entreprise de soins de sant\u00e9 sp\u00e9cialis\u00e9e dans le syst\u00e8me nerveux central (SNC), nous avons la responsabilit\u00e9 d&rsquo;am\u00e9liorer la qualit\u00e9 de vie et le bien-\u00eatre mental des personnes atteintes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-2171","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Notre responsabilit\u00e9 ESG - Neuraxpharm France<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment nous assumons notre responsabilit\u00e9 pour am\u00e9liorer le bien-\u00eatre mental et neurologique. Explorez notre engagement pour un avenir durable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notre responsabilit\u00e9\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment nous assumons notre responsabilit\u00e9 pour am\u00e9liorer le bien-\u00eatre mental et neurologique. Explorez notre engagement pour un avenir durable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite\/\" \/>\n<meta property=\"og:site_name\" content=\"Neuraxpharm France\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-28T07:48:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2025\/11\/imgi-7-group-111.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/notre-responsabilite\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/notre-responsabilite\\\/\",\"name\":\"Notre responsabilit\u00e9 ESG - Neuraxpharm France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/notre-responsabilite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/notre-responsabilite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2025\\\/11\\\/imgi-7-group-111.jpg\",\"datePublished\":\"2021-03-02T15:18:45+00:00\",\"dateModified\":\"2026-07-28T07:48:27+00:00\",\"description\":\"D\u00e9couvrez comment nous assumons notre responsabilit\u00e9 pour am\u00e9liorer le bien-\u00eatre mental et neurologique. Explorez notre engagement pour un avenir durable.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/notre-responsabilite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/notre-responsabilite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/static.neuraxpharm.com\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2025\\\/11\\\/20081957\\\/imgi-7-group-111.jpg\",\"contentUrl\":\"https:\\\/\\\/static.neuraxpharm.com\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2025\\\/11\\\/20081957\\\/imgi-7-group-111.jpg\",\"width\":464,\"height\":261,\"caption\":\"Strat\u00e9gie patient centr\u00e9e innovation et engagement social\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/\",\"name\":\"Neuraxpharm France\",\"description\":\"Ein europ\u00e4ischer Marktf\u00fchrer f\u00fcr CNS-Produkte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.neuraxpharm.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Notre responsabilit\u00e9 ESG - Neuraxpharm France","description":"D\u00e9couvrez comment nous assumons notre responsabilit\u00e9 pour am\u00e9liorer le bien-\u00eatre mental et neurologique. Explorez notre engagement pour un avenir durable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite","og_locale":"fr_FR","og_type":"article","og_title":"Notre responsabilit\u00e9","og_description":"D\u00e9couvrez comment nous assumons notre responsabilit\u00e9 pour am\u00e9liorer le bien-\u00eatre mental et neurologique. Explorez notre engagement pour un avenir durable.","og_url":"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite\/","og_site_name":"Neuraxpharm France","article_modified_time":"2026-07-28T07:48:27+00:00","og_image":[{"url":"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2025\/11\/imgi-7-group-111.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite","url":"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite\/","name":"Notre responsabilit\u00e9 ESG - Neuraxpharm France","isPartOf":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite\/#primaryimage"},"image":{"@id":"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.neuraxpharm.com\/fr\/wp-content\/uploads\/sites\/15\/2025\/11\/imgi-7-group-111.jpg","datePublished":"2021-03-02T15:18:45+00:00","dateModified":"2026-07-28T07:48:27+00:00","description":"D\u00e9couvrez comment nous assumons notre responsabilit\u00e9 pour am\u00e9liorer le bien-\u00eatre mental et neurologique. Explorez notre engagement pour un avenir durable.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.neuraxpharm.com\/fr\/notre-responsabilite\/#primaryimage","url":"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081957\/imgi-7-group-111.jpg","contentUrl":"https:\/\/static.neuraxpharm.com\/wp-content\/uploads\/sites\/15\/2025\/11\/20081957\/imgi-7-group-111.jpg","width":464,"height":261,"caption":"Strat\u00e9gie patient centr\u00e9e innovation et engagement social"},{"@type":"WebSite","@id":"https:\/\/www.neuraxpharm.com\/fr\/#website","url":"https:\/\/www.neuraxpharm.com\/fr\/","name":"Neuraxpharm France","description":"Ein europ\u00e4ischer Marktf\u00fchrer f\u00fcr CNS-Produkte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neuraxpharm.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/pages\/2171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/comments?post=2171"}],"version-history":[{"count":5,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/pages\/2171\/revisions"}],"predecessor-version":[{"id":29197,"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/pages\/2171\/revisions\/29197"}],"wp:attachment":[{"href":"https:\/\/www.neuraxpharm.com\/fr\/wp-json\/wp\/v2\/media?parent=2171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}