{"id":3679,"date":"2021-03-11T12:16:33","date_gmt":"2021-03-11T12:16:33","guid":{"rendered":"https:\/\/www.neuraxpharm.com\/v2\/?page_id=3679"},"modified":"2026-04-15T12:35:43","modified_gmt":"2026-04-15T12:35:43","slug":"trastorno-obsesivo-compulsivo-toc","status":"publish","type":"page","link":"https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc","title":{"rendered":"Trastorno Obsesivo Compulsivo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3679\" class=\"elementor elementor-3679\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-060209f elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom banner_top elementor-section-height-default\" data-id=\"060209f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;00936a0&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df365c7\" data-id=\"df365c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9789da9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9789da9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;650699a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0725104 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"0725104\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e025551\" data-id=\"e025551\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3f5ec1 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"c3f5ec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Trastorno Obsesivo Compulsivo<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4d3d95 text_disorders elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4d3d95\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;245babd&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3f35c95 sticky-parent\" data-id=\"3f35c95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c38b907 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c38b907\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;87539ac&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c11e767\" data-id=\"c11e767\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b0879d elementor-widget elementor-widget-table-of-contents\" data-id=\"8b0879d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-right&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;no_headings_message&quot;:&quot;No se ha encontrado ning\\u00fan encabezado en esta p\\u00e1gina.&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tEn esta secci\u00f3n\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__8b0879d\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-60a0257 sticky-column elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60a0257\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;87539ac&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ce8acbe\" data-id=\"ce8acbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55fa575 elementor-widget elementor-widget-spacer\" data-id=\"55fa575\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d862fa elementor-widget elementor-widget-heading\" data-id=\"0d862fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Art\u00edculos relacionados<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c99450 elementor-widget elementor-widget-jet-listing-grid\" data-id=\"5c99450\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;1&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-not-found jet-listing-grid__items\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:3204,&quot;posts_num&quot;:3,&quot;columns&quot;:1,&quot;columns_tablet&quot;:1,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-listing-source=\"posts\" data-listing-id=\"3204\" data-query-id=\"\" data-queried-id=\"3679|WP_Post\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"22110\" class=\"elementor elementor-22110\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ccb2748 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ccb2748\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;5369b3f&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35ebd25c\" data-id=\"35ebd25c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-480f481f elementor-widget elementor-widget-jet-listing-grid\" data-id=\"480f481f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;1&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-notice\">Please select another listing to show to avoid recursion.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><style>.elementor-22110 .elementor-element.elementor-element-7ccb2748 .elementor-repeater-item-5369b3f.jet-parallax-section__layout .jet-parallax-section__image{background-size:auto;}.elementor-22110 .elementor-element.elementor-element-35ebd25c > .elementor-element-populated{text-align:start;}.elementor-22110 .elementor-element.elementor-element-480f481f > .elementor-widget-container > .jet-listing-grid > .jet-listing-grid__items, .elementor-22110 .elementor-element.elementor-element-480f481f > .jet-listing-grid > .jet-listing-grid__items{--columns:1;}:root{--page-title-display:none;}\/* Start custom CSS for jet-listing-grid, class: .elementor-element-480f481f *\/.elementor-page-title {\r\n    display: block;\r\n}\/* End custom CSS *\/\n\/* Start custom CSS for jet-listing-grid, class: .elementor-element-480f481f *\/.elementor-page-title {\r\n    display: block;\r\n}\/* End custom CSS *\/<\/style><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ad3dfd elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ad3dfd\" data-element_type=\"section\" data-e-type=\"section\" id=\"main-navigation\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;87539ac&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8aeef25\" data-id=\"8aeef25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a676f3 elementor-widget elementor-widget-table-of-contents\" data-id=\"1a676f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-right&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;no_headings_message&quot;:&quot;No se ha encontrado ning\\u00fan encabezado en esta p\\u00e1gina.&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tEn esta secci\u00f3n\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__1a676f3\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a1bbc9b elementor-hidden-tablet elementor-hidden-phone\" data-id=\"a1bbc9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-18c77c0 page-health\" data-id=\"18c77c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93b4c45 elementor-widget elementor-widget-spacer\" data-id=\"93b4c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3feddb6 elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"3feddb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/www.neuraxpharm.com\/es\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Neuraxpharm\">Neuraxpharm <\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90283e7 elementor-widget elementor-widget-text-editor\" data-id=\"90283e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Trastorno Obsesivo Compulsivo (TOC) es un trastorno de salud mental frecuente y de larga duraci\u00f3n que provoca pensamientos obsesivos y comportamientos compulsivos.<\/p><p>En Neuraxpharm desarrollamos alternativas farmacol\u00f3gicas para el trastorno obsesivo compulsivo. Una vez que tu m\u00e9dico haya determinado tus necesidades espec\u00edficas, podr\u00e1 recetarte el producto que mejor se adapte a tus necesidades y a tu estado.<\/p><p>Conoce mejor los s\u00edntomas, el tratamiento y la gesti\u00f3n de esta enfermedad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c27b39 no_in_this_section elementor-widget elementor-widget-heading\" data-id=\"7c27b39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es el TOC?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9695e39 elementor-widget elementor-widget-text-editor\" data-id=\"9695e39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El TOC es una enfermedad mental que puede afectar tanto a los pensamientos como al comportamiento. Aunque puede desarrollarse en la infancia, suele aparecer en los primeros a\u00f1os de la edad adulta.<\/p><p>Las personas con TOC experimentan pensamientos, im\u00e1genes o impulsos obsesivos e indeseados. A menudo afrontan o neutralizan estos pensamientos con comportamientos compulsivos y repetitivos. Esto puede conducir a un ciclo de pensamientos y comportamientos repetidos, incontrolados y no deseados que pueden tener un impacto significativo en su vida diaria. Por ejemplo, una persona con un miedo obsesivo a los ladrones puede comprobar repetida y excesivamente las cerraduras de puertas y ventanas.<\/p><p>Muchas personas sienten en alg\u00fan momento pensamientos angustiosos e indeseados similares y la necesidad de realizar comportamientos repetitivos, pero esto puede durar poco tiempo y no significa que tengan un TOC. En el TOC, los pensamientos angustiosos y los comportamientos repetitivos son persistentes. Las personas con TOC seguir\u00e1n luchando con sus pensamientos obsesivos, incluso si saben que las ideas que reflejan no est\u00e1n basadas en la realidad.<\/p><p>Los comportamientos compulsivos que los individuos utilizan en respuesta a sus pensamientos obsesivos pueden aliviar temporalmente la ansiedad, pero la obsesi\u00f3n y la ansiedad vuelven pronto, haciendo que el ciclo comience de nuevo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e5b93b elementor-widget elementor-widget-heading\" data-id=\"6e5b93b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les son los principales tipos de TOC?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb23c9f elementor-widget elementor-widget-text-editor\" data-id=\"fb23c9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El TOC es una enfermedad \u00fanica, pero las personas pueden experimentarlo de diferentes maneras. La mayor\u00eda de las personas con TOC tienden a sentir tanto pensamientos obsesivos como compulsiones, pero es posible que solo experimenten uno de estos s\u00edntomas. Adem\u00e1s, los tipos de pensamientos obsesivos y comportamientos compulsivos variar\u00e1n entre los individuos; por ejemplo, algunas personas pueden centrarse en la limpieza mientras que otras pueden desarrollar el acaparamiento de cosas como s\u00edntoma.<\/p><p>Algunos expertos creen que el TOC que comienza en la infancia es diferente del que se desarrolla en los adultos. Un estudio en el que se analizaron parejas de gemelos demostr\u00f3 que los genes desempe\u00f1an un papel m\u00e1s importante en el TOC que se inicia en la infancia que en el TOC cuyos s\u00edntomas comienzan en la edad adulta..<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef9b9bc elementor-widget elementor-widget-heading\" data-id=\"ef9b9bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1ntas personas tienen TOC?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c90f4e elementor-widget elementor-widget-text-editor\" data-id=\"1c90f4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un estudio sobre la prevalencia del TOC en personas a partir de 20 a\u00f1os en 17 grandes pa\u00edses europeos estim\u00f3 que hab\u00eda 6,4 millones de casos en 2019, y pronostic\u00f3 que la prevalencia en 12 meses en 2029 oscilar\u00eda entre 16 por 1000 en Italia y 17 por 1000 en Noruega.<\/p><p>Las tasas mundiales de TOC se han estimado en un 1,5\u00a0% para las mujeres y un 1\u00a0% para los hombres. Los hombres se ven m\u00e1s afectados en la infancia, aunque las mujeres tienen una prevalencia ligeramente mayor en la edad adulta,. Esta enfermedad afecta a personas de todos los g\u00e9neros, etnias y niveles socioecon\u00f3micos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0c5f42 elementor-widget elementor-widget-heading\" data-id=\"e0c5f42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S\u00edntomas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf2b926 elementor-widget elementor-widget-text-editor\" data-id=\"cf2b926\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las personas con TOC pueden tener s\u00edntomas de obsesiones, compulsiones o ambos. Los s\u00edntomas pueden tener un impacto negativo en todos los aspectos de su vida, como el trabajo, el colegio, la universidad y las relaciones personales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-709d087 elementor-widget elementor-widget-heading\" data-id=\"709d087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les son los s\u00edntomas del TOC?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30229f9 lista_1 elementor-widget elementor-widget-text-editor\" data-id=\"30229f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El TOC puede hacer que las personas experimenten pensamientos repetidos no deseados y angustiosos, conocidos como obsesiones. Tambi\u00e9n pueden sentir el impulso de realizar ciertos comportamientos repetitivos para responder a esos pensamientos y neutralizarlos; esto se conoce como compulsiones. Los s\u00edntomas m\u00e1s comunes son:<\/p><h4>Obsesiones<\/h4><ul><li>Miedo a los g\u00e9rmenes o a contaminarse de alguna manera por otras personas o por el entorno<\/li><li>Pensamientos intrusivos recurrentes<\/li><li>Pensamientos indeseados y perturbadores relacionados con el sexo o la violencia<\/li><li>Miedo a autolesionarse o a da\u00f1ar a otros, ya sea a prop\u00f3sito o por accidente<\/li><li>Necesidad de simetr\u00eda, precisi\u00f3n y orden<\/li><li>Miedo a soltar obscenidades<\/li><li>Miedo a perder algo importante<\/li><\/ul><p>Aunque algunos pensamientos obsesivos pueden ser aterradores para las personas con TOC, tener estos pensamientos no significa en absoluto que se hagan realidad.<\/p><h4>Compulsiones<\/h4><ul><li>Limpieza excesiva, por ejemplo, en el hogar<\/li><li>Higiene personal excesiva &#8211; por ejemplo, lavarse las manos o ducharse repetidamente<\/li><li>Comprobaci\u00f3n repetida de cerraduras e interruptores<\/li><li>Ordenar y disponer los art\u00edculos de forma precisa<\/li><li>Necesidad de seguir contando hasta el mismo n\u00famero<\/li><li>Acaparamiento de cosas<\/li><li>Pedir con frecuencia que le den seguridad o la aprobaci\u00f3n de otra persona<\/li><\/ul><p>No todas las compulsiones tienen un v\u00ednculo obvio o l\u00f3gico con el pensamiento obsesivo que se utiliza para neutralizar; sin embargo, la realizaci\u00f3n de la conducta puede proporcionar al individuo cierto alivio de ese pensamiento.<\/p><p>Algunos individuos con TOC pueden tener tambi\u00e9n un trastorno de tics. Pueden ser movimientos repetitivos y repentinos, como parpadear, hacer muecas o sacudir la cabeza o los hombros, o vocalizaciones como carraspeos, olfateos o gru\u00f1idos repetitivos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bc1124 elementor-widget elementor-widget-heading\" data-id=\"9bc1124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les son las fases del TOC?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-825b86d elementor-widget elementor-widget-text-editor\" data-id=\"825b86d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los s\u00edntomas del TOC pueden aparecer y desaparecer y pueden reducirse o empeorar con el tiempo. Los tratamientos ayudar\u00e1n a la mayor\u00eda de las personas que padecen la enfermedad a controlar sus s\u00edntomas y a reducir el impacto en su vida cotidiana.<\/p><p>Los padres o los profesores suelen reconocer los s\u00edntomas del TOC en los ni\u00f1os, mientras que muchos adultos buscan apoyo cuando se dan cuenta de que sus pensamientos y comportamientos obsesivos no se basan en la realidad y est\u00e1n afectando a su calidad de vida.<\/p><p>En los casos m\u00e1s graves, la repetici\u00f3n constante de rituales puede durar todo el d\u00eda, haciendo imposible una rutina normal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8107c0a elementor-widget elementor-widget-heading\" data-id=\"8107c0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les son los primeros signos del TOC?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a89dac3 elementor-widget elementor-widget-text-editor\" data-id=\"a89dac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las personas con TOC suelen mostrar primero s\u00edntomas leves de obsesiones y compulsiones, que pueden empeorar con el tiempo. Los primeros signos pueden incluir comportamientos repetitivos y hacer las cosas de una misma manera siempre, problemas en las relaciones y acaparamiento de cosas.<\/p><p>A menudo, los padres o los profesores son los primeros en notar los primeros signos en los ni\u00f1os, que son similares a los de los adultos y pueden incluir la obsesi\u00f3n por los g\u00e9rmenes, la b\u00fasqueda de seguridad o la comprobaci\u00f3n constante de las cosas, y la preocupaci\u00f3n de que pueda ocurrir algo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41a878b elementor-widget elementor-widget-heading\" data-id=\"41a878b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Causas, factores de riesgo y esperanza de vida<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2db641a elementor-widget elementor-widget-text-editor\" data-id=\"2db641a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se desconocen las causas exactas del TOC; sin embargo, se cree que los factores de riesgo incluyen la gen\u00e9tica, la composici\u00f3n del cerebro y el entorno en general.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-626958f elementor-widget elementor-widget-heading\" data-id=\"626958f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 causa el TOC?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6c3e07 elementor-widget elementor-widget-text-editor\" data-id=\"f6c3e07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Existen varias causas posibles del TOC. Las personas pueden desarrollarlo como resultado de sus genes; las personas que tienen padres o hermanos con TOC tienen un mayor riesgo de desarrollarlo ellos mismos.<\/p><p>Tambi\u00e9n podr\u00eda haber una conexi\u00f3n entre los s\u00edntomas del TOC y las anormalidades en determinadas \u00e1reas del cerebro, pero esa conexi\u00f3n no est\u00e1 clara, y la investigaci\u00f3n contin\u00faa. Algunas personas con TOC tienen \u00e1reas de actividad inusualmente alta en su cerebro, o niveles bajos de la sustancia qu\u00edmica serotonina.<\/p><p>El TOC puede ser m\u00e1s com\u00fan en personas que han sufrido acoso, abusos o negligencia, y puede ser desencadenado por un acontecimiento vital importante, como ser padre o sufrir un duelo. Tambi\u00e9n puede ser m\u00e1s probable que se desarrolle en personas muy met\u00f3dicas con altos niveles de exigencia personal, o en aquellas que son generalmente ansiosas y que tienen un sentido muy fuerte de responsabilidad por s\u00ed mismas y por los dem\u00e1s.<\/p><p>En algunos casos, los ni\u00f1os pueden desarrollar s\u00edntomas de TOC tras una infecci\u00f3n por bacterias estreptoc\u00f3cicas, lo que se conoce como \u00abtrastorno neuropsiqui\u00e1trico pedi\u00e1trico autoinmune asociado a infecciones estreptoc\u00f3cicas\u00bb (PANDAS por sus siglas en ingl\u00e9s). El PANDAS se produce de forma muy repentina, con s\u00edntomas que aparecen aparentemente de la noche a la ma\u00f1ana, y tiene un impacto muy grave en la vida del ni\u00f1o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c86986 elementor-position-inline-start icon_mini_box elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6c86986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u00bfEs el TOC hereditario?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEs probable que los genes desempe\u00f1en un papel en el desarrollo del TOC, lo que significa que es hereditario. Sin embargo, las causas del TOC no est\u00e1n claras, y otros factores, como las experiencias vitales, tambi\u00e9n pueden estar implicados.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71efd06 elementor-widget elementor-widget-heading\" data-id=\"71efd06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQui\u00e9n padece TOC?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d8a3d0 elementor-widget elementor-widget-text-editor\" data-id=\"9d8a3d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El TOC puede afectar a hombres, mujeres y ni\u00f1os. Algunas personas empiezan a tener s\u00edntomas a una edad temprana -a menudo en torno a la pubertad-, pero la enfermedad suele comenzar durante los primeros a\u00f1os de la vida adulta.<\/p><p>A veces, las mujeres pueden desarrollar el TOC durante el embarazo o despu\u00e9s del nacimiento del beb\u00e9. En este caso, las obsesiones suelen estar relacionadas con la preocupaci\u00f3n por da\u00f1ar al beb\u00e9, con compulsiones como comprobar repetidamente que el beb\u00e9 respira.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b29ae2b elementor-widget elementor-widget-heading\" data-id=\"b29ae2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1nto tiempo se puede vivir con TOC?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f19e25b elementor-widget elementor-widget-text-editor\" data-id=\"f19e25b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El TOC no es una amenaza para la vida. Su impacto puede variar con el tiempo, ya que la gravedad de los s\u00edntomas var\u00eda. Los pensamientos obsesivos y los comportamientos compulsivos pueden reducirse o aumentar de forma natural en diferentes momentos. Los tratamientos y los mecanismos de afrontamiento pueden ayudar a las personas afectadas por TOC a controlar los efectos de los s\u00edntomas y mejorar la calidad de vida en general a largo plazo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8d1d9d elementor-widget elementor-widget-heading\" data-id=\"a8d1d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diagn\u00f3stico\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e3780c elementor-widget elementor-widget-text-editor\" data-id=\"3e3780c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La mayor\u00eda de las personas son diagnosticadas alrededor de los 19 a\u00f1os, y la aparici\u00f3n de los s\u00edntomas suele ser m\u00e1s temprana en los chicos que en las chicas. Sin embargo, tambi\u00e9n puede aparecer despu\u00e9s de los 35 a\u00f1os.5<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b344d44 elementor-widget elementor-widget-heading\" data-id=\"b344d44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo se diagnostica el TOC?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df939aa lista_1 elementor-widget elementor-widget-text-editor\" data-id=\"df939aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El TOC debe ser diagnosticado por un profesional de la salud mental con experiencia. Por lo general, hablar\u00e1 con el paciente sobre sus obsesiones y compulsiones, la frecuencia con la que se producen y el impacto que est\u00e1n teniendo en las actividades cotidianas de esa persona y en su calidad y disfrute de la vida en general.<\/p><p>En general, para el diagn\u00f3stico, los s\u00edntomas deben estar presentes durante una hora o m\u00e1s cada d\u00eda y deben tener un impacto duradero en la vida y las actividades del paciente.<\/p><p>Se pueden utilizar escalas de evaluaci\u00f3n para medir la gravedad del TOC. La Escala Obsesiva Compulsiva Global del Instituto Nacional de Salud Mental de los Estados Unidos (NIMH-GOCS por sus siglas en ingl\u00e9s) puede utilizarse para evaluar la gravedad general del TOC en una escala de 1 (s\u00edntomas m\u00ednimos) a 15 (muy grave), mientras que la escala obsesiva compulsiva de Yale-Brown se utiliza para medir la gravedad de los s\u00edntomas del TOC, sin que influya el tipo de obsesiones o compulsiones presentes. Los m\u00e9dicos utilizan esta escala para calificar los s\u00edntomas desde inexistentes hasta extremos, con subtotales separados para la gravedad de las obsesiones y compulsiones.<\/p><p>Los profesionales de la salud tambi\u00e9n tendr\u00e1n que descartar cualquier otra posible enfermedad de salud mental que pueda estar causando los s\u00edntomas, y considerar cualquier otra enfermedad que el paciente pueda tener (por ejemplo, depresi\u00f3n, ansiedad o un trastorno alimentario) para que se ofrezca el tratamiento adecuado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f877e6 elementor-widget elementor-widget-heading\" data-id=\"0f877e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prueba para diagnosticar el TOC\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c1ae2a elementor-widget elementor-widget-text-editor\" data-id=\"1c1ae2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>No existen pruebas f\u00edsicas que puedan utilizarse para diagnosticar el TOC. Se diagnostica a trav\u00e9s de consultas con un profesional de la salud mental con experiencia que puede evaluar los pensamientos y comportamientos del paciente y su impacto en la vida diaria.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0b92d8 elementor-widget elementor-widget-heading\" data-id=\"d0b92d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tratamiento y medicaci\u00f3n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17aa45b elementor-widget elementor-widget-text-editor\" data-id=\"17aa45b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El TOC puede ser angustioso para la persona afectada y sus allegados; sin embargo, el tratamiento puede ayudar a controlar los s\u00edntomas. Esto puede mejorar la vida cotidiana y ayudar a los afectados a disfrutar de sus relaciones y de un mejor tiempo social y de ocio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbf6b87 elementor-widget elementor-widget-heading\" data-id=\"fbf6b87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo se trata el TOC?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5d2b43 elementor-widget elementor-widget-text-editor\" data-id=\"f5d2b43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El TOC suele tratarse con terapia psicol\u00f3gica, medicaci\u00f3n o una combinaci\u00f3n de ambas. Aunque la mayor\u00eda de los pacientes con TOC responden al tratamiento, algunos seguir\u00e1n teniendo s\u00edntomas.<\/p><p>A veces, las personas con TOC tambi\u00e9n padecen otros trastornos mentales, como ansiedad, depresi\u00f3n o trastorno dism\u00f3rfico corporal. Hay que tenerlos en cuenta a la hora de discutir los posibles tratamientos.<\/p><p>Para el TOC relativamente leve, normalmente se recomienda una terapia corta. Las personas con s\u00edntomas moderados pueden necesitar una terapia de mayor duraci\u00f3n y posiblemente medicaci\u00f3n, y la mayor\u00eda responder\u00e1 al tratamiento. Las personas con un TOC m\u00e1s grave suelen recibir tanto terapia como medicaci\u00f3n, y algunas pueden ser derivadas a un especialista en salud mental.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4827d7c elementor-position-inline-start icon_mini_box elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4827d7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMedicaci\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLa medicaci\u00f3n utilizada para tratar el TOC suele ser en forma de medicamentos antidepresivos conocidos como inhibidores selectivos de la recaptaci\u00f3n de serotonina (ISRS). Estos pueden ayudar a reducir los s\u00edntomas al alterar el equilibrio de las sustancias qu\u00edmicas en el cerebro.<br><br>\nEn algunos pacientes, el tratamiento puede tardar varias semanas en surtir efecto, pero en otras personas los efectos se notan mucho m\u00e1s r\u00e1pidamente.<br><br>\nLas personas que toman un ISRS solo deben dejar de hacerlo con el apoyo de su m\u00e9dico, ya que algunas personas pueden sentir efectos secundarios si lo dejan repentinamente.<br><br>\nExisten varios ISRS diferentes, y las personas que no responden a un medicamento pueden responder a otro. El m\u00e9dico ayudar\u00e1 a encontrar la medicaci\u00f3n adecuada para cada persona.\nAlgunas personas pueden considerar que los ISRS no son eficaces en absoluto, en cuyo caso pueden recetarse en su lugar antidepresivos tric\u00edclicos (ATC) espec\u00edficos, que tambi\u00e9n inhiben la recaptaci\u00f3n de serotonina.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd6300 elementor-position-inline-start icon_mini_box elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7fd6300\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTerapia e intervenci\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLa terapia para el TOC suele consistir en un tipo de terapia cognitivo conductual (TCC) que incluye la exposici\u00f3n y la prevenci\u00f3n de la respuesta (EPR). <br><br>\nEsto implica que el terapeuta trabaje con el paciente para identificar los diferentes elementos de sus s\u00edntomas: sus pensamientos, sentimientos y comportamientos.<br><br>\nDurante las sesiones, se anima al paciente a enfrentarse a sus miedos y pensamientos obsesivos sin seguir sus conductas compulsivas neutralizadoras habituales. Esto se conoce como prevenci\u00f3n de la respuesta. Ayuda al paciente a enfrentarse a sus pensamientos y obsesiones de manera que se reduzca la ansiedad que siente en respuesta a ellos, y aprende que sus miedos no est\u00e1n arraigados en la realidad.<br><br>\nEl terapeuta trabajar\u00e1 con los pacientes a lo largo del tiempo, empezando por las obsesiones que causan menos ansiedad y trabajando hasta las que causan m\u00e1s angustia.<br><br>\nTambi\u00e9n puede haber t\u00e9cnicas de neuromodulaci\u00f3n, en las que se utiliza un est\u00edmulo qu\u00edmico o el\u00e9ctrico para alterar la actividad nerviosa. Estas t\u00e9cnicas incluyen: la estimulaci\u00f3n transcraneal de corriente directa (ETCD), en la que se aplica una d\u00e9bil corriente el\u00e9ctrica al cuero cabelludo; la estimulaci\u00f3n magn\u00e9tica transcraneal repetitiva (EMTR), una t\u00e9cnica no invasiva que utiliza corrientes el\u00e9ctricas para modular la actividad neuronal; y la estimulaci\u00f3n cerebral profunda (ECP), que consiste en implantar quir\u00fargicamente un electrodo para activar los circuitos neuronales. Hasta ahora, las t\u00e9cnicas de neuromodulaci\u00f3n se han utilizado para el TOC principalmente en el campo de la investigaci\u00f3n, pero la EMTR ha sido aprobada en los Estados Unidos.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-845006c elementor-position-inline-start icon_mini_box elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"845006c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDieta\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLas personas con TOC deben seguir una dieta normal, sana y equilibrada, y asegurarse de que comen con regularidad para que sus niveles de az\u00facar en sangre no bajen, ya que esto puede provocar un estado de \u00e1nimo bajo. Los alimentos saludables que hay que incluir en la dieta son los frutos secos y las semillas, las prote\u00ednas como los huevos, las jud\u00edas y la carne, y los hidratos de carbono complejos como los cereales integrales, las verduras y la fruta. La cafe\u00edna debe ser limitada.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75f3403 elementor-position-inline-start icon_mini_box elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"75f3403\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEjercicio\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMantener un estilo de vida saludable puede ayudar a las personas que viven con TOC. El ejercicio es beneficioso para la salud f\u00edsica y mental en general, y a menudo se recomienda como uno de los principales tratamientos para la depresi\u00f3n leve. El ejercicio regular ayuda a aumentar la autoestima y a promover un estado de \u00e1nimo positivo.<br><br>\nEl ejercicio no tiene por qu\u00e9 formar parte de una actividad organizada; puede ser algo tan sencillo como mantenerse regularmente activo dando un paseo a la hora de comer o despu\u00e9s del trabajo, o jugando al f\u00fatbol en el parque.<br><br>\nLa ansiedad causada por el TOC tambi\u00e9n puede reducirse mediante t\u00e9cnicas de relajaci\u00f3n como la meditaci\u00f3n, el yoga y los masajes.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc8e58f elementor-widget elementor-widget-heading\" data-id=\"cc8e58f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prevenci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba5a24a elementor-widget elementor-widget-text-editor\" data-id=\"ba5a24a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aunque el TOC no puede prevenirse, sus s\u00edntomas pueden reducirse mediante terapia y medicaci\u00f3n. La identificaci\u00f3n y el tratamiento tempranos tambi\u00e9n pueden evitar que el TOC leve se convierta en una forma m\u00e1s grave.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe8b5d9 elementor-widget elementor-widget-heading\" data-id=\"fe8b5d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Estudios cient\u00edficos\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c864e64 elementor-widget elementor-widget-text-editor\" data-id=\"c864e64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se est\u00e1 investigando la eficacia de las intervenciones farmacol\u00f3gicas en el TOC. Una revisi\u00f3n de 2019 de la investigaci\u00f3n sobre el tratamiento farmacol\u00f3gico descubri\u00f3 que la administraci\u00f3n prolongada de ISRS es la m\u00e1s eficaz y que la combinaci\u00f3n del tratamiento con la terapia cognitivo conductual (TCC) o la exposici\u00f3n y prevenci\u00f3n de la respuesta (EPR) da los mejores resultados.<\/p><p>Se est\u00e1n realizando otros estudios sobre medicamentos y otros enfoques terap\u00e9uticos nuevos que podr\u00edan utilizarse para los pacientes que no responden a los ISRS, incluidos los tratamientos combinados y complementarios y la estimulaci\u00f3n cerebral profunda..<\/p><p>Algunos estudios muestran que un tipo de cirug\u00eda conocida como capsulotom\u00eda anterior tambi\u00e9n puede ser eficaz,.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e67e3fd elementor-widget elementor-widget-heading\" data-id=\"e67e3fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fuentes de referencia\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b8ebe8 lista elementor-widget elementor-widget-text-editor\" data-id=\"6b8ebe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>\u00a0Inouye E. Similar and dissimilar manifestations of obsessive-compulsive neuroses in monozygotic twins. Am J Psychiatry. 1965;121:1171-1175. doi:10.1176\/ajp.121.12.1171<\/li><li>\u00a0Khan MK, Dupuy AV. Estimating the prevalence of obsessive compulsive disorder in Europe over the next ten years. Poster presented at: World Congress of Psychiatry; August 21-24, 2019; Lisbon, Portugal. doi:10.26226\/morressier.5d1a038557558b317a140ebd<\/li><li>\u00a0Weissman MM, Bland RC, Canino GJ, et al. The cross national epidemiology of obsessive compulsive disorder. The Cross National Collaborative Group.\u00a0J Clin Psychiatry. 1994;55 Suppl:5-10.<\/li><li>Kessler RC, Chiu WT, Demler O, Merikangas KR, Walters EE. Prevalence, severity, and comorbidity of 12-month DSM-IV disorders in the National Comorbidity Survey Replication (published correction appears in <i>Arch Gen Psychiatry<\/i>. 2005 Jul;62(7):709. Merikangas, Kathleen R [added]). <i>Arch Gen Psychiatry<\/i>. 2005;62(6):617-627. doi:10.1001\/archpsyc.62.6.617<\/li><li>\u00a0Goodman WK, Price LH, Rasmussen SA, et al. The Yale-Brown Obsessive Compulsive Scale. I. Development, use, and reliability. <i>Arch Gen Psychiatry<\/i>. 1989;46(11):1006-1011. doi:10.1001\/archpsyc.1989.01810110048007<\/li><li>\u00a0Stein DJ, Costa DLC, Lochner C, et al. Obsessive-compulsive disorder.\u00a0<i>Nat Rev Dis Primers<\/i>. 2019;5(1):52. doi:10.1038\/s41572-019-0102-3<\/li><li>Del Casale A, Sorice S, Padovano A, et al. Psychopharmacological treatment of obsessive-compulsive disorder (OCD). <i>Curr Neuropharmacol<\/i>. 2019;17(8):710-736. doi:10.2174\/1570159X16666180813155017<\/li><li>\u00a0Doshi PK. Anterior capsulotomy for refractory OCD: First case as per the core group guidelines.\u00a0<i>Indian J Psychiatry<\/i>. 2011;53(3):270-273. doi:10.4103\/0019-5545.86823<\/li><li>\u00a0Pepper J, Zrinzo L, Marwan H. Anterior capsulotomy for obsessive-compulsive disorder: a review of old and new literature. <i>Journal of Neurosurgery.<\/i> 2019;133:1-10. 10.3171\/2019.4.JNS19275<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c55bb2f elementor-widget elementor-widget-spacer\" data-id=\"c55bb2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6166b89 stop-sticky elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6166b89\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;efcf18a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-29241b4\" data-id=\"29241b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7098f8 elementor-widget elementor-widget-heading\" data-id=\"e7098f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Te podr\u00eda interesar...<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0cc8899\" data-id=\"0cc8899\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01d1da0 elementor-icon-list--layout-inline elementor-align-end read_more_reverse elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"01d1da0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.neuraxpharm.com\/es\/blog\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ir al Blog<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fe4344 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fe4344\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;426e004&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf0f07c\" data-id=\"cf0f07c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75135bf blog-category elementor-widget elementor-widget-jet-listing-grid\" data-id=\"75135bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-not-found jet-listing-grid__items\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:3578,&quot;posts_num&quot;:3,&quot;columns&quot;:3,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-listing-source=\"posts\" data-listing-id=\"3578\" data-query-id=\"\" data-queried-id=\"3679|WP_Post\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"22107\" class=\"elementor elementor-22107\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4dcd24fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4dcd24fa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;5757181&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fe0112c\" data-id=\"3fe0112c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-444f3187 blog-category elementor-widget elementor-widget-jet-listing-grid\" data-id=\"444f3187\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-notice\">Please select another listing to show to avoid recursion.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><style>.elementor-22107 .elementor-element.elementor-element-4dcd24fa .elementor-repeater-item-5757181.jet-parallax-section__layout .jet-parallax-section__image{background-size:auto;}.elementor-22107 .elementor-element.elementor-element-444f3187 > .elementor-widget-container > .jet-listing-grid > .jet-listing-grid__items, .elementor-22107 .elementor-element.elementor-element-444f3187 > .jet-listing-grid > .jet-listing-grid__items{--columns:3;}.elementor-22107 .elementor-element.elementor-element-4dcd24fa > .elementor-container{text-align:start;}:root{--page-title-display:none;}@media(max-width:1024px){.elementor-22107 .elementor-element.elementor-element-444f3187 > .elementor-widget-container > .jet-listing-grid > .jet-listing-grid__items, .elementor-22107 .elementor-element.elementor-element-444f3187 > .jet-listing-grid > .jet-listing-grid__items{--columns:2;}}@media(max-width:767px){.elementor-22107 .elementor-element.elementor-element-444f3187 > .elementor-widget-container > .jet-listing-grid > .jet-listing-grid__items, .elementor-22107 .elementor-element.elementor-element-444f3187 > .jet-listing-grid > .jet-listing-grid__items{--columns:1;}}<\/style><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-196ac74 elementor-widget elementor-widget-spacer\" data-id=\"196ac74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En esta secci\u00f3n Art\u00edculos relacionados .elementor-22110 .elementor-element.elementor-element-35ebd25c &gt; .elementor-element-populated{text-align:left;}:root{&#8211;page-title-display:none;}\/* Start custom CSS for jet-listing-grid, class: .elementor-element-480f481f *\/.elementor-page-title { display: block; }\/* End custom CSS *\/ \/* Start custom CSS for jet-listing-grid, class: .elementor-element-480f481f *\/.elementor-page-title { display: block; }\/* End custom CSS *\/ .elementor-3204 .elementor-element.elementor-element-fed7de8 .elementor-heading-title{color:var( &#8211;e-global-color-secondary );}.elementor-3204 .elementor-element.elementor-element-22b9e32 .elementor-heading-title{color:var( &#8211;e-global-color-primary );font-size:21px;font-weight:500;line-height:31px;}.elementor-3204 .elementor-element.elementor-element-22b9e32 &gt; .elementor-widget-container{margin:-15px 0px [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":573,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3679","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TOC - Trastorno Obsesivo-Compulsivo: S\u00edntomas y tratamiento<\/title>\n<meta name=\"description\" content=\"Reconoce obsesiones y compulsiones, comprende las causas y explora tratamientos efectivos. Informaci\u00f3n cl\u00ednica de Neuraxpharm.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trastorno Obsesivo Compulsivo\" \/>\n<meta property=\"og:description\" content=\"Reconoce obsesiones y compulsiones, comprende las causas y explora tratamientos efectivos. Informaci\u00f3n cl\u00ednica de Neuraxpharm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc\" \/>\n<meta property=\"og:site_name\" content=\"Neuraxpharm Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T12:35:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.neuraxpharm.com\/es\/wp-content\/uploads\/sites\/8\/2021\/04\/neuraxpharm-your-cns-specialist.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1779\" \/>\n\t<meta property=\"og:image:height\" content=\"995\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/enfermedades\\\/trastorno-obsesivo-compulsivo-toc\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/enfermedades\\\/trastorno-obsesivo-compulsivo-toc\",\"name\":\"TOC - Trastorno Obsesivo-Compulsivo: S\u00edntomas y tratamiento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/#website\"},\"datePublished\":\"2021-03-11T12:16:33+00:00\",\"dateModified\":\"2026-04-15T12:35:43+00:00\",\"description\":\"Reconoce obsesiones y compulsiones, comprende las causas y explora tratamientos efectivos. Informaci\u00f3n cl\u00ednica de Neuraxpharm.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/enfermedades\\\/trastorno-obsesivo-compulsivo-toc#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/enfermedades\\\/trastorno-obsesivo-compulsivo-toc\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/enfermedades\\\/trastorno-obsesivo-compulsivo-toc#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Enfermedades psiqui\u00e1tricas y neurol\u00f3gicas\",\"item\":\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/enfermedades\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trastorno Obsesivo Compulsivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/\",\"name\":\"Neuraxpharm Espa\u00f1a\",\"description\":\"A European Leader for the CNS products\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.neuraxpharm.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TOC - Trastorno Obsesivo-Compulsivo: S\u00edntomas y tratamiento","description":"Reconoce obsesiones y compulsiones, comprende las causas y explora tratamientos efectivos. Informaci\u00f3n cl\u00ednica de Neuraxpharm.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc","og_locale":"es_ES","og_type":"article","og_title":"Trastorno Obsesivo Compulsivo","og_description":"Reconoce obsesiones y compulsiones, comprende las causas y explora tratamientos efectivos. Informaci\u00f3n cl\u00ednica de Neuraxpharm.","og_url":"https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc","og_site_name":"Neuraxpharm Espa\u00f1a","article_modified_time":"2026-04-15T12:35:43+00:00","og_image":[{"width":1779,"height":995,"url":"https:\/\/www.neuraxpharm.com\/es\/wp-content\/uploads\/sites\/8\/2021\/04\/neuraxpharm-your-cns-specialist.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc","url":"https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc","name":"TOC - Trastorno Obsesivo-Compulsivo: S\u00edntomas y tratamiento","isPartOf":{"@id":"https:\/\/www.neuraxpharm.com\/es\/#website"},"datePublished":"2021-03-11T12:16:33+00:00","dateModified":"2026-04-15T12:35:43+00:00","description":"Reconoce obsesiones y compulsiones, comprende las causas y explora tratamientos efectivos. Informaci\u00f3n cl\u00ednica de Neuraxpharm.","breadcrumb":{"@id":"https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.neuraxpharm.com\/es\/enfermedades\/trastorno-obsesivo-compulsivo-toc#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Enfermedades psiqui\u00e1tricas y neurol\u00f3gicas","item":"https:\/\/www.neuraxpharm.com\/es\/enfermedades"},{"@type":"ListItem","position":2,"name":"Trastorno Obsesivo Compulsivo"}]},{"@type":"WebSite","@id":"https:\/\/www.neuraxpharm.com\/es\/#website","url":"https:\/\/www.neuraxpharm.com\/es\/","name":"Neuraxpharm Espa\u00f1a","description":"A European Leader for the CNS products","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neuraxpharm.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.neuraxpharm.com\/es\/wp-json\/wp\/v2\/pages\/3679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neuraxpharm.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.neuraxpharm.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/es\/wp-json\/wp\/v2\/comments?post=3679"}],"version-history":[{"count":138,"href":"https:\/\/www.neuraxpharm.com\/es\/wp-json\/wp\/v2\/pages\/3679\/revisions"}],"predecessor-version":[{"id":33446,"href":"https:\/\/www.neuraxpharm.com\/es\/wp-json\/wp\/v2\/pages\/3679\/revisions\/33446"}],"up":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/es\/wp-json\/wp\/v2\/pages\/573"}],"wp:attachment":[{"href":"https:\/\/www.neuraxpharm.com\/es\/wp-json\/wp\/v2\/media?parent=3679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}