{"id":488,"date":"2021-02-04T08:29:11","date_gmt":"2021-02-04T08:29:11","guid":{"rendered":"https:\/\/www.neuraxpharm.com\/it2\/?p=488"},"modified":"2022-08-10T12:47:01","modified_gmt":"2022-08-10T12:47:01","slug":"prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer","status":"publish","type":"post","link":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer","title":{"rendered":"Prendre soin des aidants : les aidants de personnes atteintes de la maladie d&rsquo;Alzheimer"},"content":{"rendered":"<p>La maladie d&rsquo;Alzheimer est une affection c\u00e9r\u00e9brale progressive et irr\u00e9versible qui constitue la cause la plus fr\u00e9quente de d\u00e9mence. Elle affecte la m\u00e9moire et les capacit\u00e9s cognitives, provoquant d\u00e9tresse et souffrance chez les personnes concern\u00e9es, souvent au d\u00e9triment de leurs familles et leurs aidants.<\/p>\n<p>Plus de 50 millions de personnes dans le monde sont atteintes de d\u00e9mence et ce chiffre devrait atteindre 152 millions d&rsquo;ici 2050<sup>1<\/sup><\/p>\n<p>La maladie d&rsquo;Alzheimer et les autres causes de d\u00e9mence sont des affections destructrices car elles r\u00e9duisent les capacit\u00e9s mentales et les fonctions physiques, provoquent une d\u00e9pression aigu\u00eb et un changement de la personnalit\u00e9. Les pressions \u00e9motionnelles, physiques et financi\u00e8res sur les familles sont immenses et plus de 50 % des aidants dans le monde d\u00e9clarent que leur sant\u00e9 a \u00e9t\u00e9 affect\u00e9e par leurs responsabilit\u00e9s d\u2019aidant<sup>1<\/sup>.<\/p>\n<p>Le nombre de personnes atteintes de la maladie d&rsquo;Alzheimer double tous les cinq ans et environ un tiers des personnes \u00e2g\u00e9es de plus de 85 ans sont peut-\u00eatre atteintes de cette maladie. 2 Les soins incombent g\u00e9n\u00e9ralement aux membres de la famille et, avec le vieillissement de la population mondiale qui multiplie les diagnostics de d\u00e9mence, le nombre d&rsquo;aidants augmente.<\/p>\n<p>Nombreux sont ceux qui r\u00e9duisent leurs heures de travail ou d\u00e9missionnent pour s&rsquo;occuper de leurs proches et, bien que cela puisse \u00eatre gratifiant, ce r\u00f4le est soumis \u00e0 des pressions constantes. Une \u00e9tude sur les aidants, r\u00e9alis\u00e9e par l&rsquo;Organisation mondiale de la sant\u00e9 et l&rsquo;organisation caritative Alzheimer&rsquo;s Disease International, a r\u00e9v\u00e9l\u00e9 que: \u201cles aidants familiaux de personnes atteintes de d\u00e9mence sont plus susceptibles de d\u00e9velopper une d\u00e9pression majeure, des troubles anxieux et des probl\u00e8mes de sant\u00e9 physique, entre autres, et leur taux de mortalit\u00e9 est plus \u00e9lev\u00e9 que celui de la population g\u00e9n\u00e9rale.<\/p>\n<p>\u00ab Fournir des soins aux personnes atteintes de d\u00e9mence peut devenir un travail \u00e0 plein temps sans soutien ad\u00e9quat. Les aidants peuvent \u00eatre contraints de quitter leur travail, d&rsquo;en r\u00e9duire les heures ou de trouver des emplois moins contraignants afin de pouvoir assurer les soins. \u00bb<sup>3<\/sup><\/p>\n<p>Les services officiels de lutte contre la d\u00e9mence offrent des niveaux d&rsquo;aide variables selon les pays et les territoires, mais la grande majorit\u00e9 des soins, en particulier au cours des premi\u00e8res ann\u00e9es, revient aux membres de la famille qui ne sont pas r\u00e9mun\u00e9r\u00e9s pour. Ils le font par affection pour leurs proches, mais leurs vies peuvent en \u00eatre compl\u00e8tement boulevers\u00e9es.<\/p>\n<h2>Prendre soin des aidants<\/h2>\n<p>\u00catre un aidant est un d\u00e9vouement conciliant l&rsquo;amour pour un membre de la famille avec une s\u00e9rie de d\u00e9fis toujours plus grands. Au stress physique li\u00e9 \u00e0 la prise en charge quotidienne d&rsquo;une personne malade s&rsquo;ajoute le traumatisme psychologique d&rsquo;\u00eatre t\u00e9moin du d\u00e9clin des capacit\u00e9s de cette derni\u00e8re.<\/p>\n<p>La fatigue et l&rsquo;\u00e9puisement d\u00e9coulant de t\u00e2ches telles que les soins personnels et les t\u00e2ches m\u00e9nag\u00e8res sont accentu\u00e9s par l&rsquo;isolement et la solitude \u00e0 mesure que la charge augmente et que les aidants mettent leur propre vie entre parenth\u00e8ses.<\/p>\n<p>Ils peuvent \u00e9prouver de profonds sentiments de culpabilit\u00e9, de chagrin, de col\u00e8re et de frustration, et le chemin vers un soutien pratique et \u00e9motionnel peut \u00eatre mal indiqu\u00e9 et difficile \u00e0 emprunter.<\/p>\n<p>Environ 80 % de l&rsquo;ensemble des soins de longue dur\u00e9e sont prodigu\u00e9s par des conjoints, des parents et des amis dont le r\u00f4le est vital pour soutenir les syst\u00e8mes de soins officiels. Euro Carers &#8211; un r\u00e9seau de groupes d&rsquo;aidants, d&rsquo;organisations caritatives et d&rsquo;universit\u00e9s &#8211; r\u00e9clame davantage de reconnaissance et de soutien pour les aidants.<sup>4<\/sup><\/p>\n<p>Ses dix principes fondamentaux plaident en faveur d&rsquo;une meilleure diffusion de l&rsquo;information, d&rsquo;un soutien financier et \u00e9motionnel, de formations, d&rsquo;aides \u00e0 l&#8217;emploi et d&rsquo;un acc\u00e8s \u00e0 des soins formels abordables pour les pr\u00e8s de 40 millions d&rsquo;aidants en Europe.<sup>4<\/sup><\/p>\n<h2>Conseils pour les aidants de personnes atteintes de la maladie d&rsquo;Alzheimer<\/h2>\n<h3>1. G\u00e9rez vos \u00e9motions<\/h3>\n<p>Les aidants ressentent toute une s\u00e9rie d&rsquo;\u00e9motions, allant d&rsquo;un lien \u00e9troit et gratifiant avec la personne malade, \u00e0 l&rsquo;exasp\u00e9ration et \u00e0 l&rsquo;\u00e9puisement. Les experts conseillent d&rsquo;accepter les moments difficiles et de se concentrer sur ce que l&rsquo;on peut accomplir tout en \u00e9tant r\u00e9aliste et indulgent envers soi-m\u00eame.<\/p>\n<p>Alzheimer&rsquo;s Society, bas\u00e9e au Royaume-Uni, d\u00e9clare : \u201c \u00ab Rappelez-vous que vous ne pouvez pas tout faire. Toute personne qui s&rsquo;occupe d&rsquo;une personne atteinte de d\u00e9mence aura besoin d&rsquo;aide \u00e0 un moment donn\u00e9. Concentrez-vous sur ce que vous pouvez faire et essayez d&rsquo;accepter le fait qu\u2019il vous faudra peut-\u00eatre de l&rsquo;aide pour certaines choses \u00bb<sup>5<\/sup><\/p>\n<p>Reconna\u00eetre ces \u00e9motions et les g\u00e9rer donne aux aidants la force de faire face \u00e0 ce qui peut \u00eatre une relation longue et contraignante.<\/p>\n<h3>2. Ne vous isolez pas<\/h3>\n<p>Parlez aux autres et demandez de l&rsquo;aide. Il est important de partager ses sentiments avec d&rsquo;autres personnes, car cela permet d&rsquo;all\u00e9ger le fardeau et d&rsquo;avoir une perspective diff\u00e9rente sur un probl\u00e8me pouvant \u00eatre source de conflit ou d&rsquo;anxi\u00e9t\u00e9.<\/p>\n<p>Souvent, les amis ne savent pas comment vous aider. Il est donc bon de leur faire part de ce que vous vivez et de la fa\u00e7on dont ils pourraient vous aider. Les groupes de soutien aux aidants sont essentiels pour vous fournir une assistance et un contact avec d&rsquo;autres personnes traversant des exp\u00e9riences similaires.<\/p>\n<p>\u00ab Vous vous sentirez peut-\u00eatre mieux simplement en sachant que vous n&rsquo;\u00eates pas seul et que d&rsquo;autres personnes comprennent ce que vous traversez. Il vous sera peut-\u00eatre plus facile de parler de vos probl\u00e8mes avec des personnes ayant une exp\u00e9rience personnelle de ces probl\u00e8mes \u00bb, souligne Alzheimer Europe, un groupement de 39 associations membres de 35 pays.<sup>6<\/sup><\/p>\n<p>Demandez de l&rsquo;aide \u00e0 votre m\u00e9decin ou \u00e0 des groupes de soutien et envisagez la possibilit\u00e9 de recourir \u00e0 une aide psychologique et \u00e0 des soins de rel\u00e8ve.<\/p>\n<p>L&rsquo;OMS a \u00e9galement d\u00e9velopp\u00e9 iSupport, un programme de formation en ligne sur les connaissances et les comp\u00e9tences destin\u00e9 aux aidants de personnes atteintes de d\u00e9mence, dans le but de \u00ab pr\u00e9venir ou de r\u00e9duire les probl\u00e8mes de sant\u00e9 mentale et physique associ\u00e9s \u00e0 la prise en charge et d&rsquo;am\u00e9liorer la qualit\u00e9 de vie des personnes qui s&rsquo;occupent de personnes atteintes de d\u00e9mence \u00bb<sup>7<\/sup>.<\/p>\n<p>N&rsquo;ayez pas peur de demander de l&rsquo;aide.<\/p>\n<h3>3. Prenez soin de vous<\/h3>\n<p>Il est facile de se n\u00e9gliger lorsqu&rsquo;on s&rsquo;occupe d&rsquo;une personne atteinte de la maladie d&rsquo;Alzheimer. Les t\u00e2ches quotidiennes accaparant votre temps et vos r\u00e9serves d&rsquo;\u00e9nergie, trouver le temps de faire les courses, de pr\u00e9parer des repas sains et de faire du sport peut \u00eatre rel\u00e9gu\u00e9 au second plan.<\/p>\n<p>N\u00e9anmoins, il est essentiel de manger r\u00e9guli\u00e8rement et sainement, de rester actif et de dormir suffisamment pour pouvoir assumer vos fonctions en tant que personne et en tant qu&rsquo;aidant.<\/p>\n<p>Une bonne alimentation est un \u00e9l\u00e9ment cl\u00e9 pour assister une personne atteinte de la maladie d&rsquo;Alzheimer. Les aidants doivent surveiller leur r\u00e9gime alimentaire et prendre soin de leur corps afin de ne pas s&rsquo;\u00e9puiser et de ne pas \u00eatre dans l&rsquo;incapacit\u00e9 de prodiguer des soins optimaux.<\/p>\n<h3>4. Restez positif<\/h3>\n<p>Acceptez le fait qu&rsquo;il y aura des moments difficiles et des d\u00e9fis, et que vous ne pouvez pas tout r\u00e9soudre. Les aidants se sentent souvent coupables de ne pas pouvoir faire plus ou impuissants face \u00e0 la progression de la maladie d&rsquo;Alzheimer, ce qui est accentu\u00e9 par la d\u00e9t\u00e9rioration de la sant\u00e9 et des facult\u00e9s cognitives de leurs proches dont ils sont t\u00e9moins.<\/p>\n<p>\u00ab Essayez de vous concentrer sur les aspects positifs des soins et du soutien apport\u00e9s \u00e0 la personne atteinte de d\u00e9mence \u00bb, conseille Alzheimer&rsquo;s Society<sup>5<\/sup>. \u00ab Puisez votre force de votre engagement envers eux et de votre affection pour eux. Pensez \u00e0 votre relation avec la personne et au fait que vous l&rsquo;aidez \u00e9norm\u00e9ment, m\u00eame si elle ne semble pas toujours le savoir ou l&rsquo;appr\u00e9cier. \u00bb<\/p>\n<p>En veillant \u00e0 trouver du temps pour vos propres centres d&rsquo;int\u00e9r\u00eat et passe-temps, vous gagnerez \u00e9galement en positivit\u00e9 et en d\u00e9tente.<\/p>\n<h3>5. Faites des projets d\u2019avenir<\/h3>\n<p>La routine quotidienne peut \u00eatre contraignante et les aspects financiers, m\u00e9dicaux, de soins et juridiques importants, tels qu&rsquo;une procuration et un testament \u00e0 jour, sont souvent laiss\u00e9s \u00ab pour un autre jour \u00bb. Le fait de parler \u00e0 la personne atteinte de la maladie d&rsquo;Alzheimer et de discuter de ses souhaits avant qu&rsquo;elle ne perde la capacit\u00e9 de communiquer ses d\u00e9cisions apporte de l&rsquo;ordre et de la paix dans une relation.<\/p>\n<p>Cela permet \u00e0 l&rsquo;aidant d\u2019apporter son soutien avec clart\u00e9. Les groupes de soutien locaux &#8211; la plupart ont des ressources en ligne &#8211; sont une bonne source de conseils et d&rsquo;orientation. Il est \u00e9galement utile de pr\u00eater attention \u00e0 vos propres circonstances afin de vous assurer qu&rsquo;aucune pression suppl\u00e9mentaire ne compromet votre capacit\u00e9 \u00e0 prendre soin de vous ou votre bien-\u00eatre.<\/p>\n<p>La cr\u00e9ation d&rsquo;un calendrier de soins contribue \u00e9galement aux aspects pratiques de la prise en charge d&rsquo;une personne et permet de pr\u00e9voir plus facilement du temps pour s&rsquo;adonner \u00e0 des passe-temps et faire du sport ou simplement pour s&rsquo;occuper de soi. Un emploi du temps aidera \u00e9galement la personne atteinte de la maladie d&rsquo;Alzheimer \u00e0 faire preuve de coh\u00e9rence.<\/p>\n<p>&nbsp;<\/p>\n<p>Sources:<\/p>\n<ol>\n<li>Alzheimer\u2019s Disease International. Dementia Facts &amp; Figures. Accessed February 2021. <a href=\"https:\/\/www.alzint.org\/about\/dementia-facts-figures\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.alzint.org\/about\/dementia-facts-figures\/<\/a><\/li>\n<li>National Institute on Aging. What Causes Alzheimer&rsquo;s Disease? Accessed February 2021. <a href=\"https:\/\/www.nia.nih.gov\/health\/what-causes-alzheimers-disease\" target=\"_blank\" rel=\"noopener\">https:\/\/www.nia.nih.gov\/health\/what-causes-alzheimers-disease<\/a><\/li>\n<li>World Health Organisation and Alzheimer\u2019s Disease International. Supporting Informal Caregivers of people living with dementia. 2015. Accessed February 2021. <a href=\"https:\/\/www.who.int\/mental_health\/neurology\/dementia\/dementia_thematicbrief_informal_care.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/www.who.int\/mental_health\/neurology\/dementia\/dementia_thematicbrief_informal_care.pdf<\/a><\/li>\n<li>Euro Carers. Mission &amp; Guiding Principles. Accessed February 2021. <a href=\"https:\/\/eurocarers.org\/about\/\" target=\"_blank\" rel=\"noopener\">https:\/\/eurocarers.org\/about\/<\/a><\/li>\n<li>Alzheimer\u2019s Society. Your health and wellbeing. Accessed February 2021. <a href=\"https:\/\/www.alzheimers.org.uk\/get-support\/help-dementia-care\/caring-for-person-dementia\">https:\/\/www.alzheimers.org.uk\/get-support\/help-dementia-care\/caring-for-person-dementia<\/a><\/li>\n<li>Alzheimer Europe. Self-help organisations. Accessed February 2021. <a href=\"https:\/\/www.alzheimer-europe.org\/Living-with-dementia\/Caring-for-someone-with-dementia\/Coping-with-caring\/Self-help-organisations#fragment3\" target=\"_blank\" rel=\"noopener\">https:\/\/www.alzheimer-europe.org\/Living-with-dementia\/Caring-for-someone-with-dementia\/Coping-with-caring\/Self-help-organisations#fragment3<\/a><\/li>\n<li>World Health Organization. WHO iSupport: a programme for carers of people with dementia. Accessed February 2021. <a href=\"https:\/\/www.who.int\/mental_health\/neurology\/dementia\/isupport\/en\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.who.int\/mental_health\/neurology\/dementia\/isupport\/en\/<\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>La maladie d&rsquo;Alzheimer est une affection c\u00e9r\u00e9brale progressive et irr\u00e9versible qui constitue la cause la plus fr\u00e9quente de d\u00e9mence.<\/p>\n","protected":false},"author":11,"featured_media":5242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[89],"tags":[],"class_list":["post-488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maladie-dalzheimer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aidants Alzheimer : prendre soin de vous - Neuraxpharm Switzerland<\/title>\n<meta name=\"description\" content=\"Prenez soin des aidants Alzheimer. D\u00e9couvrez des conseils essentiels pour mieux vivre et g\u00e9rer le quotidien aupr\u00e8s de vos proches.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prendre soin des aidants : les aidants de personnes atteintes de la maladie d&#039;Alzheimer\" \/>\n<meta property=\"og:description\" content=\"Prenez soin des aidants Alzheimer. D\u00e9couvrez des conseils essentiels pour mieux vivre et g\u00e9rer le quotidien aupr\u00e8s de vos proches.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/\" \/>\n<meta property=\"og:site_name\" content=\"Neuraxpharm Switzerland\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T08:29:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-10T12:47:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-content\/uploads\/sites\/16\/2021\/03\/Dementia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"695\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danny Buckland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danny Buckland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\"},\"author\":{\"name\":\"Danny Buckland\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/#\\\/schema\\\/person\\\/5e98de21df7792c42f65519659dc4ed1\"},\"headline\":\"Prendre soin des aidants : les aidants de personnes atteintes de la maladie d&rsquo;Alzheimer\",\"datePublished\":\"2021-02-04T08:29:11+00:00\",\"dateModified\":\"2022-08-10T12:47:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\"},\"wordCount\":1791,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2021\\\/03\\\/Dementia.jpg\",\"articleSection\":[\"Maladie d'Alzheimer\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\\\/\",\"name\":\"Aidants Alzheimer : prendre soin de vous - Neuraxpharm Switzerland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2021\\\/03\\\/Dementia.jpg\",\"datePublished\":\"2021-02-04T08:29:11+00:00\",\"dateModified\":\"2022-08-10T12:47:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/#\\\/schema\\\/person\\\/5e98de21df7792c42f65519659dc4ed1\"},\"description\":\"Prenez soin des aidants Alzheimer. D\u00e9couvrez des conseils essentiels pour mieux vivre et g\u00e9rer le quotidien aupr\u00e8s de vos proches.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2021\\\/03\\\/Dementia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2021\\\/03\\\/Dementia.jpg\",\"width\":1920,\"height\":695,\"caption\":\"portrait\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/#website\",\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/\",\"name\":\"Neuraxpharm Switzerland\",\"description\":\"Ein europ\u00e4ischer Marktf\u00fchrer f\u00fcr CNS-Produkte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/#\\\/schema\\\/person\\\/5e98de21df7792c42f65519659dc4ed1\",\"name\":\"Danny Buckland\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g\",\"caption\":\"Danny Buckland\"},\"description\":\"Danny Buckland is an award-winning journalist who writes about health for newspapers, magazines and online outlets across Europe. His work ranges across all healthcare topics with a strong accent on innovation in technology, drug development and system redesign to meet growing challenges. He has produced White Papers and thought leadership articles for a range of clients and charities, moderates panel discussions and generates engaging content.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/danny-buckland-8252a16\\\/\"],\"url\":\"https:\\\/\\\/www.neuraxpharm.com\\\/ch-fr\\\/blog\\\/auteur\\\/dbuckland\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aidants Alzheimer : prendre soin de vous - Neuraxpharm Switzerland","description":"Prenez soin des aidants Alzheimer. D\u00e9couvrez des conseils essentiels pour mieux vivre et g\u00e9rer le quotidien aupr\u00e8s de vos proches.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer","og_locale":"fr_FR","og_type":"article","og_title":"Prendre soin des aidants : les aidants de personnes atteintes de la maladie d'Alzheimer","og_description":"Prenez soin des aidants Alzheimer. D\u00e9couvrez des conseils essentiels pour mieux vivre et g\u00e9rer le quotidien aupr\u00e8s de vos proches.","og_url":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/","og_site_name":"Neuraxpharm Switzerland","article_published_time":"2021-02-04T08:29:11+00:00","article_modified_time":"2022-08-10T12:47:01+00:00","og_image":[{"width":1920,"height":695,"url":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-content\/uploads\/sites\/16\/2021\/03\/Dementia.jpg","type":"image\/jpeg"}],"author":"Danny Buckland","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Danny Buckland","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/#article","isPartOf":{"@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer"},"author":{"name":"Danny Buckland","@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/#\/schema\/person\/5e98de21df7792c42f65519659dc4ed1"},"headline":"Prendre soin des aidants : les aidants de personnes atteintes de la maladie d&rsquo;Alzheimer","datePublished":"2021-02-04T08:29:11+00:00","dateModified":"2022-08-10T12:47:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer"},"wordCount":1791,"commentCount":0,"image":{"@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-content\/uploads\/sites\/16\/2021\/03\/Dementia.jpg","articleSection":["Maladie d'Alzheimer"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer","url":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/","name":"Aidants Alzheimer : prendre soin de vous - Neuraxpharm Switzerland","isPartOf":{"@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/#primaryimage"},"image":{"@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-content\/uploads\/sites\/16\/2021\/03\/Dementia.jpg","datePublished":"2021-02-04T08:29:11+00:00","dateModified":"2022-08-10T12:47:01+00:00","author":{"@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/#\/schema\/person\/5e98de21df7792c42f65519659dc4ed1"},"description":"Prenez soin des aidants Alzheimer. D\u00e9couvrez des conseils essentiels pour mieux vivre et g\u00e9rer le quotidien aupr\u00e8s de vos proches.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/prendre-soin-des-aidants-les-aidants-de-personnes-atteintes-de-la-maladie-dalzheimer\/#primaryimage","url":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-content\/uploads\/sites\/16\/2021\/03\/Dementia.jpg","contentUrl":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-content\/uploads\/sites\/16\/2021\/03\/Dementia.jpg","width":1920,"height":695,"caption":"portrait"},{"@type":"WebSite","@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/#website","url":"https:\/\/www.neuraxpharm.com\/ch-fr\/","name":"Neuraxpharm Switzerland","description":"Ein europ\u00e4ischer Marktf\u00fchrer f\u00fcr CNS-Produkte","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neuraxpharm.com\/ch-fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.neuraxpharm.com\/ch-fr\/#\/schema\/person\/5e98de21df7792c42f65519659dc4ed1","name":"Danny Buckland","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a728648f44c72edbe4c3d0925c08b1ec3087349d29145fbceffb6e90fca7904?s=96&d=mm&r=g","caption":"Danny Buckland"},"description":"Danny Buckland is an award-winning journalist who writes about health for newspapers, magazines and online outlets across Europe. His work ranges across all healthcare topics with a strong accent on innovation in technology, drug development and system redesign to meet growing challenges. He has produced White Papers and thought leadership articles for a range of clients and charities, moderates panel discussions and generates engaging content.","sameAs":["https:\/\/www.linkedin.com\/in\/danny-buckland-8252a16\/"],"url":"https:\/\/www.neuraxpharm.com\/ch-fr\/blog\/auteur\/dbuckland"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/posts\/488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=488"}],"version-history":[{"count":18,"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/posts\/488\/revisions"}],"predecessor-version":[{"id":26480,"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/posts\/488\/revisions\/26480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/media\/5242"}],"wp:attachment":[{"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.neuraxpharm.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}